{"id":4503,"date":"2019-06-12T16:23:53","date_gmt":"2019-06-12T15:23:53","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=4503"},"modified":"2019-06-12T16:44:39","modified_gmt":"2019-06-12T15:44:39","slug":"discos-silenciosos-oidos-atentos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2019\/06\/12\/discos-silenciosos-oidos-atentos\/","title":{"rendered":"Discos silenciosos, o\u00eddos atentos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4504\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Silent-Meditation-600x342.jpg\" alt=\"silent-meditation\" width=\"559\" height=\"318\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Silent-Meditation-600x342.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Silent-Meditation-150x86.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Silent-Meditation-300x171.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Silent-Meditation-768x438.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Silent-Meditation.jpg 1603w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Reconozco que tal vez este blog preste demasiada atenci\u00f3n a los discos silenciosos. <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2019\/02\/06\/chsssssssssssssssssssssssssssssssssssssssst\/\">Normalmente<\/a> <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2019\/01\/16\/cincuenta-silencios-de-lujo\/\">se<\/a> <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2014\/02\/19\/un-silencio-muy-particular\/\">trata<\/a> <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/10\/26\/navidades-silenciosas\/\">de<\/a> <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/08\/29\/versiones-del-silencio\/\"><em>4\u201933\u2019\u2019<\/em><\/a>, la composici\u00f3n de John Cage en la que no suena ni una sola nota: me apasionan sus interpretaciones en directo (sobre todo, por la tensi\u00f3n que implica sobreponerse a la tentaci\u00f3n de apretar una tecla, pulsar una cuerda, hacer alg\u00fan ruido) pero tambi\u00e9n me interesan sus versiones grabadas, esos discos en los que solo est\u00e1 registrado alg\u00fan sonido ambiental no intencionado (y a veces ni eso, porque se trata de puro silencio digital). A lo mejor a ustedes les entra mucha risa con este asunto, y lo entiendo, porque a m\u00ed tambi\u00e9n me pasa: ante <em>4\u201933\u2019\u2019<\/em> me debato entre el choteo, el desconcierto, la fascinaci\u00f3n y el inter\u00e9s te\u00f3rico. Caramba, ayer mismo volv\u00ed a citarla en una <a href=\"https:\/\/www.elcorreo.com\/culturas\/musica\/ruido-musica-20190509162640-nt.html\" rel=\"external nofollow\">introducci\u00f3n al <em>noise<\/em><\/a> que publiqu\u00e9 en el peri\u00f3dico, como referente ineludible para la idea de que todo ruido puede ser contemplado como m\u00fasica, aunque para m\u00ed lo m\u00e1s sugestivo de todo esto es c\u00f3mo cambia la manera de escuchar cuando el silencio es activo, cuando hay alguien <em>no tocando<\/em> o un disco <em>no sonando<\/em>.<\/p>\n<p>Pero hoy no vamos a hablar de <em>4\u201933\u2019\u2019<\/em>, sino de una prima suya, aunque los responsables rechazan que tenga nada que ver con la pieza de Cage m\u00e1s all\u00e1 de la (evidente) similitud formal. Me refiero a <em>Silent Meditation<\/em>, un nuevo elep\u00e9 silencioso pensado para acompa\u00f1ar sesiones de meditaci\u00f3n. El proyecto merece atenci\u00f3n por varias razones, entre las que destaca el gracejo de sus promotores a la hora de explicarlo. Eric Antonov y su hijo Ben <a href=\"https:\/\/www.kickstarter.com\/projects\/silentmeditation\/silent-meditation-on-vinyl\" rel=\"external nofollow\">pusieron en marcha un <em>crowdfunding<\/em> <\/a>despu\u00e9s de que Ben se comprase en un mercadillo un disco de meditaci\u00f3n grabado en los 70, que no respondi\u00f3 a sus expectativas: las voces que guiaban al oyente hacia la paz mental solo lograban apartarle de ese camino. \u00abPens\u00e9 sobre ello con seriedad y entonces me di cuenta de que solo quer\u00eda silencio. Quer\u00eda un disco que crease espacio. Me imagin\u00e9 poni\u00e9ndolo y escuchando la primera cara: durante esos veinte minutos, docenas de pensamientos aparecer\u00edan y desaparecer\u00edan. Cada escucha ser\u00eda totalmente diferente, una sorpresa\u00bb, argumenta el padre. As\u00ed se le ocurri\u00f3 <em>Silent Meditation<\/em>, un acompa\u00f1amiento silencioso para meditaciones de veinte minutos, alrededor de quince si se opta por reproducirlo a 45 revoluciones por minuto.<\/p>\n<p>\u00abNota: no hace falta un tocadiscos para disfrutarlo plenamente. T\u00e9cnicamente, ni siquiera hace falta el disco\u00bb, dice Eric, que es un tipo con mucho sentido del humor. \u00abDicho eso, el silencio es un territorio valioso que se explora pocas veces. Es sorprendente, a veces aterrador, y a menudo lo evitamos. Este disco puede ser un espejo para verte a ti mismo o una nueva ventana al mundo\u00bb, a\u00f1ade, adem\u00e1s de negar espec\u00edficamente la cercan\u00eda a <em>4\u201933\u2019\u2019<\/em>: \u00abLa composici\u00f3n de Cage era m\u00fasica y \u00e9l quer\u00eda incluir todos los sonidos en esa definici\u00f3n. Esto no es m\u00fasica, ni ha habido ning\u00fan m\u00fasico implicado en esta grabaci\u00f3n. Este silencio es muy diferente, es una invitaci\u00f3n a observar tu experiencia y una herramienta para hacerlo\u00bb. El objetivo del <em>crowdfunding<\/em> era recaudar 600 d\u00f3lares, pero la suma final borde\u00f3 los 6.000, para que vean la demanda que tienen los discos silenciosos: si alguien est\u00e1 interesado y se le pas\u00f3, puede conseguir el disco (en vinilo trasl\u00facido) en tiendas <em>online<\/em> <a href=\"https:\/\/www.normanrecords.com\/records\/176374-silence-silent-meditation\" rel=\"external nofollow\">como Norman Records<\/a>. Y, despu\u00e9s, darse el lujo de reproducirlo a volumen brutal sin temor a los vecinos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Reconozco que tal vez este blog preste demasiada atenci\u00f3n a los discos silenciosos. Normalmente se trata de 4\u201933\u2019\u2019, la composici\u00f3n de John Cage en la que no suena ni una sola nota: me apasionan sus interpretaciones en directo (sobre todo, por la tensi\u00f3n que implica sobreponerse a la tentaci\u00f3n de apretar una tecla, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[22,774,1471,3680,2182,2673],"class_list":["post-4503","post","type-post","status-publish","format-standard","hentry","category-musica","tag-22","tag-discos","tag-john-cage","tag-meditacion","tag-novedades","tag-silencio"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=4503"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4503\/revisions"}],"predecessor-version":[{"id":4507,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4503\/revisions\/4507"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=4503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=4503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=4503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}