{"id":4487,"date":"2019-06-03T16:37:44","date_gmt":"2019-06-03T15:37:44","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=4487"},"modified":"2019-06-03T16:42:49","modified_gmt":"2019-06-03T15:42:49","slug":"algunos-conciertos-de-junio-6","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2019\/06\/03\/algunos-conciertos-de-junio-6\/","title":{"rendered":"Algunos conciertos de junio"},"content":{"rendered":"<div id=\"attachment_4488\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4488\" class=\" wp-image-4488\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Surfin-Bichos-Toni-Villar-600x270.jpg\" alt=\"Foto: Toni Villar\" width=\"560\" height=\"252\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Surfin-Bichos-Toni-Villar-600x270.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Surfin-Bichos-Toni-Villar-150x68.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Surfin-Bichos-Toni-Villar-300x135.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Surfin-Bichos-Toni-Villar-768x346.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/06\/Surfin-Bichos-Toni-Villar.jpg 1080w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><p id=\"caption-attachment-4488\" class=\"wp-caption-text\"><em>Foto: Toni Villar<\/em><\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Traigo una selecci\u00f3n poco habitual, porque cinco de las ocho citas son festivales y dos de ellos no se ajustan al l\u00edmite geogr\u00e1fico de la secci\u00f3n, habitualmente vizca\u00edno. Unos me interesan m\u00e1s y otros menos, pero es verdad que todos tienen alg\u00fan gancho atractivo. Vamos all\u00e1. Como siempre, sin repetir recinto.<\/p>\n<p><strong>Institute (Muelle, d\u00eda 3).<\/strong> Esto es hoy, dentro de un ratillo. Si tardo un poco m\u00e1s en publicar, lo mismo se ha acabado ya, porque estos conciertos de post-punk tienen la costumbre de empezar muy pronto y pasar en un suspiro. He dicho <em>post<\/em>, pero en realidad a esta <a href=\"https:\/\/www.youtube.com\/watch?v=kxUCUIZMk88\" rel=\"external nofollow\">banda de Austin<\/a> (ciudad de la que han salido tant\u00edsimas cosas buenas) se la podr\u00eda catalogar perfectamente como punk, solo que con cierto aire raruno. Telonean dos representantes de la efervescente escenilla local, Karpatos y Aihotz (que a lo mejor han ampliado la cosa, pero, cuando yo los vi, no pasaban del cuarto de hora de acuciante concierto). Corran hacia all\u00ed si pueden.<\/p>\n<p><strong>Kaiola Festibala (Torrezabal, d\u00eda 8)<\/strong>. Dos de las convocatorias de este mes merecer\u00edan la consideraci\u00f3n de milagrosas, si no fuera porque sabemos que los milagros no existen y que estas cosas son el resultado del esfuerzo y el compromiso de seres humanos. El Kaiola de Galdakao alcanza su cuarta edici\u00f3n con otro muestrario estelar de m\u00fasicas diferentes, inquietas y a menudo, por qu\u00e9 no, dif\u00edciles. Esta vez, encabezan el cartel los holandeses <a href=\"https:\/\/www.youtube.com\/watch?v=JUyjNcauweQ\" rel=\"external nofollow\">The Ex<\/a>, un mito del punk bien entendido que lo mismo se zambulle en el free jazz que en las m\u00fasicas africanas, y lo completan nada menos que <a href=\"https:\/\/www.youtube.com\/watch?v=u3LCN-5qoS0\" rel=\"external nofollow\">Enablers<\/a>, Christine Abdelnour &amp; Chris Corsano, Heather Leigh &amp; Peter Brotzmann y el extravagante bohemio <a href=\"https:\/\/www.youtube.com\/watch?v=a1QRlpLxtCU\" rel=\"external nofollow\">Gh\u00e9dalia Tazart\u00e8s<\/a>, todo un personaje.<\/p>\n<p><strong>The Chameleons (Kafe Antzokia, d\u00eda 9).<\/strong> Aunque pocos sonidos representan mejor que el de The Chameleons la esencia del post-punk brit\u00e1nico de los 80, la fama nunca ha tratado del todo bien a Mark Burgess y los suyos: sus canciones atmosf\u00e9ricas e intensas, m\u00e1s afiladas en directo que en disco, siempre han tenido un hueco garantizado en el coraz\u00f3n de los devotos del estilo, pero su popularidad transversal sigue siendo muy inferior a la de compa\u00f1eros de generaci\u00f3n y de viaje. Esta visita de la banda (bajo la encarnaci\u00f3n de Chameleons Vox, con formaci\u00f3n de quinteto y centrada en el \u00e1lbum <a href=\"https:\/\/www.youtube.com\/watch?v=PJ3osEyiiXU\" rel=\"external nofollow\"><em>Strange Times<\/em><\/a>) es una buena ocasi\u00f3n para reivindicarlos. Telonea el tr\u00edo californiano Second Still, que a m\u00ed (voz aparte) me recordaba mucho a los primeros Cocteau Twins, con sus obsesivas cajas de ritmo, pero ahora <a href=\"https:\/\/www.youtube.com\/watch?v=Q9VrYQHkSUg\" rel=\"external nofollow\">ha acelerado el paso<\/a>.<\/p>\n<p><strong>The Jackets (Nave 9, d\u00eda 13).<\/strong> Tiene muy buena pinta esta banda suiza de garaje, o quiz\u00e1 deber\u00edamos decir esta banda de \u00abpure raw wild Swiss psychedelic fuzz garage\u00bb, que cuenta con la inesperada aprobaci\u00f3n de unos se\u00f1ores mayores llamados Alice Cooper y Little Steven. La verdad es que lo del <em>fuzz<\/em> se lo toman muy en serio, porque hay pasajes en los que su guitarra parece el registro sonoro de un terremoto, y dicen que su vocalista y guitarrista Jack Torera (es chica y, por desgracia, nombre art\u00edstico) es una <em>frontwoman<\/em> de eficacia probada.<\/p>\n<p><strong>BBK Music Legends (Centro Ola, d\u00edas 14 y 15).<\/strong> A m\u00ed los carteles del Music Legends me suelen dejar muy fr\u00edo, y eso me serv\u00eda como argumento ante m\u00ed mismo para demostrarme que todav\u00eda no soy tan viejo, pero resulta que el programa de este a\u00f1o me resulta inesperadamente atractivo, as\u00ed que a lo mejor ha llegado mi hora. En fin, que el plan de ver a The Beach Boys, Little Steven, <a href=\"https:\/\/www.youtube.com\/watch?v=FLP6QluMlrg\" rel=\"external nofollow\">Suzanne Vega<\/a> y Paul Collins, por espigar mis cuatro favoritos, me mola lo suyo.<\/p>\n<p><strong>Surfin\u2019 Bichos (Deusto, d\u00eda 15).<\/strong> Yo no solo ignoraba que este a\u00f1o volv\u00eda a haber Hirian, sino que tampoco me hab\u00eda enterado de que los intermitentes Surfin\u2019 Bichos estaban de nuevo en activo, as\u00ed que el anuncio supuso para m\u00ed una doble sorpresa. El festival callejero y gratuito se celebra este a\u00f1o en Deusto y cuenta con quince bandas: de Putochinomaric\u00f3n a Zea Mays, de <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/07\/13\/una-cumbia-robert-smith\/\">Kumbia Queers<\/a> a <a href=\"https:\/\/www.youtube.com\/watch?v=kZSEbwYfnfk\" rel=\"external nofollow\">Los Mambo Jambo<\/a>. Y sobre los <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/11\/22\/himnos-resurreccion\/\">Surfin\u2019 Bichos<\/a>, los caballeros de la foto de arriba, qu\u00e9 voy a contarles yo: fueron una banda esencial en mi vida y representan mi momento favorito del rock espa\u00f1ol, ese espejismo cegador y fugaz que marc\u00f3 la transici\u00f3n entre las postrimer\u00edas de la Movida y el advenimiento del indie mim\u00e9tico.<\/p>\n<p><strong>Andoaingo Rock Jaialdia (Nafarroa Plaza de Andoain, d\u00eda 15).<\/strong> Este es el otro milagro del lote, un nuevo desaf\u00edo a la l\u00f3gica: doce ediciones cumple el festi de Andoain, \u00a1doce!, y lo hace con un nuevo cartelazo y sin modificar el precio de entrada, que sigue siendo de cero euros, nada, gratis, dohain, free, \u00f3keypis, maimaim-poana&#8230; La estrella de este a\u00f1o es Thurston Moore, el rubio de Sonic Youth, tan larguirucho como influyente, pero el siguiente escal\u00f3n del cartel tambi\u00e9n es de \u00f3rdago, con los australianos <a href=\"https:\/\/www.youtube.com\/watch?v=zYWHjfVtoSM\" rel=\"external nofollow\">Tropical Fuck Storm<\/a>, la nueva banda de Gareth y Fiona, de los Drones.<\/p>\n<p><strong>Azkena Rock Festival (Mendizabala, d\u00edas 21 y 22).<\/strong> Comprender\u00e1n que, si acepto Andoain como extensi\u00f3n ocasional de Bizkaia, no voy a dejar fuera a los hermanos vitorianos. El otro d\u00eda charlaba con el colega de un colega y me dec\u00eda que <a href=\"https:\/\/www.youtube.com\/watch?v=ofkzvM7Skxg\" rel=\"external nofollow\">The B-52\u2019s<\/a> le parec\u00edan un pegote en el cartel del ARF. No me atrev\u00ed a responderle que, por mucho que tal vez tenga raz\u00f3n, a m\u00ed ese pegote es lo que m\u00e1s me apetece del lote. Poco rockista que es uno. Ya saben que, m\u00e1s all\u00e1 de mis tonter\u00edas, por ah\u00ed andar\u00e1n Stray Cats, Wilco, The Cult, los Melvins&#8230; y tambi\u00e9n Tropical Fuck Storm. Y s\u00ed, ya s\u00e9 que seguir poni\u00e9ndoles el ap\u00f3strofo a los B-52\u2019s me delata, una vez m\u00e1s, como hombre antiguo.<\/p>\n<p>Vamos con The Jackets y su <em>hit<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/3GYr0oSIcf0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Traigo una selecci\u00f3n poco habitual, porque cinco de las ocho citas son festivales y dos de ellos no se ajustan al l\u00edmite geogr\u00e1fico de la secci\u00f3n, habitualmente vizca\u00edno. Unos me interesan m\u00e1s y otros menos, pero es verdad que todos tienen alg\u00fan gancho atractivo. Vamos all\u00e1. Como siempre, sin repetir recinto. Institute (Muelle, d\u00eda [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[142,3673,244,3672,327,602,1109,3511,3676,3353,2714,2798,3675,3674,3186],"class_list":["post-4487","post","type-post","status-publish","format-standard","hentry","category-musica","tag-andoain","tag-andoaingo-rock-jaialdia","tag-azkena-rock-festival","tag-bbk-music-legends","tag-bilbao","tag-conciertos","tag-galdakao","tag-hirian","tag-institute","tag-kaiola","tag-sonidos-de","tag-surfin-bichos","tag-the-chameleons","tag-the-jackets","tag-vitoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=4487"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4487\/revisions"}],"predecessor-version":[{"id":4491,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4487\/revisions\/4491"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=4487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=4487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=4487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}