{"id":4449,"date":"2019-05-03T09:10:39","date_gmt":"2019-05-03T08:10:39","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=4449"},"modified":"2019-05-03T09:10:51","modified_gmt":"2019-05-03T08:10:51","slug":"cancion-de-la-semana-tierra-de-nadie","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2019\/05\/03\/cancion-de-la-semana-tierra-de-nadie\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Tierra de nadie&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4450\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/05\/Gabinete-Caligari-en-Vista-Alegre-600x378.jpg\" alt=\"gabinete-caligari-en-vista-alegre\" width=\"560\" height=\"353\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/05\/Gabinete-Caligari-en-Vista-Alegre-600x378.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/05\/Gabinete-Caligari-en-Vista-Alegre-150x95.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/05\/Gabinete-Caligari-en-Vista-Alegre-300x189.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/05\/Gabinete-Caligari-en-Vista-Alegre-768x484.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/05\/Gabinete-Caligari-en-Vista-Alegre.jpg 1288w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Estos d\u00edas, Gabinete Caligari se han adue\u00f1ado de la banda sonora de mi casa, por aquello del calentamiento para <a href=\"https:\/\/www.elcorreo.com\/culturas\/musica\/jaime-urrutia-mezclaria-20190503205618-nt.html\" rel=\"external nofollow\">el concierto de Jaime Urrutia<\/a>. En realidad, la m\u00fasica no ha tardado en emanciparse de esa funci\u00f3n preparatoria, porque s\u00e9 perfectamente que buena parte de lo que he estado escuchando no va a tener ning\u00fan reflejo en el repertorio de esta noche en el Antzoki. Ya he dicho m\u00e1s de una vez que a m\u00ed me gustan todas las etapas de Gabinete. La inicial, oscura y morbosa, me apasiona especialmente, pero tambi\u00e9n disfruto de todo lo posterior: su brillante adaptaci\u00f3n del afterpunk al imaginario ca\u00f1\u00ed, su evoluci\u00f3n hacia sonidos de rock cl\u00e1sico e incluso canciones como <em>La culpa fue del cha-cha-cha<\/em>, que ha quedado como emblema de su decadencia y detonante de su disoluci\u00f3n pero a m\u00ed me parece brillante. De hecho, mis escuchas de estos d\u00edas me han reafirmado en lo s\u00f3lido que es el \u00e1lbum que la contiene, <em>Privado<\/em>, el quinto de la carrera del tr\u00edo.<\/p>\n<p>Pero, como los toros (me perdonar\u00e1n la licencia), uno tiene sus querencias, que me han llevado sin remedio a aquella primera fase que beb\u00eda de la est\u00e9tica y los sonidos del post-punk brit\u00e1nico. Las evocaciones de ese periodo suelen centrarse en <em>Golpes<\/em>, <em>Olor a carne quemada<\/em> y <em>Obediencia<\/em>, que encabezaban sus primeros sencillos, pero pasan m\u00e1s por alto los cortes siniestrillos de su primer \u00e1lbum, <em>Que Dios reparta suerte<\/em>, de 1983, quiz\u00e1 porque las asombrosas canciones taurinas del disco les hicieron sombra. Yo siempre he tenido debilidad por tres de esas parientes pobres y, escuch\u00e1ndolas estos d\u00edas, me han parecido frescas, vigentes y perfectamente versionables por grupos post-punk actuales como Futuro Terror, tan cercanos en algunos rasgos a los primeros Gabinete. Me refiero a la mas\u00f3nica <em>Grado 33<\/em> y a los temas que cierran y abren el disco, <em>El arte de amar<\/em> y este intenso <em>Tierra de nadie<\/em>.<\/p>\n<p>La fotaza de arriba, con Urrutia al capote, es del archivo de EL CORREO (no aparece el nombre del autor, qu\u00e9 rabia) y est\u00e1 tomada en el coso bilba\u00edno de Vista Alegre.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/8NBiQAxvElE\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Estos d\u00edas, Gabinete Caligari se han adue\u00f1ado de la banda sonora de mi casa, por aquello del calentamiento para el concierto de Jaime Urrutia. En realidad, la m\u00fasica no ha tardado en emanciparse de esa funci\u00f3n preparatoria, porque s\u00e9 perfectamente que buena parte de lo que he estado escuchando no va a tener ning\u00fan [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,602,1106,1397],"class_list":["post-4449","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-conciertos","tag-gabinete-caligari","tag-jaime-urrutia"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=4449"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4449\/revisions"}],"predecessor-version":[{"id":4452,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4449\/revisions\/4452"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=4449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=4449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=4449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}