{"id":443,"date":"2007-07-18T17:32:51","date_gmt":"2007-07-18T16:32:51","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=442"},"modified":"2007-07-18T17:32:51","modified_gmt":"2007-07-18T16:32:51","slug":"taichi-it-s-my-wife-and-it-s-my-life","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/07\/18\/taichi-it-s-my-wife-and-it-s-my-life\/","title":{"rendered":"Taichi&#8230; it&#039;s my wife and it&#039;s my life"},"content":{"rendered":"<p><IMG src=\"\/evadidos\/files\/ReedLou.jpg\" align=\"right\" hspace=\"5\" vspace=\"5\" width=\"200\">Ya se sabe que algunos m\u00fasicos cambian de estilo seg\u00fan sopla el viento. Si nos gustan, les llamamos camale\u00f3nicos, y si no, chaqueteros asquerosos. La historia del rock guarda memoria de volantazos notables, como la deriva tecnopop de Neil Young o la conversi\u00f3n de U2 a la electr\u00f3nica (el \u00e1lbum folk de los blackmetaleros ucranianos <A target=\"_blank\" href=\"http:\/\/www.amazon.com\/Songs-Grief-Solitude-Drudkh\/dp\/B000KJTCUA\">Drudkh<\/a> tambi\u00e9n servir\u00eda), pero nada me hab\u00eda preparado para tener ante m\u00ed un disco <i>new age<\/i> de <A target=\"_blank\" href=\"http:\/\/www.loureed.org\/00\/index.html\">Lou Reed<\/a>. Bueno, perd\u00f3n, un disco de \u00abm\u00fasica que sirve de fondo para la vida, para sustituir la cacofon\u00eda cotidiana con sonidos nuevos y ordenados de naturaleza imprevisible\u00bb, por aprovechar su propia descripci\u00f3n. El hombre de la Velvet, de <i>Berlin<\/i> y de <i>Transformer<\/i>, el autor de ese monstruo hambriento y cruel que se llama <i>Metal Machine Music<\/i>, el macarra del rostro gran\u00edtico, de los picos que cambian la vida y las venas cortadas&#8230; ahora va el t\u00edo y llena <A target=\"_blank\" href=\"http:\/\/store.soundstrue.com\/mm01117d.html\"><i>Hudson River Wind Meditations<\/i><\/a> de \u00absonidos hipn\u00f3ticos\u00bb -de <i>hypnos<\/i>, sue\u00f1o, aunque siempre quede m\u00e1s bonito que <i>sopor\u00edferos<\/i>&#8211; para acompa\u00f1ar sus entregadas sesiones de meditaci\u00f3n y taichi. Por cierto, \u00bfustedes logran visualizar a Lou Reed renunciando a su proverbial rigidez para adoptar la postura de la grulla que levanta el ala?<\/p>\n<p>Si el ced\u00e9 les engancha, pueden complementarlo con el deuved\u00e9 <i>Chen Taijiquan<\/i>, del maestro <A target=\"_blank\" href=\"http:\/\/www.renguangyi.com\/\">Ren Guang Yi<\/a>, en el que Reed brinda fondo musical a las palabras del honorable asi\u00e1tico. Esto es dar buen ejemplo, y no lo de <i>Heroin<\/i>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya se sabe que algunos m\u00fasicos cambian de estilo seg\u00fan sopla el viento. Si nos gustan, les llamamos camale\u00f3nicos, y si no, chaqueteros asquerosos. La historia del rock guarda memoria de volantazos notables, como la deriva tecnopop de Neil Young o la conversi\u00f3n de U2 a la electr\u00f3nica (el \u00e1lbum folk de los blackmetaleros ucranianos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1813],"class_list":["post-443","post","type-post","status-publish","format-standard","hentry","category-musica","tag-lou-reed"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=443"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/443\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}