{"id":433,"date":"2007-06-17T16:39:39","date_gmt":"2007-06-17T16:39:39","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=433"},"modified":"2007-06-17T16:39:39","modified_gmt":"2007-06-17T16:39:39","slug":"una-pelicula-interactiva","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/06\/17\/una-pelicula-interactiva\/","title":{"rendered":"Una pel\u00edcula interactiva"},"content":{"rendered":"<p><P><FONT face=Arial size=2><IMG height=206 hspace=10 src=\"\/evadidos\/files\/Fahr.jpg\" width=275 align=right vspace=5>&#8220;\u00bfY en qu\u00e9 consiste tu nuevo juego?&#8221;, le preguntaron a David Cage, cabeza de la compa\u00f1\u00eda francesa Quantic Dream. &#8220;Es una pel\u00edcula interactiva&#8221;. Uy, uy, uy&#8230; El g\u00e9nero injugable por excelencia. Nos temimos lo peor, pero <A href=\"http:\/\/www.atari.com\/indigo\/\" target=_blank>&#8216;Fahrenheit&#8217;<\/A> no sali\u00f3 tan mal, al fin y al cabo. Hay dos tipos de creadores de videojuegos. El primer tipo quiere hacer juegos que entretienen a la gente. El segundo tipo quiere hacer arte. Los mejores juegos son siempre entretenidos, pero no todos son &#8216;art\u00edsticos&#8217;. El segundo tipo corre un riesgo mayor de fracasar cuando pone el \u00e9nfasis en la carta del arte. Otra cosa que le sucede al segundo tipo es que a \u00e9l, en realidad, lo que le gustar\u00eda es dedicarse al cine. <\/FONT><\/P><P><FONT face=Arial size=2>Muchos videojuegos echan mano de <A href=\"http:\/\/en.wikipedia.org\/wiki\/Cut_scene\" target=_blank>&#8216;cut scenes&#8217;<\/A> o escenas intermedias que interrumpen el flujo de la acci\u00f3n para presentar nuevos personajes, introducir giros de gui\u00f3n o envolver al jugador en la historia. Sagas como <A href=\"http:\/\/en.wikipedia.org\/wiki\/Wing_Commander_%28computer_game%29\" target=_blank>&#8216;Wing Commander&#8217;<\/A> y <A href=\"http:\/\/es.wikipedia.org\/wiki\/Command_&#038;_Conquer\" target=_blank>&#8216;Command &#038; Conquer&#8217; <\/A>son famosas por ellas, pero nos hemos acostumbrado a que sean normalmente una porquer\u00eda. En g\u00e9neros con una gran dependencia de los elementos narrativos, como la aventura gr\u00e1fica, las escenas se vuelven imprescindibles. El acierto de los creadores de &#8216;Fahrenheit&#8217; estriba en que las escenas exigen la intervenci\u00f3n constante del jugador. El error consiste en el reparto de papeles: controlamos al protagonista, un joven acusado de asesinato, mientras oculta las pruebas que lo incriminan, pero tambi\u00e9n a los detectives que lo persiguen, lo que parece bastante absurdo.<\/FONT> <\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&#8220;\u00bfY en qu\u00e9 consiste tu nuevo juego?&#8221;, le preguntaron a David Cage, cabeza de la compa\u00f1\u00eda francesa Quantic Dream. &#8220;Es una pel\u00edcula interactiva&#8221;. Uy, uy, uy&#8230; El g\u00e9nero injugable por excelencia. Nos temimos lo peor, pero &#8216;Fahrenheit&#8217; no sali\u00f3 tan mal, al fin y al cabo. Hay dos tipos de creadores de videojuegos. El primer [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-433","post","type-post","status-publish","format-standard","hentry","category-juegos"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=433"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/433\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}