{"id":4242,"date":"2018-12-20T14:55:42","date_gmt":"2018-12-20T13:55:42","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=4242"},"modified":"2018-12-20T14:58:30","modified_gmt":"2018-12-20T13:58:30","slug":"canciones-de-la-semana-mi-mundo-y-fantastico-isidro","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2018\/12\/20\/canciones-de-la-semana-mi-mundo-y-fantastico-isidro\/","title":{"rendered":"Canciones de la semana: &#8216;Mi mundo&#8217; y &#8216;Fant\u00e1stico Isidro&#8217;"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4243\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/12\/Antifan-600x450.jpg\" alt=\"antifan\" width=\"560\" height=\"420\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/12\/Antifan-600x450.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/12\/Antifan-150x113.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/12\/Antifan-300x225.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/12\/Antifan-768x576.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/12\/Antifan.jpg 897w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>No me ocurre tan a menudo escuchar canciones de dos grupos espa\u00f1oles de nueva hornada y no saber por cu\u00e1l de ellas decidirme para la secci\u00f3n. As\u00ed que, como estamos en fechas de generosidad (y, adem\u00e1s, como no s\u00e9 si el viernes que viene podr\u00e9 publicar <em>canci\u00f3n de la semana<\/em>) ah\u00ed van las dos bien revueltas, para que no falte de nada.<\/p>\n<p>Empezamos con los de la foto campestre de arriba, <a href=\"https:\/\/sonidomuchacho.com\/grupo\/antifan\/\" rel=\"external nofollow\">Antifan<\/a>, el grupo formado por Jerva, I-ACE y Hartosopash. Los dos primeros son miembros de <a href=\"https:\/\/www.youtube.com\/watch?v=kzLJ7Vy6orw\" rel=\"external nofollow\">Agorazein<\/a>, el grupo del que sali\u00f3 C. Tangana, y el tercero es productor de hip hop, as\u00ed que a lo mejor se imaginan que esta canci\u00f3n supone un vuelco repentino en mis gustos viejunos, la zambullida tard\u00eda de este blog en los nuevos ritmos urbanos. Pues no, porque Antifan citan como referencias a P.I.L., The Durutti Column o S\u00e9ptimo Sello (\u00a1<a href=\"https:\/\/www.youtube.com\/watch?v=rdOiMayGApU\" rel=\"external nofollow\">S\u00e9ptimo Sello<\/a>!) y hacen esencialmente un post-punk contempor\u00e1neo y tremendamente result\u00f3n, que me ha hecho escuchar cinco veces seguidas esta canci\u00f3n. Ay, qu\u00e9 cosas, tengo que admitir cierta ilusi\u00f3n ante lo que puede dar de s\u00ed el desembarco en mi mundo de gente de ese otro mundo. El propio Jerva cita en su presentaci\u00f3n a autoridades como los Buzzcocks, Eskorbuto o Ana Curra y resume as\u00ed la esencia de la banda: \u00abHemos salido del dolor, de la fealdad y del anonimato\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/5HtLWhMUNO8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Los otros se llaman <a href=\"https:\/\/www.facebook.com\/habitarlamar\/\" rel=\"external nofollow\">Habitar La Mar<\/a>, son un quinteto de Ja\u00e9n y supongo que proceden de un <em>background<\/em> m\u00e1s roquero. Su segundo EP suena tan incre\u00edblemente bien, tan potente, con unas guitarras tan brutales, que me dar\u00eda lo mismo que tocasen <em>Calderete<\/em> o <em>Noche de paz<\/em>, pero el caso es que facturan un noise rock que bebe del post-punk: algunos versos me hacen pensar en bandas como Futuro Terror o Biznaga, con las guitarras multiplicadas. En realidad, ahora que lo pienso, tambi\u00e9n tienen algo de rap, aunque m\u00e1s en la l\u00ednea agreste y desga\u00f1itada de El Lobo en Tu Puerta. Veo que han elegido <a href=\"https:\/\/www.youtube.com\/watch?v=AGeOyRGGChc\" rel=\"external nofollow\">otro tema<\/a> como sencillo, pero a m\u00ed me gusta especialmente este <em>Fant\u00e1stico Isidro<\/em>, quiz\u00e1 porque est\u00e1 colocado el primero del lote y fue el que me provoc\u00f3 la conmoci\u00f3n. \u00ab\u00a1No tienes huevos!\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=3941351175\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=2318930158\/transparent=true\/\" width=\"300\" height=\"150\" seamless=\"\"><a href=\"http:\/\/habitarlamar.bandcamp.com\/album\/realismo-hist-rico\" rel=\"external nofollow\">Realismo Hist\u00e9rico by Habitar La Mar<\/a><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; No me ocurre tan a menudo escuchar canciones de dos grupos espa\u00f1oles de nueva hornada y no saber por cu\u00e1l de ellas decidirme para la secci\u00f3n. As\u00ed que, como estamos en fechas de generosidad (y, adem\u00e1s, como no s\u00e9 si el viernes que viene podr\u00e9 publicar canci\u00f3n de la semana) ah\u00ed van las [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3600,461,3601],"class_list":["post-4242","post","type-post","status-publish","format-standard","hentry","category-musica","tag-antifan","tag-cancion-de-la-semana","tag-habitar-la-mar"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=4242"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4242\/revisions"}],"predecessor-version":[{"id":4245,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4242\/revisions\/4245"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=4242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=4242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=4242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}