{"id":424,"date":"2007-05-22T18:07:31","date_gmt":"2007-05-22T18:07:31","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=424"},"modified":"2007-05-22T18:07:31","modified_gmt":"2007-05-22T18:07:31","slug":"cans-y-otras-gaitas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/05\/22\/cans-y-otras-gaitas\/","title":{"rendered":"Cans y otras gaitas"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/evadidos\/files\/Cansss.jpg\" alt=\"\" width=\"240\" align=\"right\" hspace=\"5\" vspace=\"5\" \/>La verdad es que ya es casi tan famoso como su <em>antimodelo<\/em>, pero el Festival de Cans me parece una de esas ideas perfectas en su completa majader\u00eda y me resisto a no seguir promocion\u00e1ndolo. La aldea pontevedresa de Cans organiza a partir del jueves la cuarta edici\u00f3n de su certamen cinematogr\u00e1fico, anunciado en <a href=\"http:\/\/festivaldecans.com\" target=\"_blank\" rel=\"external nofollow\">la web<\/a> con los siguientes argumentos: \u00abSi eres un tipo fino, tienes un modisto que te hace los trajes a medida, s\u00f3lo bebes vinos con nombre franc\u00e9s y de tapa prefieres caviar beluga, quiz\u00e1s a\u00fan queden billetes en alg\u00fan crucero a la Costa Azul. Si te gusta la fiesta, tienes curiosidad por lo que hacen las nuevas promesas del audiovisual gallego y quieres sentir el perfume de la hierba reci\u00e9n cortada mientras viajas en <em>chimp\u00edn<\/em> (remolque) desde <em>o torreiro<\/em> (explanada) hasta un cobertizo transformado en sala de cine, aqu\u00ed est\u00e1 tu sitio\u00bb. Y, ciertamente, yo me veo m\u00e1s en Cans que en Cannes, porque me encanta el caldo gallego y hasta el programa musical me resulta atractivo: V\u00edctor Coyote y Pablo Novoa junto a los bombos portugueses de Os Bravos, una sesi\u00f3n de Juan de Pablos y actuaciones de The Ellas (grupo en el que Luis Tosar y otros tres barbudos versionan canciones de mujeres) y de unos prometedores (por el nombre) Tony Lomba &#038; Elio dos Santos.<\/p>\n<p>Por cierto, hablando de desviaciones galaicas: \u00bfalguno de ustedes vio la semana pasada <em>Luar<\/em>, el alucinante programa de variedades de la TVG? S\u00ed, hombre, \u00e9se que hace poco encogi\u00f3 nuestro coraz\u00f3n de fans anunciando <a href=\"http:\/\/www.youtube.com\/watch?v=rpJK1zo0-qI\" target=\"_blank\" rel=\"external nofollow\">la muerte de El Fary<\/a>. El viernes, cerveceando en un bar del barrio, casi me atragant\u00e9 al presenciar la actuaci\u00f3n de un tipo vestido de androide que tocaba techno con gaita, y quiero averiguar su nombre. No me disimulen, que seguro que alguno lo sabe.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La verdad es que ya es casi tan famoso como su antimodelo, pero el Festival de Cans me parece una de esas ideas perfectas en su completa majader\u00eda y me resisto a no seguir promocion\u00e1ndolo. La aldea pontevedresa de Cans organiza a partir del jueves la cuarta edici\u00f3n de su certamen cinematogr\u00e1fico, anunciado en la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,6,7],"tags":[467,564,1018,1111,1820],"class_list":["post-424","post","type-post","status-publish","format-standard","hentry","category-inclasificables","category-mundo-freak","category-musica","tag-cans","tag-cine","tag-festivales","tag-galicia","tag-luar"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=424"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/424\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}