{"id":4171,"date":"2018-11-15T13:31:43","date_gmt":"2018-11-15T12:31:43","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=4171"},"modified":"2018-11-15T13:31:56","modified_gmt":"2018-11-15T12:31:56","slug":"cosecha-de-enlaces-de-albert-pla-al-gato-bowie","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2018\/11\/15\/cosecha-de-enlaces-de-albert-pla-al-gato-bowie\/","title":{"rendered":"Cosecha de enlaces: de Albert Pla al gato Bowie"},"content":{"rendered":"<div id=\"attachment_4172\" style=\"width: 569px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4172\" class=\" wp-image-4172\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/11\/Bowie-I\u00f1igo-Royo-600x428.jpg\" alt=\"Foto: I\u00f1igo Royo\" width=\"559\" height=\"399\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/11\/Bowie-I\u00f1igo-Royo-600x428.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/11\/Bowie-I\u00f1igo-Royo-150x107.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/11\/Bowie-I\u00f1igo-Royo-300x214.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/11\/Bowie-I\u00f1igo-Royo-768x547.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/11\/Bowie-I\u00f1igo-Royo.jpg 1333w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><p id=\"caption-attachment-4172\" class=\"wp-caption-text\"><em>Foto: I\u00f1igo Royo<\/em><\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Tengo muy abandonada esta sana costumbre de la cosecha de enlaces, es decir, la recopilaci\u00f3n ocasional de temas m\u00e1s o menos musicales que publico en otras partes del peri\u00f3dico. La recupero con la intenci\u00f3n fundamental de reunir las entregas de <em>M\u00fasica econ\u00f3mica<\/em>, una seccioncita dominical en la que repaso algunas canciones relacionadas de alguna manera con la econom\u00eda. Por ahora van seis: <em><a href=\"https:\/\/www.elcorreo.com\/economia\/musica-economica-leva-20180924114809-nt.html\" rel=\"external nofollow\">L\u2019Eva i l\u2019Eugeni<\/a><\/em>, de Albert Pla, que me sirvi\u00f3 como introducci\u00f3n un poco tangencial; <em><a href=\"https:\/\/www.elcorreo.com\/economia\/brother-spare-dime-20181002202312-nt.html\" rel=\"external nofollow\">Brother, Can You Spare A Dime?<\/a><\/em>, el ineludible himno de la Gran Depresi\u00f3n; <em><a href=\"https:\/\/www.elcorreo.com\/economia\/tu-economia\/career-opportunities-quieres-20181017171052-nt.html\" rel=\"external nofollow\">Career Opportunities<\/a><\/em>, en la que los Clash revisaban la oferta de empleo; <em><a href=\"https:\/\/www.elcorreo.com\/economia\/tu-economia\/ricos-imbeciles-pobres-20181023120230-nt.html\" rel=\"external nofollow\">Por qu\u00e9 los ricos<\/a><\/em>, de Los Prisioneros, con ese estribillo inmortal que dice \u00abpor qu\u00e9 los ricos tienen derecho a pasarlo tan bien si son tan imb\u00e9ciles como los pobres\u00bb; <em><a href=\"https:\/\/www.elcorreo.com\/economia\/tu-economia\/repartir-tierra-sevillanas-20181030135331-nt.html\" rel=\"external nofollow\">Hay que repartir la tierra<\/a><\/em>, sevillana jornalera de Gente del Pueblo, tan reivindicados en los \u00faltimos tiempos por Lagartija Nick, y <a href=\"https:\/\/www.elcorreo.com\/economia\/tu-economia\/folding-money-ventana-20181105192409-nt.html\" rel=\"external nofollow\"><em>F-olding Money<\/em><\/a>, el cl\u00e1sico de serie B de Tommy Blake, con los padecimientos de un perdedor en pleno consumismo estadounidense de los 50. Ya puestos, tambi\u00e9n tienen en abierto algunas cr\u00f3nicas de la <em>Semana de la MTV<\/em>, a saber: el <a href=\"https:\/\/www.elcorreo.com\/bizkaia\/mtv-ema-2018-bilbao\/celebra-poder-femenino-20181031232755-nt.html\" rel=\"external nofollow\">concierto de Durango<\/a>, diez minutos de <a href=\"https:\/\/www.elcorreo.com\/bizkaia\/mtv-ema-2018-bilbao\/mames-listo-convertirse-20181102151005-nt.html\" rel=\"external nofollow\">ensayo de Crystal Fighters<\/a> y la <a href=\"https:\/\/www.elcorreo.com\/culturas\/musica\/camila-cabello-gran-20181105070549-nt.html\" rel=\"external nofollow\">gala de premios<\/a> final. Y, si les interesa, pueden leer acerca de <a href=\"https:\/\/www.elcorreo.com\/bizkaia\/hermanos-duermen-juntos-20181021201045-nt.html\" rel=\"external nofollow\">las mascotas de Lander Zalakain<\/a>, el bater\u00eda de Belako, que son Pluto el perro y Bowie el gato. Es decir, esa criatura que mira atentamente desde la foto de arriba.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Tengo muy abandonada esta sana costumbre de la cosecha de enlaces, es decir, la recopilaci\u00f3n ocasional de temas m\u00e1s o menos musicales que publico en otras partes del peri\u00f3dico. La recupero con la intenci\u00f3n fundamental de reunir las entregas de M\u00fasica econ\u00f3mica, una seccioncita dominical en la que repaso algunas canciones relacionadas de alguna [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[91,3587,621,3588,3586,2891,3066],"class_list":["post-4171","post","type-post","status-publish","format-standard","hentry","category-musica","tag-albert-pla","tag-belako","tag-cosecha-de-enlaces","tag-gente-del-pueblo","tag-los-prisioneros","tag-the-clash","tag-tommy-blake"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=4171"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4171\/revisions"}],"predecessor-version":[{"id":4174,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4171\/revisions\/4174"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=4171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=4171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=4171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}