{"id":4124,"date":"2018-10-12T16:35:10","date_gmt":"2018-10-12T15:35:10","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=4124"},"modified":"2018-10-12T17:02:03","modified_gmt":"2018-10-12T16:02:03","slug":"cancion-de-la-semana-istikrarli-hayal-hakikattir","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2018\/10\/12\/cancion-de-la-semana-istikrarli-hayal-hakikattir\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;\u0130stikrarl\u0131 Hayal Hakikattir&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4125\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/10\/Gaye-Su-Akyol-600x600.jpg\" alt=\"gaye-su-akyol\" width=\"561\" height=\"561\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/10\/Gaye-Su-Akyol-600x600.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/10\/Gaye-Su-Akyol-150x150.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/10\/Gaye-Su-Akyol-300x300.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/10\/Gaye-Su-Akyol-768x768.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/10\/Gaye-Su-Akyol.jpg 960w\" sizes=\"auto, (max-width: 561px) 100vw, 561px\" \/><\/p>\n<p>Me he dado cuenta de dos cosas. La primera es que estaba a punto de soltarles un rollo que ya he repetido unas cuantas veces. La segunda, que hace un par de a\u00f1os escrib\u00ed en la revista de m\u00fasica para suscriptores un textito sobre Gaye Su Akyol, nuestra protagonista de hoy, que nunca hab\u00eda compartido por aqu\u00ed. As\u00ed que ah\u00ed les va con final adaptado a la <em>canci\u00f3n de la semana<\/em>.<\/p>\n<p>&#8230;..<\/p>\n<p>En Turqu\u00eda parece natural lo que, en otros lugares del mundo, puede sonar a forzada impostura. La ubicaci\u00f3n y la propia estructura del pa\u00eds, recostado en una esquina de Asia y con la punta de un pie bien clavada en Europa, hace que all\u00ed las culturas (y, m\u00e1s espec\u00edficamente, lo que nos interesa aqu\u00ed: las m\u00fasicas) convivan y se mezclen con ins\u00f3lita fluidez, estableciendo los lazos profundos de quienes llevan mucho tiempo trat\u00e1ndose. La psicodelia es seguramente el ejemplo m\u00e1s claro: los grupos de Estados Unidos o Gran Breta\u00f1a se afanaban y se afanan a menudo en impregnar sus canciones de cierto orientalismo, a menudo torpe y superficial, mientras que sus equivalentes turcos se limitan a abrazar con entusiasmo sus dos tradiciones, la rica m\u00fasica cl\u00e1sica otomana y el rock and roll. De esa suma salieron algunos de los discos m\u00e1s estimulantes e inagotables de la d\u00e9cada de los 70.<\/p>\n<p><a href=\"https:\/\/gayesuakyol.bandcamp.com\/\" rel=\"external nofollow\">Gaye Su Akyol<\/a> es el \u00faltimo ejemplo brillante de esta hibridaci\u00f3n. La vocalista procede de Estambul, la ciudad que Napole\u00f3n ve\u00eda como capital del mundo, y su formaci\u00f3n musical bebe de fuentes muy dispares. De ni\u00f1a estuvo expuesta a la generosa raci\u00f3n de m\u00fasica cl\u00e1sica turca (un g\u00e9nero vocal acompa\u00f1ado de instrumentos como el la\u00fad o la c\u00edtara) que programaba la televisi\u00f3n nacional, pero a esa dieta sonora no tardaron en a\u00f1adirse sonidos contempor\u00e1neos. Todav\u00eda estaba en primaria cuando se entusiasm\u00f3 por el <em>Nevermind<\/em> de Nirvana, propiedad de sus hermanos mayores: \u00abCuando lo escuch\u00e9 por primera vez, mi cerebro explot\u00f3. Entonces descubr\u00ed a otras bandas de Seattle, y despu\u00e9s a gente como Nick Cave, Joy Division, Sonic Youth y Einst\u00fcrzende Neubauten\u00bb. Curiosamente, el siguiente paso en esta evoluci\u00f3n un tanto ca\u00f3tica fueron los hippies Jefferson Airplane: \u00abEso me llev\u00f3 a la psicodelia y el surf. Lo que hac\u00edan todos ellos parec\u00eda encajar con cantantes turcas de m\u00e1s edad que me encantaban, como Selda Ba\u011fcan y M\u00fczeyyen Senar\u00bb. El c\u00edrculo se hab\u00eda cerrado.<\/p>\n<p>Nuestra protagonista es hija de Muzaffer Akyol, reputado pintor, y durante mucho tiempo persigui\u00f3 vocaciones ajenas a la m\u00fasica. Se licenci\u00f3 en antropolog\u00eda y trabaj\u00f3 como artista pl\u00e1stica, pero a la vez se introdujo en la fecunda escena <em>underground<\/em> de su ciudad: primero, se dio a conocer como parte del proyecto electr\u00f3nico Seni G\u00f6rmem \u0130mkans\u0131z, y despu\u00e9s estableci\u00f3 una alianza con el vers\u00e1til tr\u00edo de rock Bubituzak, que se convirti\u00f3 en su banda de acompa\u00f1amiento. Las m\u00e1scaras con las que cubren sus rostros los tres m\u00fasicos se han convertido en una impactante se\u00f1a de identidad de los conciertos de Gaye Su Akyol, junto al vaso de raki, el an\u00eds turco, que la cantante siempre procura tener a mano. Su primer \u00e1lbum,\u00a0<em>Develerle Ya\u015f\u0131yorum<\/em> (algo as\u00ed como <em>Vivo con los camellos<\/em>) ya constituy\u00f3 una revelaci\u00f3n, pero con el segundo, el reci\u00e9n editado<em> Hologram \u012cmparatorlu\u011fu<\/em> (<em>El imperio del holograma<\/em>), dio el salto a la relevancia internacional. A la cr\u00edtica le fascin\u00f3 su compleja identidad sonora, de resultados tan embriagadores como los de su aguardiente. Quiz\u00e1 sus paisanos distingan otras proporciones, pero para el oyente occidental la m\u00fasica de Gaye Su Akyol es fundamentalmente turca, con sus rizos mel\u00f3dicos, sus ritmos intrincados y una instrumentaci\u00f3n en la que no falta el oud, ese la\u00fad de m\u00e1stil corto fundamental en la tradici\u00f3n de tantos pa\u00edses.<\/p>\n<p>A finales de este mes llegar\u00e1\u00a0<em>\u0130stikrarl\u0131 Hayal Hakikattir<\/em> (es decir, <em>Una fantas\u00eda consistente es realidad<\/em>), al que ha servido de presentaci\u00f3n la canci\u00f3n hom\u00f3nima. D\u00e9jense llevar.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/pykJX9SCpAY\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me he dado cuenta de dos cosas. La primera es que estaba a punto de soltarles un rollo que ya he repetido unas cuantas veces. La segunda, que hace un par de a\u00f1os escrib\u00ed en la revista de m\u00fasica para suscriptores un textito sobre Gaye Su Akyol, nuestra protagonista de hoy, que nunca hab\u00eda compartido [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,3571,3107],"class_list":["post-4124","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-gaye-su-akyol","tag-turquia"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=4124"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4124\/revisions"}],"predecessor-version":[{"id":4129,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4124\/revisions\/4129"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=4124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=4124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=4124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}