{"id":4021,"date":"2018-08-02T19:32:47","date_gmt":"2018-08-02T18:32:47","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=4021"},"modified":"2018-08-03T08:54:23","modified_gmt":"2018-08-03T07:54:23","slug":"cancion-de-la-semana-white-baby","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2018\/08\/02\/cancion-de-la-semana-white-baby\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;White Baby&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4025\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/08\/The-Blankz-2-600x197.png\" alt=\"the-blankz-2\" width=\"560\" height=\"184\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/08\/The-Blankz-2-600x197.png 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/08\/The-Blankz-2-150x49.png 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/08\/The-Blankz-2-300x98.png 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/08\/The-Blankz-2.png 677w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Si les gusta el punk-pop noventero, seguro que <em>White Baby<\/em> les parece una canci\u00f3n estupenda y supereficaz: impetuosa, alegre, saltarina, coreable y adhesiva, tiene todo lo que hay que tener para convertirse en un <em>hit<\/em> inmediato del estilo. El caso es que a m\u00ed el punk-pop noventero me suele inspirar, ante todo, una monumental indiferencia, as\u00ed que algo m\u00e1s tiene que haber en este tema para que me ponga tan contento cada vez que suena. No se asusten, que tampoco voy a lanzarme a un profundo an\u00e1lisis musicol\u00f3gico: no hay que esperar m\u00e1s que cinco segundos (veintinco en el v\u00eddeo) para que suenen los teclados, culpables principales de mi enganche a esta canci\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/theblankzband\/\" rel=\"external nofollow\">The Blankz<\/a> son veteranos de la escena punk de Arizona (s\u00e9 poco de su curr\u00edculum, pero la experiencia se les ve en las jetas) y este <em>White Baby<\/em> es su primer sencillo, producido por Cris Kirkwood, de Meat Puppets. El asunto de la letra es singular: el vocalista, que responde por Tommy Blank, explora en la canci\u00f3n su infrecuente identidad \u00e9tnica de ni\u00f1o blanco adoptado por una familia de origen mexicano (\u00abni\u00f1o blanco, mam\u00e1 morena\u00bb) e incluso utiliza sus v\u00eddeos dom\u00e9sticos para ilustrarla.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/qdBY7uztSBs\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Si les gusta el punk-pop noventero, seguro que White Baby les parece una canci\u00f3n estupenda y supereficaz: impetuosa, alegre, saltarina, coreable y adhesiva, tiene todo lo que hay que tener para convertirse en un hit inmediato del estilo. El caso es que a m\u00ed el punk-pop noventero me suele inspirar, ante todo, una monumental [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3538,461,3537],"class_list":["post-4021","post","type-post","status-publish","format-standard","hentry","category-musica","tag-arizona","tag-cancion-de-la-semana","tag-the-blankz"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=4021"}],"version-history":[{"count":5,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4021\/revisions"}],"predecessor-version":[{"id":4028,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4021\/revisions\/4028"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=4021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=4021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=4021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}