{"id":3936,"date":"2018-05-11T18:52:52","date_gmt":"2018-05-11T17:52:52","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3936"},"modified":"2018-05-11T19:01:21","modified_gmt":"2018-05-11T18:01:21","slug":"cancion-de-la-semana-astor","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2018\/05\/11\/cancion-de-la-semana-astor\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Astor&#8217;"},"content":{"rendered":"<div id=\"attachment_3938\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3938\" class=\" wp-image-3938\" src=\"\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/05\/Axolotes-Mexicanos-600x400.jpg\" alt=\"Foto: Diego Jim\u00e9nez\" width=\"560\" height=\"373\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/05\/Axolotes-Mexicanos-600x400.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/05\/Axolotes-Mexicanos-150x100.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/05\/Axolotes-Mexicanos-300x200.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/05\/Axolotes-Mexicanos-768x512.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/05\/Axolotes-Mexicanos.jpg 942w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><p id=\"caption-attachment-3938\" class=\"wp-caption-text\"><em>Foto: Diego Jim\u00e9nez<\/em><\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Escucho a <a href=\"https:\/\/www.facebook.com\/AxolotesMexicanos\" rel=\"external nofollow\">Axolotes Mexicanos<\/a> desde aquella versi\u00f3n del <em>Me gusta ser una zorra<\/em> de las Vulpess que hicieron en sus comienzos, retitulada <a href=\"https:\/\/axolotesmexicanos.bandcamp.com\/track\/me-gusta-ser-una-gorda-demo\" rel=\"external nofollow\"><em>Me gusta ser una gorda<\/em><\/a>, as\u00ed que estaba convencido de que ya hab\u00edan tenido <em>canci\u00f3n de la semana<\/em> en el blog. Sobre todo, porque hace tres a\u00f1os me gust\u00f3 much\u00edsimo su minielep\u00e9 de debut, <a href=\"https:\/\/axolotesmexicanos.bandcamp.com\/album\/holi-3\" rel=\"external nofollow\"><em>Holi &lt;3<\/em><\/a>, con temas tan adictivos como <em>Disparo de amor<\/em> o <em>Hay una china que vive en mi piso<\/em>, pero resulta que no, que nunca hab\u00edan aparecido por esta secci\u00f3n, as\u00ed que es hora de poner fin a esa ausencia hoy que editan nuevo \u00e1lbum, <a href=\"https:\/\/elefantrecords.bandcamp.com\/album\/salu2\" rel=\"external nofollow\"><em>Salu2<\/em><\/a>. El grupo de los hermanos asturianos Olaya y Juan Pedrayes es una rara criatura que combina arrollador punk pop con influencias menos cl\u00e1sicas, como el pop y el rock japoneses (el rollo nip\u00f3n es determinante en buena parte de su est\u00e9tica) y el pop electr\u00f3nico de dormitorio, lo llamen como lo llamen en el \u00faltimo cuarto de hora. Como persona de edad avanzada que soy, he de reconocer que me enganchan pero tambi\u00e9n me alienan a veces, ya que en algunos momentos me siento penosamente alejado de lo que podr\u00edamos llamar su cosmovisi\u00f3n. Que me hacen sentirme (m\u00e1s) viejo, vamos.<\/p>\n<p>Supongo que la elecci\u00f3n me delata, porque el nuevo disco contiene temas m\u00e1s apegados a las tendencias contempor\u00e1neas, pero yo me aferro de manera cerril a un himno energ\u00e9tico y tirando a ramoniano como <em>Astor<\/em>, que viene a sonar como si Melt-Banana versionasen a Los Vegetales. Me encanta, por supuesto, su letra de costumbrismo emocional sobre amistades imposibles de reparar. Pero, m\u00e1s all\u00e1 de <em>Astor<\/em>, he de decir que Axolotes Mexicanos vuelven a demostrar que son uno de los grupos m\u00e1s divertidos de este pa\u00eds, con esos brincos estil\u00edsticos entre canciones que rar\u00edsimamente alcanzan los tres minutos y esas letras efervescentes salpicadas de referencias a las redes sociales. En este disco, por cierto, llama inevitablemente la atenci\u00f3n un corte, <em>Farmacia<\/em>, sobre un asunto que no se ha tocado muy a menudo en el pop: \u00abQuiero que me venga la regla ya. \/ Si no, tendr\u00e9 que ir a planificaci\u00f3n familiar\u00bb, canta Olaya en los dos primeros versos.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/evMh2njm6oE\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Escucho a Axolotes Mexicanos desde aquella versi\u00f3n del Me gusta ser una zorra de las Vulpess que hicieron en sus comienzos, retitulada Me gusta ser una gorda, as\u00ed que estaba convencido de que ya hab\u00edan tenido canci\u00f3n de la semana en el blog. Sobre todo, porque hace tres a\u00f1os me gust\u00f3 much\u00edsimo su minielep\u00e9 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[221,239,461],"class_list":["post-3936","post","type-post","status-publish","format-standard","hentry","category-musica","tag-asturias","tag-axolotes-mexicanos","tag-cancion-de-la-semana"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3936"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3936\/revisions"}],"predecessor-version":[{"id":3940,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3936\/revisions\/3940"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}