{"id":3884,"date":"2018-04-03T19:13:25","date_gmt":"2018-04-03T18:13:25","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3884"},"modified":"2018-04-03T19:13:39","modified_gmt":"2018-04-03T18:13:39","slug":"algunos-conciertos-de-abril-4","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2018\/04\/03\/algunos-conciertos-de-abril-4\/","title":{"rendered":"Algunos conciertos de abril"},"content":{"rendered":"<div id=\"attachment_3885\" style=\"width: 569px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3885\" class=\" wp-image-3885\" src=\"\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/04\/The-Capaces-foto-Guillem-Willy-600x366.jpg\" alt=\"Foto: Guillem Willy\" width=\"559\" height=\"341\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/04\/The-Capaces-foto-Guillem-Willy-600x366.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/04\/The-Capaces-foto-Guillem-Willy-150x91.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/04\/The-Capaces-foto-Guillem-Willy-300x183.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/04\/The-Capaces-foto-Guillem-Willy-768x468.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/04\/The-Capaces-foto-Guillem-Willy.jpg 2048w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><p id=\"caption-attachment-3885\" class=\"wp-caption-text\"><em>Foto: Guillem Willy<\/em><\/p><\/div>\n<p>&nbsp;<\/p>\n<p>One, two, three, four&#8230; Vamos, sin m\u00e1s rodeos, a la selecci\u00f3n de conciertos del mes: en esta ocasi\u00f3n, siete actuaciones en siete recintos distintos.<\/p>\n<p><strong>The Capaces (d\u00eda 8, Nave 9).<\/strong> Pocas cosas quitar\u00e1n mejor las lega\u00f1as un domingo por la ma\u00f1ana (o la resaca, si son ustedes bebedores nocturnos) que una descarga de esta <a href=\"https:\/\/www.youtube.com\/watch?v=qEySjSf5Hm4\" rel=\"external nofollow\">banda barcelonesa<\/a> encabezada por la poderosa vocalista Martillo Fontana. Son los de la foto de arriba, y lo suyo es punk rock hipervitaminado de guitarras solistas con filo de Detroit. Completan el pu\u00f1etazo matinal Negracalavera.<\/p>\n<p><strong>La Chasse y Avale (d\u00eda 10, Sarean)<\/strong>. Como suele ocurrirme con los conciertos en Sarean, esto empieza demasiado pronto para m\u00ed. \u00bfEs que soy el \u00fanico que est\u00e1 currando a las siete de un d\u00eda laborable? Me da pena, porque me parece una de las citas m\u00e1s estimulantes del mes: dos d\u00faos femeninos franceses de bajo y bater\u00eda, a saber, La Chasse (marsellesas que se definen como \u00aboccult noisepunk\u00bb) y Avale (\u00abamor fr\u00edo\u00bb desde Metz). Todo muy oscuro, aunque sea a media tarde.<\/p>\n<p><strong>Los Nastys y Wizard (d\u00eda 13, Bizkaia Aretoa).<\/strong> El festival gratuito Unisound va a repartir un mont\u00f3n de propuestas motivantes por distintos rincones de Bilbao, as\u00ed que conviene leerse con atenci\u00f3n <a href=\"http:\/\/bilbaogazte.bilbao.eus\/es\/2018\/03\/27\/vuelve-unisound-bilbao\/\" rel=\"external nofollow\">el programa<\/a>: en plan picoteo, a m\u00ed me apetecen <a href=\"https:\/\/whereisvvv.bandcamp.com\/album\/dance-and-cry-ii\" rel=\"external nofollow\">VVV<\/a>, Las Odio, <a href=\"https:\/\/www.youtube.com\/watch?v=72WMrwAVE_k\" rel=\"external nofollow\">Putochinomaric\u00f3n<\/a> o Los Manises, pero, puestos a elegir una cita completa, me quedo con la que encabezan los madrile\u00f1os Nastys (garaje denso con un <a href=\"https:\/\/www.youtube.com\/watch?v=TnE_9zKFhyI\" rel=\"external nofollow\">disco nuevo<\/a> que est\u00e1 de lujo) y los bordeleses <a href=\"https:\/\/www.youtube.com\/watch?v=OV8O4wD9QDo\" rel=\"external nofollow\">Wizard<\/a> (instrumentales progresivos en plan bien). Estar\u00e1n tambi\u00e9n los locales Las Selvas.<\/p>\n<p><strong>Akauzazte (d\u00eda 14, Alh\u00f3ndiga).<\/strong> Ya han pasado la frontera de los 25 a\u00f1os de carrera estos giputxis salvajes salidos del Matadero de Azkoitia, con un estilo variable siempre en los territorios ruidosos de la vanguardia. En su <a href=\"https:\/\/www.youtube.com\/watch?v=TibRMCPt4oQ&amp;list=PLEgP1kan4Z2kZte6u6qGRdMMOw8BsuRvC\" rel=\"external nofollow\">\u00e1lbum de 2015<\/a>, que no s\u00e9 si sigue siendo el \u00faltimo, se defin\u00edan como \u00abfolk industrial vasco\u00bb y creaban un ruido r\u00edtmico, ritualista y adictivo, pero tampoco tengo claro si siguen en la misma l\u00ednea, as\u00ed que mejor copio un par de datos de la web de la <em>Azk\u00fandiga<\/em>: actualmente son cinco miembros, con dos bater\u00edas, y dan forma (o se la quitan, no s\u00e9) a un \u00abmagma hipn\u00f3tico\u00bb.<\/p>\n<p><strong>Izar &amp; Star: Ron Asheton y The Sonics (d\u00eda 19, Kafe Antzokia).<\/strong> Habl\u00e1bamos antes de guitarras con filo de Detroit, \u00bfverdad? Pues aqu\u00ed habr\u00e1 muchas m\u00e1s, porque la mitad de la sesi\u00f3n estar\u00e1 dedicada a las bandas de Ron Asheton (los Stooges, claro, pero tambi\u00e9n <a href=\"https:\/\/www.youtube.com\/watch?v=3MZIQWhSdOo\" rel=\"external nofollow\">Destroy All Monsters<\/a> o su <a href=\"https:\/\/www.youtube.com\/watch?v=vQm0DfdVaus\" rel=\"external nofollow\">New Order<\/a>). Los encargados de medirse con su repertorio ser\u00e1n nada menos que Se\u00f1or No, que han reclutado para la ocasi\u00f3n a Joseba B. Lenoir y a Pela, vocalista de Sumisi\u00f3n City Blues. Por si eso fuera poco, la otra mitad de la noche promete cafrer\u00edo roquero a discreci\u00f3n, gracias a la colisi\u00f3n entre los Aterkings de Markina y los himnos eternos de los Sonics. \u00a1Qu\u00e9 bella es la m\u00fasica cl\u00e1sica!<\/p>\n<p><strong>TxikiMAZ (d\u00eda 28, en alg\u00fan lugar de Basauri).<\/strong> Ya, ya s\u00e9 que entre <a href=\"http:\/\/www.mazbasauri.com\/\" rel=\"external nofollow\">los conciertos del MAZ<\/a> en abril hay cosas ricas como Biznaga o Rufus T. Firefly, pero qu\u00e9 le vamos a hacer: yo formo parte del club de devotos del TxikiMAZ, esa secta de padres que llevamos a nuestros reto\u00f1os a Basauri con la excusa de culturizarlos en el rock y con el plan secreto de darnos nosotros un homenaje a media ma\u00f1ana. Creo que todav\u00eda no se sabe qui\u00e9n va a tocar, pero lo cierto es que me da m\u00e1s o menos igual.<\/p>\n<p><strong>Guttercats (d\u00eda 29, La Nube).<\/strong> A estos <a href=\"https:\/\/www.youtube.com\/watch?v=FGaTmx73iNY\" rel=\"external nofollow\">se\u00f1ores parisinos<\/a> (cu\u00e1ntos franceses en la selecci\u00f3n de este mes) les atribuyen influencias como los Jacobites, Peter Perrett o Rowland S. Howard, as\u00ed que ya pueden imaginarse que lo suyo es decadentismo roquero, pero m\u00e1s mel\u00f3dico que tenebroso, con pasajes luminosos que recuerdan a The Church o The Go-Betweens. Hay que aplicarles, adem\u00e1s, el <em>factor de mejora La Nube<\/em>, ya que est\u00e1 sobradamente comprobado que cualquier grupo bueno se vuelve todav\u00eda mejor en las distancias cortas y el escenario an\u00f3malo del local de Santutxu.<\/p>\n<p>Vamos con un poquito de La Chasse en directo.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/cZ7yGKSq5qk\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; One, two, three, four&#8230; Vamos, sin m\u00e1s rodeos, a la selecci\u00f3n de conciertos del mes: en esta ocasi\u00f3n, siete actuaciones en siete recintos distintos. The Capaces (d\u00eda 8, Nave 9). Pocas cosas quitar\u00e1n mejor las lega\u00f1as un domingo por la ma\u00f1ana (o la resaca, si son ustedes bebedores nocturnos) que una descarga de esta [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3502,3499,278,327,602,3503,1382,3498,3500,1934,2714,3497,3367,3501],"class_list":["post-3884","post","type-post","status-publish","format-standard","hentry","category-musica","tag-akauzazte","tag-avale","tag-basauri","tag-bilbao","tag-conciertos","tag-guttercats","tag-izar-star","tag-la-chasse","tag-los-nastys","tag-maz","tag-sonidos-de","tag-the-capaces","tag-txikimaz","tag-wizard"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3884"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3884\/revisions"}],"predecessor-version":[{"id":3887,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3884\/revisions\/3887"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}