{"id":3869,"date":"2018-03-19T16:28:29","date_gmt":"2018-03-19T15:28:29","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3869"},"modified":"2018-03-26T14:31:16","modified_gmt":"2018-03-26T13:31:16","slug":"ruidos-de-ultima-hora","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2018\/03\/19\/ruidos-de-ultima-hora\/","title":{"rendered":"Ruidos de \u00faltima hora"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3870\" src=\"\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/03\/Pussycat-And-The-Dirty-Johnsons-600x374.png\" alt=\"pussycat-and-the-dirty-johnsons\" width=\"560\" height=\"349\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/03\/Pussycat-And-The-Dirty-Johnsons-600x374.png 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/03\/Pussycat-And-The-Dirty-Johnsons-150x93.png 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/03\/Pussycat-And-The-Dirty-Johnsons-300x187.png 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/03\/Pussycat-And-The-Dirty-Johnsons-768x479.png 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2018\/03\/Pussycat-And-The-Dirty-Johnsons.png 796w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Este ha sido uno de esos meses en los que la selecci\u00f3n mensual de conciertos se me qued\u00f3 desfasada a los pocos d\u00edas de publicarla, porque me enter\u00e9 no de una ni de dos, sino de tres citas que no aparec\u00edan por ninguna parte cuando yo estaba confeccionando mi humilde pero chula miniagenda. Para colmo, cumplen la regla de oro de la secci\u00f3n mensual (ya saben, no repetir sala), porque ninguno de los tres recintos aparec\u00eda en <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2018\/02\/28\/algunos-conciertos-de-marzo-4\">aquella lista inicial de diez<\/a> (\u00a1diez, casi nada!). As\u00ed que, en fin, ah\u00ed va un ap\u00e9ndice un poco apresurado a aquel <em>post<\/em>: no recuerdo, por cierto, ning\u00fan otro mes en el que me haya tenido que ir a los trece conciertos recomendados.<\/p>\n<p>Este viernes y este s\u00e1bado, 23 y 24, el Hika Ateneo acoger\u00e1 una nueva edici\u00f3n de <a href=\"https:\/\/www.facebook.com\/Fuzz-in-the-City-731879440164552\/\" rel=\"external nofollow\">Fuzz In The City<\/a>, el c\u00f3nclave garajero de bandas \u00bbatronadoras, explosivas y salvajes\u00bb. Esta vez, el local ribere\u00f1o acoger\u00e1 el viernes a los barceloneses Hiroshima, los granadinos Banana C\u00f3smica y los brit\u00e1nicos Pussycat And The Dirty Johnsons (las amigables personas de la foto de arriba) y el s\u00e1bado a los locales Villapellejos, los portugueses The Twist Connection y los franceses The Wylde Tryfles. Vienen a ser unas Naciones Unidas sesenteras que garantizan el buen humor y el sudor copioso, o el buen sudor y el humor copioso.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=3161977867\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=2593243231\/transparent=true\/\" width=\"300\" height=\"150\" seamless=\"\"><a href=\"http:\/\/thewyldetryfles1.bandcamp.com\/album\/upside-down-full-album\" rel=\"external nofollow\">UPSIDE DOWN ( Full album) by THE WYLDE TRYFLES<\/a><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Los otros dos conciertos se solapan, pero a m\u00ed ese detalle me da igual, porque estar\u00e9 en Logro\u00f1o y no podr\u00e9 asistir a ninguno de los dos, as\u00ed que mi rabia es m\u00e1s general. La noche del Viernes Santo (d\u00eda 30, pedazo de ateos) se celebrar\u00e1 en el Kremlin <a href=\"https:\/\/www.facebook.com\/events\/329168974153825\/\" rel=\"external nofollow\">una noche de mucho ruidito<\/a> con coraz\u00f3n industrial, en la que participan dos proyectos catalanes de hermosos nombres (Anatom\u00eda Humana Desmontable y Caramuerto) y otros dos vascos (Emankore, que nunca s\u00e9 si se escribe junto o separado, y el DJ Landerground). Vamos con una muestra <em>anat\u00f3mica<\/em>, es decir, un corte del proyecto de Laura H\u00f6ldein.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=2488472442\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=1474802752\/transparent=true\/\" width=\"300\" height=\"150\" seamless=\"\"><a href=\"http:\/\/anatomiahumanadesmontable.bandcamp.com\/album\/medusa-el-ctrica-split-with-magmadam\" rel=\"external nofollow\">MEDUSA EL\u00c9CTRICA split with Magmadam by Anatomia Humana Desmontable<\/a><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Y, mientras el Kremlin tiembla con las vibraciones de la electr\u00f3nica pesada, el Shake! acoger\u00e1 un minifestival o macrobolo con <a href=\"https:\/\/www.facebook.com\/Shakebilbao\/photos\/a.1243081972370030.1073741828.1240680229276871\/1841570849187803\/?type=3&amp;theater\" rel=\"external nofollow\"><del>cinco<\/del> cuatro bandas<\/a> de punk arrebatado, en vertientes que van del macarrismo roquero al terrorismo nihilista. Las estrellas invitadas son Warm Bodies, de Missouri, y Cuchillo de Fuego, de Pontevedra, y el frente vasco lo defender\u00e1n <del>Motorastola,<\/del> Aihotz (no s\u00e9 si seguir\u00e1n tocando quince minutos, como cuando los vimos teloneando a Futuro Terror, o habr\u00e1n subido ya a veinte) y Karpatos.<\/p>\n<p>Les dejo con una sesi\u00f3n de acupuntura a cargo de Warm Bodies y su voz punzante.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/fRS9q9XwjwQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Este ha sido uno de esos meses en los que la selecci\u00f3n mensual de conciertos se me qued\u00f3 desfasada a los pocos d\u00edas de publicarla, porque me enter\u00e9 no de una ni de dos, sino de tres citas que no aparec\u00edan por ninguna parte cuando yo estaba confeccionando mi humilde pero chula miniagenda. Para [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[327,602,1104,3494],"class_list":["post-3869","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao","tag-conciertos","tag-fuzz-in-the-city","tag-warm-bodies"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3869"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3869\/revisions"}],"predecessor-version":[{"id":3882,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3869\/revisions\/3882"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}