{"id":3610,"date":"2017-11-30T13:35:00","date_gmt":"2017-11-30T12:35:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3610"},"modified":"2017-11-30T17:37:05","modified_gmt":"2017-11-30T16:37:05","slug":"algunos-conciertos-de-diciembre-4","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2017\/11\/30\/algunos-conciertos-de-diciembre-4\/","title":{"rendered":"Algunos conciertos de diciembre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3611\" src=\"\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/11\/Kabbalah-600x401.jpg\" alt=\"kabbalah\" width=\"560\" height=\"374\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/11\/Kabbalah-600x401.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/11\/Kabbalah-150x100.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/11\/Kabbalah-300x201.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/11\/Kabbalah-768x514.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/11\/Kabbalah.jpg 2048w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfNo tienen la impresi\u00f3n de que en Bizkaia cada vez hay m\u00e1s locales de conciertos? Hablo de lo peque\u00f1ito, que es lo que m\u00e1s me interesa: por ejemplo, en nuestra selecci\u00f3n de diciembre (nueve conciertos en nueve recintos distintos), nos vamos a pasar dos veces por La Naja, ya ven qu\u00e9 cosas.<\/p>\n<p><strong>La Secta (d\u00eda 1, piso superior del Kafe Antzokia).<\/strong> \u00bfTengo que volver a decir que, para m\u00ed, el periodo de finales de los 80 y principios de los 90 es el m\u00e1s estimulante del rock espa\u00f1ol? Lo he escrito tantas veces (hablando de Los Bichos, de Surfin\u2019 Bichos, de Cancer Moon&#8230;) que a lo mejor acabo coloc\u00e1ndolo como lema bajo el t\u00edtulo del blog. Uno de mis mejores recuerdos de aquella \u00e9poca remota es un concierto de los bilba\u00ednos La Secta en el Replicante de Burlada, que empez\u00f3 (tambi\u00e9n lo he comentado alguna vez) con el cantante pas\u00e1ndome entre las piernas en un arrebato el\u00e9ctrico. Pues bien: este viernes tenemos a la formaci\u00f3n de <a href=\"https:\/\/www.youtube.com\/watch?v=o0D8--AGNf4\" rel=\"external nofollow\"><em>Blue Tales<\/em><\/a>, su \u00e1lbum cl\u00e1sico de 1990, recuperando aquel rock a caballo entre Detroit y Australia que tan bien hac\u00edan. Tambi\u00e9n estar\u00e1n sus coet\u00e1neos leoneses The Salamanders. Qu\u00e9 ilusi\u00f3n.<\/p>\n<p><strong>Kabbalah (d\u00eda 1, La Triangu).<\/strong> Me gusta un mont\u00f3n el \u00e1lbum de debut de <a href=\"https:\/\/www.youtube.com\/watch?v=rHXl7ljGHLk\" rel=\"external nofollow\">Kabbalah<\/a>, el proyecto navarro de rock oculto que han puesto en marcha Carmen y Marga, excomponentes de Las Culebras. Muchos grupos que invocan la psicodelia oscura se quedan, en realidad, solo con su armaz\u00f3n guitarrero, pero Kabbalah tocan todos los palos y exploran los recovecos con fluidez y magia. Negra, claro. Ah, son las de arriba y estar\u00e1n acompa\u00f1adas en su \u00abcelebraci\u00f3n saturnal\u00bb por Wicked Wizzards, de Mungia.<\/p>\n<p><strong>ECM (d\u00eda 2, Txirbilenea).<\/strong> Como en su \u00faltima visita acudimos pocos a verles, y qu\u00e9 bien lo pasamos, vuelvo a reclamar m\u00e1s atenci\u00f3n para este d\u00fao catal\u00e1n que enarbola orgullosamente la bandera de la Deutsch Amerikanische Freundschaft. Ya saben: por un lado, bater\u00eda-electr\u00f3nica-voz, y por otro, sexo-baile-poder. El concierto en Sestao de <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2011\/12\/28\/rescate-de-canciones-esto-es-ecm\/\">Electr\u00f3nica Cuerpo M\u00fasica<\/a> (eso significan las siglas) forma parte de una jornada contra la represi\u00f3n e incluye tambi\u00e9n a su proyecto paralelo <a href=\"https:\/\/www.youtube.com\/watch?v=WBNvS-I0Q4k\" rel=\"external nofollow\">Endora y sus Vicios<\/a>, a Difuntos Telara\u00f1a y a Uger.<\/p>\n<p><strong>Glam Skanks (d\u00eda 3, Nave 9).<\/strong> Como la de DAF, tambi\u00e9n la herencia del glam me da la sensaci\u00f3n de estar un poco desaprovechada, con el juego que da. Y las californianas <a href=\"https:\/\/www.youtube.com\/watch?v=TcHHmDsgjpw\" rel=\"external nofollow\">Glam Skanks <\/a>(qu\u00e9 significar\u00e1 <em>skank<\/em>&#8230; <a href=\"https:\/\/forum.wordreference.com\/threads\/skank.1927277\/\" rel=\"external nofollow\">ah, vaya<\/a>) tienen pinta de sacarles chispas a los hallazgos l\u00fadicos y desinhibidos de la vertiente macarra del g\u00e9nero. Prometen \u00abun viaje en una monta\u00f1a rusa de rock and roll a trav\u00e9s de una nube centelleante de purpurina y una lluvia de boas de plumas\u00bb.<\/p>\n<p><strong>Cuchillo de Fuego (d\u00eda 6, High).<\/strong> El local de La Naja est\u00e1 acogiendo \u00faltimamente conciertos muy interesantes. <a href=\"https:\/\/www.youtube.com\/watch?v=grOK2PdDAow\" rel=\"external nofollow\">Cuchillo de Fuego<\/a> vienen de Pontevedra y hacen una m\u00fasica trepidante y ruidosa (ll\u00e1menlo noise rock o post hardcore o como quieran) con voz ag\u00f3nica y letras ajenas a toda convenci\u00f3n: \u00abD\u00e9jame entrar en tu espacio de \u2018coworking\u2019, \/ que la lluvia ya me encharca el alma\u00bb, arranca su nuevo \u00e1lbum, <em>Megavedra<\/em>. Con ellos estar\u00e1n los locales y siempre intensos K\u00e1rpatos, todo \u00abpor el m\u00f3dico y redondeado precio de 830 pesetas\u00bb.<\/p>\n<p><strong>Matt Bianco (d\u00eda 15, Bizkaia Aretoa).<\/strong> Me frot\u00e9 los ojos un par de veces cuando le\u00ed que ven\u00edan Matt Bianco al 365 Jazz Bilbao. Tienen que aparecer aqu\u00ed: ya s\u00e9 que, emparedado entre Cuchillo de Fuego y la barbaridad que viene despu\u00e9s, el jazz-pop amigable y elegante de Matt Bianco destaca como una cucaracha en el lavabo, pero qu\u00e9 quieren, uno se debe a su pasado. Y all\u00e1 por la primera mitad de los 80, en mi primera adolescencia, a m\u00ed me encantaban las canciones del entonces tr\u00edo brit\u00e1nico y, muy en especial, la voz de su corista polaca Basia Trzetrzelewska, que despu\u00e9s se har\u00eda muy famosa en Europa simplemente como Basia. El apellido no era muy comercial, no. Creo que en los Bianco de hoy solo queda el vocalista y fundador Mark Reilly, pero espero que siga cantando cl\u00e1sicos ligeros como <a href=\"https:\/\/www.youtube.com\/watch?v=-CcyLGh4Whw\" rel=\"external nofollow\"><em>Sneaking Out The Back Door<\/em><\/a> o <em>Get Out Of Your Lazy Bed<\/em>, tan lejanos que parecen de una vida anterior.<\/p>\n<p><strong>Zarata Fest (d\u00edas 22 y 23, La Morada).<\/strong> Un evento que se define como \u00abfestival de m\u00fasica rara y afines\u00bb tiene, ya de partida, todo mi aprecio. El Zarata es una sana erupci\u00f3n de riesgo y anomal\u00eda que le sale a Bilbao todos los a\u00f1os: en esta und\u00e9cima edici\u00f3n, con entrada por La Naja, participar\u00e1 un mont\u00f3n de gente que no conozco, que para eso es un festival de m\u00fasica extra\u00f1a y no el Love The 90\u2019s.<\/p>\n<p><strong><em>M\u00e1s all\u00e1 del cementerio<\/em> (d\u00eda 23, Santana 27).<\/strong> Qu\u00e9 entra\u00f1able pr\u00f3logo a la Nochebuena propone este homenaje a Eskorbuto, que conmemora el 25 aniversario de la muerte de Iosu y Jualma. Adem\u00e1s de Pako, el bater\u00eda y superviviente de la m\u00edtica banda punk, participar\u00e1 un espl\u00e9ndido plantel en el que figuran Toni Metralla y los Antibalas, Penadas por la Ley, Rat-Zinger, Radiocrimen, Subversi\u00f3n X, Distorsi\u00f3n, Radikal Hardcore y Los Demenciales Chicos Acelerados, adem\u00e1s de invitados especiales. El repertorio de Eskorbuto es infalible, as\u00ed que ser\u00e1 una bonita velada. \u00a1Felices navidades sangrientas!<\/p>\n<p><strong>Izar &amp; Star 100 (dia 26, Kafe Antzokia).<\/strong> El tiempo vuela y el ciclo Izar &amp; Star, imprescindible en las agendas bilba\u00ednas, alcanza ya su convocatoria n\u00famero cien. Lo celebra con un fiest\u00f3n a su estilo, es decir, enfrentando a artistas de hoy con ilustres repertorios del pasado: Se\u00f1ores se atrever\u00e1n con R.E.M., McEnroe le hincar\u00e1n el diente a El \u00daltimo de la Fila y Jupiter Jon montar\u00e1n la <em>punky reggae party<\/em>, para garantizar el desmadre y la resaca.<\/p>\n<p>En una hermosa acrobacia, voy a enlazar dos de los conciertos del mes y les dejo con ECM versionando a Eskorbuto.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/aQNtPfoE-F8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u00bfNo tienen la impresi\u00f3n de que en Bizkaia cada vez hay m\u00e1s locales de conciertos? Hablo de lo peque\u00f1ito, que es lo que m\u00e1s me interesa: por ejemplo, en nuestra selecci\u00f3n de diciembre (nueve conciertos en nueve recintos distintos), nos vamos a pasar dos veces por La Naja, ya ven qu\u00e9 cosas. La Secta [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1],"tags":[327,602,3428,3338,939,1382,3426,1657,3429,2642,2714,2717,3427,3430],"class_list":["post-3610","post","type-post","status-publish","format-standard","hentry","category-musica","category-uncategorized","tag-bilbao","tag-conciertos","tag-cuchillo-de-fuego","tag-ecm","tag-eskorbuto","tag-izar-star","tag-kabbalah","tag-la-secta","tag-matt-bianco","tag-sestao","tag-sonidos-de","tag-sopelana","tag-the-glam-skanks","tag-zarata-fest"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3610"}],"version-history":[{"count":4,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3610\/revisions"}],"predecessor-version":[{"id":3615,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3610\/revisions\/3615"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}