{"id":3520,"date":"2017-09-29T17:15:18","date_gmt":"2017-09-29T16:15:18","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3520"},"modified":"2017-09-29T18:53:48","modified_gmt":"2017-09-29T17:53:48","slug":"cancion-de-la-semana-als-wars-das-letzte-mal","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2017\/09\/29\/cancion-de-la-semana-als-wars-das-letzte-mal\/","title":{"rendered":"Canci\u00f3n de la semana: \u2018Als w\u00e4r\u2019s das letzte Mal\u2019"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3521\" src=\"\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/09\/Deutsch-Amerikanische-Freundschaft-D.A.F..jpg\" alt=\"Deutsch Amerikanische Freundschaft (DAF)\" width=\"560\" height=\"400\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/09\/Deutsch-Amerikanische-Freundschaft-D.A.F..jpg 616w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/09\/Deutsch-Amerikanische-Freundschaft-D.A.F.-150x107.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/09\/Deutsch-Amerikanische-Freundschaft-D.A.F.-300x214.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/09\/Deutsch-Amerikanische-Freundschaft-D.A.F.-600x429.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Me he puesto muy contento al comprobar que DAF, la Deutsch Amerikanische Freundschaft, no hab\u00edan tenido jam\u00e1s canci\u00f3n de la semana en el blog, porque eso me permite celebrar como se merece la caja <a href=\"https:\/\/www.groenland.com\/en\/artist\/deutsch-amerikanische-freundschaft\/\" rel=\"external nofollow\"><em>Das Ist DAF<\/em><\/a>, una lujosa edici\u00f3n de sus cuatro \u00e1lbumes m\u00e1s representativos que ha puesto fin a su lamentable ausencia de Spotify y dem\u00e1s canales de la modernidad. DAF, ya lo he dicho un mont\u00f3n de veces, son <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2009\/04\/30\/la-amistad-germano-americana\/\">uno de mis grupos favoritos<\/a> y tambi\u00e9n me parecen un caso infrecuente de banda que cre\u00f3 un estilo radicalmente propio: cuando pasaron de quinteto a d\u00fao, hicieron de la necesidad virtud y se sacaron de la manga su intensa combinaci\u00f3n de m\u00e1quinas y sudor, de electr\u00f3nica y m\u00fasculo. Sobre las sencillas e insistentes secuencias de su \u00ablegendario Korg MS-20\u00bb (as\u00ed lo define Groenland, el sello que edita la caja), la bater\u00eda de resonantes c\u00edmbalos de Robert G\u00f6rl y la voz acuciante del cordob\u00e9s Gabi Delgado-L\u00f3pez abrieron el camino para toda la <em>electronic body music<\/em>, que en realidad rebaj\u00f3 su f\u00f3rmula al prescindir del componente corporal. DAF sonaban militarmente sexuales o sexualmente militares, excitantes e inquietantes a la vez, sacando un partido inesperado a la fon\u00e9tica percutiva del alem\u00e1n.<\/p>\n<p>La caja no incluye el \u00e1lbum de debut, aquel <em>Ein Produkt der Deutsch-Amerikanischen Freundschaft<\/em> que ven\u00eda a ser un caldero de ideas a medio hacer, plasmadas en improvisaciones electr\u00f3nicas. S\u00ed est\u00e1 el segundo, <em>Die kleinen und die B\u00f6sen<\/em>, en el que todav\u00eda son un quinteto que explora distintas posibilidades entre el post-punk y lo industrial. Y, por supuesto, trae su imprescindible trilog\u00eda como d\u00fao (<em>Alles ist Gut<\/em>, <em>Gold und Liebe<\/em> y <em>F\u00fcr immer<\/em>), tan estimulante hoy como hace treinta y cinco a\u00f1os. Mi favorito es <em>F\u00fcr immer<\/em>, el disco con el que los descubr\u00ed, comprado por 150 pesetas en una tienda de Pamplona, pero he decidido seleccionar este <em>Als w\u00e4r\u2019s das letzte Mal<\/em>, una canci\u00f3n de amor obsesiva e hipn\u00f3tica que est\u00e1 incluida en <em>Alles ist Gut<\/em>. \u00c1mame como si fuese la \u00faltima vez&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/0hJhIEDeDRY\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Me he puesto muy contento al comprobar que DAF, la Deutsch Amerikanische Freundschaft, no hab\u00edan tenido jam\u00e1s canci\u00f3n de la semana en el blog, porque eso me permite celebrar como se merece la caja Das Ist DAF, una lujosa edici\u00f3n de sus cuatro \u00e1lbumes m\u00e1s representativos que ha puesto fin a su lamentable [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[99,461,3397,2478],"class_list":["post-3520","post","type-post","status-publish","format-standard","hentry","category-musica","tag-alemania","tag-cancion-de-la-semana","tag-daf","tag-recopilaciones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3520"}],"version-history":[{"count":5,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3520\/revisions"}],"predecessor-version":[{"id":3526,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3520\/revisions\/3526"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}