{"id":352,"date":"2007-01-29T17:11:00","date_gmt":"2007-01-29T17:11:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=352"},"modified":"2007-01-29T17:11:00","modified_gmt":"2007-01-29T17:11:00","slug":"que-viene-albini","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/01\/29\/que-viene-albini\/","title":{"rendered":"\u00a1Que viene Albini!"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2007\/01\/29\/que-viene-albini\/albini\/\" rel=\"attachment wp-att-1980\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-1980\" title=\"Steve Albini\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2007\/01\/Albini.jpg\" alt=\"\" width=\"160\" height=\"160\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2007\/01\/Albini.jpg 160w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2007\/01\/Albini-150x150.jpg 150w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>Algunos grupos de rock son como metadona o, si prefieren, como los fuets de pavo que anuncian ahora por la tele: un suced\u00e1neo de emociones m\u00e1s genuinas e intensas. A m\u00ed me sucede eso con Shellac, la banda que lidera Steve Albini desde mediados de los 90: me encanta, claro, pero para m\u00ed siempre ser\u00e1 una sombra de Big Black, la banda que lideraba Steve Albini a mediados de los 80. Big Black consegu\u00edan transmitir su carga de vicio y depravaci\u00f3n aunque no entendieses las letras -sobre \u00abmutilaci\u00f3n, asesinato, violaci\u00f3n, abuso de menores, piroman\u00eda, inmolaci\u00f3n, racismo y misoginia\u00bb, seg\u00fan la amena lista de la All Music Guide- con un estilo sin precedentes y sin aut\u00e9nticos seguidores, que se centraba en una caja de ritmos cacharrera y unas guitarras m\u00e1s parecidas a una rotaflex que a instrumentos musicales. El tr\u00edo era como un sumidero donde desaguaban el hardcore, el rock alternativo estadounidense de la \u00e9poca (el bueno, el de Sonic Youth, Dinosaur Jr. y Butthole Surfers) y la m\u00fasica industrial, en una mezcla viciada y adictiva que ya nadie sabe hacer: aunque siempre se les menciona como pioneros del rock industrial, se situaban en el extremo opuesto a tanto esteta de lo oscuro como padecemos ahora. \u00d3iganlos y v\u00e9anlos <a href=\"http:\/\/www.youtube.com\/watch?v=vSivVYwKwZc\" target=\"_blank\" rel=\"external nofollow\">aqu\u00ed<\/a> y <a href=\"http:\/\/www.youtube.com\/watch?v=l_gfuN_Llqs\" target=\"_blank\" rel=\"external nofollow\">aqu\u00ed<\/a>.<\/p>\n<p>Y, ahora, a ver si enderezo todo este rodeo: aunque yo a\u00f1ore la urgencia bestial y sin miramientos de aquel primer grupo -y tambi\u00e9n, aunque parezca una contradicci\u00f3n, sus estupendas canciones-, nadie puede negar que Shellac son impresionantes y en directo <a href=\"http:\/\/www.youtube.com\/watch?v=euFufG3MvnM\" target=\"_blank\" rel=\"external nofollow\">han de serlo a\u00fan m\u00e1s<\/a>. Por eso estoy ya <em>expectant\u00edsimo<\/em> ante el festival Noise On Tour Rocks, que se celebrar\u00e1 en el Kafe Antzokia bilba\u00edno el 18 y el 19 de mayo y nos traer\u00e1 a Shellac junto a otras leyendas como Angry Samoans o Beasts Of Bourbon. A falta de pan, buenas son tortas, y seguro que Albini y sus chicos nos dan una bien fuerte, je, je.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Algunos grupos de rock son como metadona o, si prefieren, como los fuets de pavo que anuncian ahora por la tele: un suced\u00e1neo de emociones m\u00e1s genuinas e intensas. A m\u00ed me sucede eso con Shellac, la banda que lidera Steve Albini desde mediados de los 90: me encanta, claro, pero para m\u00ed siempre ser\u00e1 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[321,327,602,2529,2659,2757],"class_list":["post-352","post","type-post","status-publish","format-standard","hentry","category-musica","tag-big-black","tag-bilbao","tag-conciertos","tag-rock","tag-shellac","tag-steve-albini"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=352"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/352\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}