{"id":3448,"date":"2017-05-26T11:48:57","date_gmt":"2017-05-26T10:48:57","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3448"},"modified":"2017-05-26T11:48:57","modified_gmt":"2017-05-26T10:48:57","slug":"cancion-de-la-semana-an-epic-story","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2017\/05\/26\/cancion-de-la-semana-an-epic-story\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;An Epic Story&#039;"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2017\/05\/26\/cancion-de-la-semana-an-epic-story\/peter-perrett-foto-steve-gullick\/\" rel=\"attachment wp-att-3449\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3449\" title=\"Peter Perrett (foto - Steve Gullick)\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/05\/Peter-Perrett-foto-Steve-Gullick-600x380.jpg\" alt=\"\" width=\"560\" height=\"355\" \/><\/a><br \/>\nSi alguien se hubiese jugado su dinero hace treinta y tantos a\u00f1os a que, en 2017, \u00edbamos a tener \u00e1lbum nuevo de <a href=\"https:\/\/www.facebook.com\/peterperrettmusic?pnref=story\" target=\"_blank\" rel=\"external nofollow\">Peter Perrett<\/a>, seguro que las casas de apuestas le habr\u00edan pagado cien a uno. El l\u00edder de The Only Ones, uno de los santos de cabecera de este blog, est\u00e1 entre los supervivientes m\u00e1s improbables de la historia del rock: \u00abSiempre flirteo con la muerte\u00bb, empieza la letra de <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2006\/12\/21\/otra-chica-otro-planeta\" target=\"_blank\">su canci\u00f3n m\u00e1s conocida<\/a>, y en su caso no era un verso de postureo malditista. Perrett, un hombre de aspecto fr\u00e1gil y melanc\u00f3lico, se someti\u00f3 durante a\u00f1os a una dieta qu\u00edmica un tanto desmesurada (miren, <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/05\/13\/retrato-del-roquero-decadente\" target=\"_blank\">aqu\u00ed hablamos de ello<\/a>) que convert\u00eda su vida cotidiana en un inconcebible caos. Pero no solo contin\u00faa aqu\u00ed, entre nosotros, sino que est\u00e1 a punto de sacar disco nuevo y, qu\u00e9 les voy a decir&#8230; \u00a1ya quisieran muchos ese nivel!<\/p>\n<p>Se supone que es su primer \u00e1lbum en solitario, porque aquel proyecto que bautiz\u00f3 Peter Perrett In The One no se considera como tal, y lo ha grabado respaldado por sus hijos Jamie y Peter Jr. Primero present\u00f3 <a href=\"https:\/\/www.youtube.com\/watch?v=LYuGlD3XSOw\" target=\"_blank\" rel=\"external nofollow\"><em>How The West Was Won<\/em><\/a>, una canci\u00f3n que saqueaba amigablemente el <em>Sweet Jane<\/em> de Lou Reed (las maquetas de los Only Ones colaron una vez como grabaciones perdidas de la Velvet), pero este segundo adelanto, <em>An Epic Story<\/em>, nos sit\u00faa ya en el centro de los dominios de Perrett, ese mundo vulnerable y rematadamente sentimental. En realidad, la canci\u00f3n cuenta una historia rom\u00e1ntica, porque est\u00e1 dedicada a Zena, su esposa desde hace 47 a\u00f1os, pero es verdad que en su caso el amor tiene bastante de \u00e9pica, ya que en su momento tuvo que ser heroico soportar al Peter m\u00e1s extraviado y a su excitable amante Lucinda. \u00abSiempre ser\u00e9 tu hombre, \/ nadie podr\u00eda quererme como lo haces t\u00fa. \/ Si pudiese vivir de nuevo mi vida entera, \/ te elegir\u00eda a ti cada una de las veces\u00bb, dice ese estribillo que resplandece. Si la apuesta hubiese incluido que Perrett iba a publicar un nuevo cl\u00e1sico en 2017, yo creo que nos habr\u00edan dado doscientos a uno.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/KlGEO2v8xH8\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Si alguien se hubiese jugado su dinero hace treinta y tantos a\u00f1os a que, en 2017, \u00edbamos a tener \u00e1lbum nuevo de Peter Perrett, seguro que las casas de apuestas le habr\u00edan pagado cien a uno. El l\u00edder de The Only Ones, uno de los santos de cabecera de este blog, est\u00e1 entre los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,2329],"class_list":["post-3448","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-peter-perrett"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3448"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3448\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}