{"id":3431,"date":"2017-05-08T11:35:17","date_gmt":"2017-05-08T10:35:17","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3431"},"modified":"2017-05-08T11:35:17","modified_gmt":"2017-05-08T10:35:17","slug":"algo-sucio-algo-electrico","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2017\/05\/08\/algo-sucio-algo-electrico\/","title":{"rendered":"Algo sucio, algo el\u00e9ctrico"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2017\/05\/08\/algo-sucio-algo-electrico\/reportaje-fotogr%c2%87fico-del-grupo-granadino-lagartija-nick-en-el-parque-de-las-ciencias\/\" rel=\"attachment wp-att-3432\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3432\" title=\"Lagartija Nick (foto - J.E. G\u00f3mez\/Ideal)\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/05\/Lagartija-Nick-600x486.jpg\" alt=\"\" width=\"560\" height=\"453\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Mi lado ego\u00edsta se siente en la gloria cada vez que asisto a un concierto de Lagartija Nick en un local peque\u00f1o y acogedor, de los que a m\u00ed me gustan, como <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2014\/06\/30\/algunos-sonidos-de-julio-3\/\" target=\"_blank\">La Nube<\/a> o el <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/03\/05\/satelite-en-el-satelite\/\" target=\"_blank\">Sat\u00e9lite T<\/a>. Pero mi lado idealista se pasa todo el rato rebel\u00e1ndose, d\u00e1ndome la chapa con pronunciamientos altisonantes sobre la justicia y la dignidad, y as\u00ed suele seguir durante unos cuantos d\u00edas, por mucho que el pitido de o\u00eddos no me permita hacerle mucho caso. Lo malo es que tiene raz\u00f3n, claro: en un pa\u00eds normal, con un ajuste m\u00e1s o menos defendible entre los m\u00e9ritos y las recompensas, Antonio Arias y compa\u00f1\u00eda estar\u00edan encabezando festivales de esos que a m\u00ed no me gustan, abarrotando salas bien grandotas y apareciendo en programas de esa excelente televisi\u00f3n de pa\u00eds normal que tendr\u00edamos.<\/p>\n<p>Por eso me hace mucha ilusi\u00f3n la iniciativa del sello <a href=\"http:\/\/lunardiscos.es\/\" target=\"_blank\" rel=\"external nofollow\">Lunar<\/a>, que acaba de editar <em>Inercia (el p\u00e1rpado del puercoesp\u00edn)<\/em>, un homenaje al \u00e1lbum que ha quedado como obra maestra de la banda granadina, o m\u00e1s bien como obra maestra de su faceta estrictamente rockera, ya que <em>Omega<\/em> siempre estar\u00e1 ah\u00ed como referente estratosf\u00e9rico de la m\u00fasica sin fronteras. A m\u00ed de Lagartija Nick me gusta todo, tambi\u00e9n su fase de metal electr\u00f3nico y sus discos m\u00e1s recientes, pero es cierto que en <em>Inercia<\/em> redondearon su sonido alrededor de unas cuantas canciones adictivas y may\u00fasculas. De los grupos participantes en el tributo, Tri\u00e1ngulo de Amor Bizarro (que hacen <em>Esa extra\u00f1a inercia<\/em>) y Perro (con <em>Porno-st\u00e9reo<\/em>) son los que m\u00e1s a su bola van, con una regurgitaci\u00f3n muy personal que se agradece en un entorno mayormente conservador. Amaral reversionan en clave electr\u00f3nica <em>Universal<\/em>, el tema que ya interpretaron en su excelente EP <em>Granada<\/em>, mientras que Le\u00f3n Benavente han grabado un<em> Solo amnesia<\/em> del que podr\u00edan sacar chispas en directo. Del resto me han gustado especialmente los jiennenses Blam de Lam, a los que ni siquiera conoc\u00eda, con un <em>Algo sucio, algo el\u00e9ctrico<\/em> que arranca en plan Spacemen 3 guitarreros y concluye en plan Spacemen 3 electr\u00f3nicos. Eso s\u00ed, no me queda m\u00e1s remedio que ceder la despedida a mi lado idealista, ya saben, ese abuelo Cebolleta justiciero y un poco aguafiestas: pasen un rato estupendo con <em>Inercia (el p\u00e1rpado del puercoesp\u00edn)<\/em>, que para eso son estos discos, pero, sobre todo, sigan escuchando o empiecen a escuchar ahora mismo <a href=\"https:\/\/www.youtube.com\/watch?v=HvG5NM2D5Dk&#038;list=PLCFF04D090FC0F749\" target=\"_blank\" rel=\"external nofollow\">el <em>Inercia<\/em> a secas<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed?uri=spotify:album:20ggT5HS18rxl5eJ3Kcgt3\" frameborder=\"0\" width=\"300\" height=\"380\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Mi lado ego\u00edsta se siente en la gloria cada vez que asisto a un concierto de Lagartija Nick en un local peque\u00f1o y acogedor, de los que a m\u00ed me gustan, como La Nube o el Sat\u00e9lite T. Pero mi lado idealista se pasa todo el rato rebel\u00e1ndose, d\u00e1ndome la chapa con pronunciamientos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[126,3330,1667,1716,3363,3091,3092,3161],"class_list":["post-3431","post","type-post","status-publish","format-standard","hentry","category-musica","tag-amaral","tag-blam-de-lam","tag-lagartija-nick","tag-leon-benavente","tag-perro","tag-triangulo-de-amor-bizarro","tag-tributos","tag-versiones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3431"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3431\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}