{"id":341,"date":"2007-01-15T18:52:00","date_gmt":"2007-01-15T18:52:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=341"},"modified":"2007-01-15T18:52:00","modified_gmt":"2007-01-15T18:52:00","slug":"raritos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/01\/15\/raritos\/","title":{"rendered":"Raritos"},"content":{"rendered":"<p>Leo que una encuesta de la emisora brit\u00e1nica BBC dio como resultado que la persona m\u00e1s exc\u00e9ntrica a juicio de los s\u00fabditos de Su Graciosa Majestad es <a href=\"http:\/\/www.bjorkonline.com\" target=\"_blank\" rel=\"external nofollow\">Bj\u00f6rk<\/a>, esta buena mujer que cantaba en los <a href=\"http:\/\/es.wikipedia.org\/wiki\/The_Sugarcubes\" target=\"_blank\" rel=\"external nofollow\">Sugarcubes<\/a> antes de convertirse en la musa universal de los gafapastas. De finalistas quedaron <a href=\"http:\/\/www.ozzy.com\" target=\"_blank\" rel=\"external nofollow\">Ozzy Osbourne<\/a>, el amigo de los murci\u00e9lagos, y <a href=\"http:\/\/www.eltonjohn.com\" target=\"_blank\" rel=\"external nofollow\">Elton John<\/a>, el amigo de las princesas difuntas.<\/p>\n<p>No s\u00e9 qu\u00e9 criterios utilizan en UK para definir a alguien como exc\u00e9ntrico, teniendo en cuenta que se trata del pa\u00eds donde llaman comida al fish &#038; chips, ponen moqueta en los rincones m\u00e1s insospechados de sus casas -\u00a1En el WC! \u00a1En la cocina!- y cuyos pr\u00f3ceres tienden a aparecer de cuerpo presente vestidos de dominatrix y con la cabeza enfundada en una bolsa o del brazo de Bienvenida P\u00e9rez.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Bj\u00f6rk\" src=\"\/evadidos\/files\/bjork_01.jpg\" alt=\"\" width=\"230\" height=\"233\" align=\"right\" \/>En cualquier caso, me da que para estas cosas siempre se fijan en los mismos y sin criterio alguno. Porque a ver, \u00bfqu\u00e9 tienen de raro estos tres? Bj\u00f6rk es la enterada que todos hemos tenido en clase, la que estaba a la \u00faltima en literatura noruega, compraba el &#8216;Beat Generation&#8217; y escuchaba flexis de grupos independientes griegos. Y con la misma ropa.<\/p>\n<p>Qu\u00e9 decir de Ozzy. Es el jevi mayor y sonado que todos\u00a0 hemos tenido en el barrio. S\u00ed, el que a mediados de los 80 nos pas\u00f3 el <a href=\"http:\/\/www.metallica.com\" target=\"_blank\" rel=\"external nofollow\">&#8216;Master Of Puppets&#8217;<\/a> grabado en una cinta de 90, con el <a href=\"http:\/\/www.anthrax.com\" target=\"_blank\" rel=\"external nofollow\">&#8216;Spreading The Disease&#8217; de Anthrax<\/a> en la cara B y cosas de <a href=\"http:\/\/www.voivod.com\" target=\"_blank\" rel=\"external nofollow\">Voivod<\/a> para rellenar el hueco. S\u00ed, hombre, el que esnifaba pegamento. Pues Ozzy es ese mismo pero con mucho dinero y pegamento de primera. En cuanto a Elton John, es tan extravagante como Boris o Paco Clavel. O sea, un se\u00f1or normal del artisteo felizmente casado con otro se\u00f1or normal y del artisteo. A ver d\u00f3nde est\u00e1 la excentricidad ah\u00ed.<\/p>\n<p>Propongo a los siete amigos y familiares que leen este blog que voten al personaje extravagante del a\u00f1o. Seguro que nos salen tres premiados mucho m\u00e1s interesantes que los de la BBC.<\/p>\n<p>Y antes de que salte el Primo: FR David no vale.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Leo que una encuesta de la emisora brit\u00e1nica BBC dio como resultado que la persona m\u00e1s exc\u00e9ntrica a juicio de los s\u00fabditos de Su Graciosa Majestad es Bj\u00f6rk, esta buena mujer que cantaba en los Sugarcubes antes de convertirse en la musa universal de los gafapastas. De finalistas quedaron Ozzy Osbourne, el amigo de los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[353,893,909,976,2245,2493],"class_list":["post-341","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bjork","tag-elton-john","tag-encuestas","tag-extravagancia","tag-ozzy-osbourne","tag-reino-unido"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=341"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/341\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}