{"id":3379,"date":"2017-03-04T08:17:54","date_gmt":"2017-03-04T07:17:54","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3379"},"modified":"2017-03-04T08:17:54","modified_gmt":"2017-03-04T07:17:54","slug":"cancion-de-la-semana-snakes-vs-rats","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2017\/03\/04\/cancion-de-la-semana-snakes-vs-rats\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Snakes Vs Rats&#039;"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2017\/03\/04\/cancion-de-la-semana-snakes-vs-rats\/kevin-martin-the-bug-y-dylan-carlson-earth\/\" rel=\"attachment wp-att-3380\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3380\" title=\"Kevin Martin (The Bug) y Dylan Carlson (Earth)\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/03\/Kevin-Martin-The-Bug-y-Dylan-Carlson-Earth.jpg\" alt=\"\" width=\"560\" height=\"560\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/03\/Kevin-Martin-The-Bug-y-Dylan-Carlson-Earth.jpg 1000w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/03\/Kevin-Martin-The-Bug-y-Dylan-Carlson-Earth-150x150.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/03\/Kevin-Martin-The-Bug-y-Dylan-Carlson-Earth-300x300.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/03\/Kevin-Martin-The-Bug-y-Dylan-Carlson-Earth-768x768.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/03\/Kevin-Martin-The-Bug-y-Dylan-Carlson-Earth-600x600.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Los dos se\u00f1ores de la foto a lo mejor no son el tipo de personas a las que uno desear\u00eda enfrentarse en una reuni\u00f3n de vecinos, pero se trata de leyendas en lo suyo. Y lo suyo son dos senderos art\u00edsticos muy diferentes que, a la vez, presentan evidentes paralelismos: como analiza Ninja Tune, el sello que edita su colaboraci\u00f3n, ambos \u201chan estado explorando y distorsionando sus respectivos g\u00e9neros durante m\u00e1s de veinte a\u00f1os y en ese tiempo han definido y redefinido lo que significa heavy\u201d. A la izquierda, con su eterna combinaci\u00f3n de visera y capucha, tenemos al brit\u00e1nico Kevin Martin, que en su carrera de mil alias, proyectos y colaboraciones (<a href=\"https:\/\/www.facebook.com\/thebugofficialpage\/\" target=\"_blank\" rel=\"external nofollow\">The Bug<\/a>, Techno Animal, King Midas Sound, GOD, Ice, The Sidewinder&#8230;) ha establecido inesperados enlaces entre g\u00e9neros como la m\u00fasica industrial, el free jazz, el ambient o el metal extremo, utilizando como amalgama una mutaci\u00f3n monstruosa del dub jamaicano. Adem\u00e1s, y eso quiero resaltarlo porque es como entr\u00f3 en mi vida, es el responsable de algunas de las recopilaciones m\u00e1s fascinantes que conozco: en los 90 compil\u00f3 unos cuantos t\u00edtulos para la serie <em>Virgin Ambient<\/em>, entre los que figuran los reveladores <a href=\"https:\/\/www.youtube.com\/watch?v=DPSEMCX8O7g&#038;list=PLDFD707C49B6A0B41\" target=\"_blank\" rel=\"external nofollow\"><em>Isolationism<\/em><\/a> y <a href=\"https:\/\/www.youtube.com\/watch?v=h8IFVGhWrWE&#038;list=PL555FAF7F46B99933\" target=\"_blank\" rel=\"external nofollow\"><em>Macro Dub Infection<\/em><\/a>.<\/p>\n<p>A la derecha, en fin, est\u00e1 el estadounidense Dylan Carlson, conocido popularmente en su calidad de amigo de Kurt Cobain (y tambi\u00e9n, s\u00ed, de hombre que compr\u00f3 el arma con la que se mat\u00f3 el l\u00edder de Nirvana), pero importante en realidad por haber sido uno de los grandes innovadores del rock de guitarras, al que empuj\u00f3 hasta un territorio donde deja de estar claro si sigue siendo rock. Al frente de su proyecto de \u201cambient metal\u201d <a href=\"https:\/\/www.thronesanddominions.com\/\" target=\"_blank\" rel=\"external nofollow\">Earth<\/a>, el barbudo y patibulario Dylan tuvo la visi\u00f3n de una m\u00fasica colosal, repetitiva y ralentizada, como si cada acorde pesase toneladas y se desplazase con dificultad, aunque en los \u00faltimos tiempos ha dulcificado su propuesta hacia un rollo m\u00e1s contemplativo, m\u00e1s entroncado de alguna manera en la tradici\u00f3n, m\u00e1s (digamos) bonito. Dylan y Kevin, Kevin y Dylan, The Bug y Earth, ya hab\u00edan colaborado en alguna ocasi\u00f3n, y ahora lanzan un \u00e1lbum conjunto al que sirve de adelanto este <em>Snakes vs. Rats<\/em>, que a m\u00ed me hace pensar en unos Godflesh tard\u00edos reducidos al esqueleto r\u00edtmico: de casualidad no tiene nada, porque el l\u00edder de Godflesh, Justin K. Broadrick, es el c\u00f3mplice habitual de Kevin Martin en varios de sus proyectos.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=4215435627\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=2163685699\/transparent=true\/\" width=\"320\" height=\"240\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Los dos se\u00f1ores de la foto a lo mejor no son el tipo de personas a las que uno desear\u00eda enfrentarse en una reuni\u00f3n de vecinos, pero se trata de leyendas en lo suyo. Y lo suyo son dos senderos art\u00edsticos muy diferentes que, a la vez, presentan evidentes paralelismos: como analiza Ninja [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,587,828,831,1163,1578,2161,2884],"class_list":["post-3379","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-colaboraciones","tag-dylan-carlson","tag-earth","tag-godflesh","tag-kevin-martin","tag-nirvana","tag-the-bug"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3379"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3379\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}