{"id":3350,"date":"2017-01-26T13:17:29","date_gmt":"2017-01-26T12:17:29","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3350"},"modified":"2017-01-26T13:17:29","modified_gmt":"2017-01-26T12:17:29","slug":"cancion-de-la-semana-riffermania-kill-kill-kill","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2017\/01\/26\/cancion-de-la-semana-riffermania-kill-kill-kill\/","title":{"rendered":"Canci\u00f3n de la semana: \u2018Riffermania (Kill Kill Kill)\u2019"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2017\/01\/26\/cancion-de-la-semana-riffermania-kill-kill-kill\/singapore-sling-foto-heida-jonsdottir\/\" rel=\"attachment wp-att-3351\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3351\" title=\"Singapore Sling (foto - Hei\u00f0a J\u00f3nsd\u00f3ttir)\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2017\/01\/Singapore-Sling-foto-Hei\u00f0a-J\u00f3nsd\u00f3ttir.png\" alt=\"\" width=\"560\" height=\"274\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/pages\/Singapore-Sling\/34742149719?fref=ts\" target=\"_blank\" rel=\"external nofollow\">Singapore Sling<\/a> constituyen una rareza dentro de Islandia, ese pa\u00eds musicalmente fascinante que produce decenas de grupos exportables a partir de una poblaci\u00f3n como la de La Rioja. El propio Henrik Bjornsson, l\u00edder absoluto de la banda, ha declarado que la cre\u00f3 a partir de una radical combinaci\u00f3n de amor y odio: amor por ciertas m\u00fasicas del pasado y odio, en fin, por la mayor\u00eda de las m\u00fasicas que le rodeaban en el presente. Bjornsson y su banda vienen a ser los Jesus &#038; Mary Chain islandeses, con perd\u00f3n por el clich\u00e9, y uno se imagina al tipo marginado en un rinc\u00f3n de la colorista e hipermoderna escena de Reikiavik, con su ropa de cuero y su cara de palo, rumiando pensamientos como el subt\u00edtulo de esta canci\u00f3n.<\/p>\n<p>La banda, con Bjornsson como \u00fanico miembro fijo, lleva ya diecis\u00e9is a\u00f1os en activo, y de hecho yo fui muy fan de su primer disco, aquel <a href=\"https:\/\/www.youtube.com\/watch?v=cptnjTAKtZE\" target=\"_blank\" rel=\"external nofollow\"><em>The Curse Of Singapore Sling<\/em><\/a> que, s\u00ed, reproduc\u00eda los esquemas de The Jesus &#038; Mary Chain, pero de manera sobresaliente: en realidad, da la impresi\u00f3n de que Bjornsson y compa\u00f1\u00eda est\u00e1n m\u00e1s bien canalizando los mismos sonidos vetustos (los Stooges, el garaje, los grupos de chicas) que fascinaban a los hermanos Reid, de una manera que puede lindar con otros grupos actuales como los franceses <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2011\/04\/30\/cancion-la-semana-je-suis-une-go-go-girl\/\" target=\"_blank\">Limi\u00f1anas<\/a>. Singapore Sling est\u00e1n a punto de editar su noveno \u00e1lbum y han lanzado como adelanto este <em>Riffermania (Kill Kill Kill)<\/em>, escrupulosamente fiel a sus par\u00e1metros habituales. Si les gusta y acaban canturreando esos coros tan simp\u00e1ticos que urgen a matar, no se pierdan su reciente <a href=\"https:\/\/www.youtube.com\/watch?v=m_P7-isDx4Q&#038;t=27s\" target=\"_blank\" rel=\"external nofollow\">conciertillo para la KEXP<\/a>, que est\u00e1 muy bien.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/6zcJc637iAA\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Singapore Sling constituyen una rareza dentro de Islandia, ese pa\u00eds musicalmente fascinante que produce decenas de grupos exportables a partir de una poblaci\u00f3n como la de La Rioja. El propio Henrik Bjornsson, l\u00edder absoluto de la banda, ha declarado que la cre\u00f3 a partir de una radical combinaci\u00f3n de amor y odio: amor [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,1374,2683],"class_list":["post-3350","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-islandia","tag-singapore-sling"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3350"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3350\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}