{"id":3300,"date":"2016-12-02T13:07:16","date_gmt":"2016-12-02T12:07:16","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3300"},"modified":"2016-12-02T13:07:16","modified_gmt":"2016-12-02T12:07:16","slug":"cancion-de-la-semana-dear-prudence","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2016\/12\/02\/cancion-de-la-semana-dear-prudence\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Dear Prudence&#039;"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2016\/12\/02\/cancion-de-la-semana-dear-prudence\/diadermin\/\" rel=\"attachment wp-att-3301\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3301\" title=\"Diadermin\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/12\/Diadermin.jpg\" alt=\"\" width=\"560\" height=\"214\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/12\/Diadermin.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/12\/Diadermin-150x57.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/12\/Diadermin-300x115.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>No, no es <a href=\"https:\/\/www.youtube.com\/watch?v=UQmznZFi8Ho\" target=\"_blank\" rel=\"external nofollow\">la de los Beatles<\/a>, ni siquiera la versi\u00f3n estupenda que hicieron <a href=\"https:\/\/www.youtube.com\/watch?v=M6rrTROoZIw\" target=\"_blank\" rel=\"external nofollow\">Siouxsie And The Banshees<\/a>, aunque ese <em>Dear Prudence<\/em> hist\u00f3rico y can\u00f3nico aparece como referencia en la letra. Nuestra canci\u00f3n de esta semana lleva acompa\u00f1\u00e1ndome unos cuantos a\u00f1os: es uno de esos temas que se cuelan en tu reproductor un d\u00eda, discretamente, sin avasallar, y que a base de escuchas en modo aleatorio acaban revelando toda su grandeza, imponi\u00e9ndose con bravura a lo que el azar les coloca antes y despu\u00e9s. Lo firma el d\u00fao coru\u00f1\u00e9s <a href=\"https:\/\/www.facebook.com\/eilodiadermin\" target=\"_blank\" rel=\"external nofollow\">Diadermin<\/a> y quer\u00eda traerlo por aqu\u00ed hace mucho tiempo, pero no hab\u00eda encontrado la ocasi\u00f3n hasta ahora, cuando la actualidad me ha brindado una excusa m\u00e1s bien pu\u00f1etera: veo que los gallegos acaban de lanzar <a href=\"https:\/\/diadermin.bandcamp.com\" target=\"_blank\" rel=\"external nofollow\"><em>Diadermin 2007-2017<\/em><\/a>, un recopilatorio \u00abde despedida\u00bb con veintis\u00e9is canciones de su personal\u00edsimo pop electr\u00f3nico, dom\u00e9stico y a menudo surrealista, que lo mismo puede evocar a New Order que a <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2008\/08\/14\/la-era-la-inseminacion-artificial\/\" target=\"_blank\">GG Quintanilla<\/a>. Explican que se van a retirar una temporada para \u00abpracticar <em>running<\/em>\u00bb.<\/p>\n<p>La oscura y obsesiva <em>Dear Prudence<\/em> extracta <a href=\"https:\/\/intermediodvd.wordpress.com\/2012\/10\/08\/comedias-y-proverbios-o-cuento-moral-por-lois-pereiro-poema\" target=\"_blank\" rel=\"external nofollow\">un texto de Lois Pereiro<\/a>, el maldito por excelencia de las letras gallegas, un poeta de vida breve y l\u00edrica intensa que aprovecho para recomendar tambi\u00e9n desde aqu\u00ed. Acabo de descubrir en la Wikipedia su epitafio, que traducido al castellano dice: \u00abEscupidme encima cuando pas\u00e9is por delante del lugar donde yo repose, envi\u00e1ndome un h\u00famedo mensaje de vida y de furia necesaria\u00bb. La letra de <em>Dear Prudence<\/em> empieza m\u00e1s o menos as\u00ed: \u00abDe la habitaci\u00f3n vecina, \/ de la que solo me separaba una larga pared, \/ sal\u00eda una canci\u00f3n que me dec\u00eda tantas cosas \/ hace veinte a\u00f1os\u00bb. Y termina con la referencia a un amor de \u00abcoexistencia intangible\u00bb, como de cine franc\u00e9s: \u00abEric Rohmer en Coru\u00f1a, \/ Eric Rohmer en Madrid, \/ Eric Rohmer en ninguna parte\u00bb. Qu\u00e9 bonita es, por cierto, la expresi\u00f3n gallega <em>en ningures<\/em>.<\/p>\n<p>Una \u00faltima cosilla fr\u00edvola: tiene narices que, siendo como soy fan fatal de Tri\u00e1ngulo de Amor Bizarro, no me hubiese enterado hasta ahora de que la mitad femenina de Diadermin, Maria Cea, es hermana gemela de Isa TAB. Evidentemente.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=10399534\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=2093037886\/transparent=true\/\" width=\"320\" height=\"240\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; No, no es la de los Beatles, ni siquiera la versi\u00f3n estupenda que hicieron Siouxsie And The Banshees, aunque ese Dear Prudence hist\u00f3rico y can\u00f3nico aparece como referencia en la letra. Nuestra canci\u00f3n de esta semana lleva acompa\u00f1\u00e1ndome unos cuantos a\u00f1os: es uno de esos temas que se cuelan en tu reproductor un d\u00eda, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,750,1111],"class_list":["post-3300","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-diadermin","tag-galicia"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3300"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3300\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}