{"id":330,"date":"2007-01-03T12:52:14","date_gmt":"2007-01-03T12:52:14","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=330"},"modified":"2007-01-03T12:52:14","modified_gmt":"2007-01-03T12:52:14","slug":"en-desintoxicacion","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/01\/03\/en-desintoxicacion\/","title":{"rendered":"En desintoxicaci\u00f3n"},"content":{"rendered":"<p>Espero que hayan digerido ya las corderadas y las mariscadas, los kilos y las toxinas de m\u00e1s, las sobras de turr\u00f3n y mazap\u00e1n, las reuniones familiares y los regalos in\u00fatiles. Cuando era m\u00e1s joven, me asombraba que mis padres y los adultos en general se alegrasen de la vuelta a la normalidad tras las fiestas, pero estoy descubriendo en m\u00ed esa misma sensaci\u00f3n de alivio y un repentino amor por las verduras. Son buenas las verduras, pru\u00e9benlas: ahora mismo tengo una esforzada brigada de alcachofas y berenjenas barriendo mi aparato digestivo, que imagino tan guarro y pegajoso como mi calle despu\u00e9s de que los vecinos hayan arrojado desde el balc\u00f3n serpentinas, confeti y cava del Lidl.<\/p>\n<p><a href=\"http:\/\/www.regnyouth.com\/?p=3981\" target=\"_blank\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" style=\"margin: 5px;\" title=\"Paulina Rubio\" src=\"\/evadidos\/files\/paul_02.jpg\" alt=\"\" width=\"150\" height=\"200\" align=\"right\" hspace=\"5\" vspace=\"5\" \/>Aqu\u00ed tienen<\/a> una \u00faltima oportunidad para ponerse al d\u00eda con la m\u00fasica de 2006, siquiera sea de forma p\u00f3stuma, en un enlace dedicado a mis querid\u00edsimos compa\u00f1eros de blog y su evasi\u00f3n de listas. A m\u00ed, las navidades me han servido para tener un poco de contacto <em>retrasado <\/em>con la m\u00fasica comercial del a\u00f1o, omnipresente en galas y baretos, y la verdad es que me ha parecido mejor que otras veces: \u00bfno les gusta, por ejemplo, <a href=\"http:\/\/www.youtube.com\/watch?v=lCSTULqmmYE\" target=\"_blank\" rel=\"external nofollow\">&#8216;Ni una sola palabra&#8217;<\/a> de Paulina Rubio? Yo no he parado de cantarla desde que la escuch\u00e9 cuatro o cinco veces en Nochevieja, y me parece la prueba de que se puede hacer m\u00fasica para las masas sin mutar en Kike Santander. Y, antes de que impriman carteles de <em>wanted <\/em>con mi jeta, les confesar\u00e9 que el enganche con <em>la Colatera<\/em> (Dios, <a href=\"http:\/\/www.paulinarubio.com\/Html\/inicio2.html\" target=\"_blank\" rel=\"external nofollow\">vaya web<\/a> terror\u00edfica) no es lo peor: tambi\u00e9n me gusta &#8216;Si yo te digo ven&#8217;, de Maita Vende Ca, arquetipo de buenrollismo palmero. De todas formas, lo mismo esto es efecto de las toxinas navide\u00f1as y se me pasa con la dieta verde y <a href=\"http:\/\/www.youtube.com\/watch?v=FEL3heZVlPY\" target=\"_blank\" rel=\"external nofollow\">un poco de black metal depurativo<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Espero que hayan digerido ya las corderadas y las mariscadas, los kilos y las toxinas de m\u00e1s, las sobras de turr\u00f3n y mazap\u00e1n, las reuniones familiares y los regalos in\u00fatiles. Cuando era m\u00e1s joven, me asombraba que mis padres y los adultos en general se alegrasen de la vuelta a la normalidad tras las fiestas, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1856,2118,2294],"class_list":["post-330","post","type-post","status-publish","format-standard","hentry","category-musica","tag-maita-vende-ca","tag-navidad","tag-paulina-rubio"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=330"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/330\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}