{"id":3247,"date":"2016-09-28T11:43:05","date_gmt":"2016-09-28T10:43:05","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3247"},"modified":"2016-09-28T11:43:05","modified_gmt":"2016-09-28T10:43:05","slug":"lemmy-ya-es-estatua","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2016\/09\/28\/lemmy-ya-es-estatua\/","title":{"rendered":"Lemmy ya es estatua"},"content":{"rendered":"<p>En los comienzos del rock, nadie habr\u00eda previsto que, alg\u00fan d\u00eda, esos tipos que berreaban y sacud\u00edan la pelvis adquirir\u00edan la respetabilidad necesaria para convertirse en escultura. Pero el mundo ha acabado lleno, quiz\u00e1 demasiado, de estatuas de roqueros: hace unos a\u00f1os me toc\u00f3 seleccionar unas cuantas para <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201403\/04\/martes-estatuas-rockeros-rockeros.html\" target=\"_blank\" rel=\"external nofollow\">un reportajito<\/a> y me sorprendi\u00f3 la abundancia y variedad de material. Tambi\u00e9n me llam\u00f3 la atenci\u00f3n, hablando en general, su impactante fealdad, con la de Bob Marley en Kingston y la de Kurt Cobain en Aberdeen como ejemplos particularmente estremecedores. Es un poco triste darle un buen meneo a la historia de la m\u00fasica popular para acabar inmortalizado en forma de monumental engendro.<\/p>\n<p>El caso es que Lemmy, el difunto l\u00edder de Mot\u00f6rhead, tambi\u00e9n cuenta ya con su estatua. Se ha financiado a trav\u00e9s de <em>crowdfunding<\/em>, est\u00e1 hecha de bronce y presenta una ventaja con respecto a otras: la han colocado en un bar, lo que parece m\u00e1s congruente con el personaje que una plaza p\u00fablica con columpios y bancos para jubilados. Est\u00e1, en concreto, en su local favorito, el m\u00edtico Rainbow Bar &#038; Grill de Los \u00c1ngeles, donde Lemmy se pasaba las horas muertas bebiendo Jack Daniels con cola y jugando a la m\u00e1quina de p\u00f3ker: le gustaba tanto el videojuego de marras que, en los \u00faltimos d\u00edas de su vida, se lo colocaron al lado de la cama. A algunos fans no les ha convencido del todo esa rara garita en la que le han colocado, rebautizada ya como \u00abla ducha\u00bb, pero hay un detalle todav\u00eda m\u00e1s cuestionable: la estatua se basa en <a href=\"http:\/\/images1.laweekly.com\/imager\/u\/blog\/7273175\/img_2131.jpg\" target=\"_blank\" rel=\"external nofollow\">una foto cl\u00e1sica<\/a> de Lemmy, obra de Robert John, pero&#8230; \u00a1le han quitado el cigarrillo!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2016\/09\/28\/lemmy-ya-es-estatua\/estatua-de-lemmy\/\" rel=\"attachment wp-att-3248\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3248\" title=\"Estatua de Lemmy\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/09\/Estatua-de-Lemmy.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/09\/Estatua-de-Lemmy.jpg 960w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/09\/Estatua-de-Lemmy-150x150.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/09\/Estatua-de-Lemmy-300x300.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/09\/Estatua-de-Lemmy-768x768.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/09\/Estatua-de-Lemmy-600x600.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En los comienzos del rock, nadie habr\u00eda previsto que, alg\u00fan d\u00eda, esos tipos que berreaban y sacud\u00edan la pelvis adquirir\u00edan la respetabilidad necesaria para convertirse en escultura. Pero el mundo ha acabado lleno, quiz\u00e1 demasiado, de estatuas de roqueros: hace unos a\u00f1os me toc\u00f3 seleccionar unas cuantas para un reportajito y me sorprendi\u00f3 la abundancia [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[272,452,938,1710,1774,2043,2051],"class_list":["post-3247","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bares","tag-california","tag-esculturas","tag-lemmy","tag-los-angeles","tag-monumentos","tag-motorhead"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3247"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3247\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}