{"id":3163,"date":"2016-04-28T15:19:15","date_gmt":"2016-04-28T14:19:15","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3163"},"modified":"2016-04-28T15:19:15","modified_gmt":"2016-04-28T14:19:15","slug":"que-viva-europa","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2016\/04\/28\/que-viva-europa\/","title":{"rendered":"Que viva Europa"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2016\/04\/28\/que-viva-europa\/gruff-rhys\/\" rel=\"attachment wp-att-3164\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3164\" title=\"El m\u00fasico gal\u00e9s Gruff Rhys\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Gruff-Rhys.jpg\" alt=\"\" width=\"560\" height=\"262\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Gruff-Rhys.jpg 947w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Gruff-Rhys-150x70.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Gruff-Rhys-300x140.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Gruff-Rhys-768x359.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Gruff-Rhys-600x281.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Hace unos d\u00edas, a cuenta del <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2016\/04\/20\/la-magia-galesa\/\" target=\"_blank\">fabuloso nuevo \u00e1lbum<\/a> de Cate Le Bon, alud\u00ed una vez m\u00e1s por aqu\u00ed al cuelgue que parece intr\u00ednseco a tantos m\u00fasicos galeses. Pues bien, Gruff Rhys es algo as\u00ed como el sumo sacerdote de esa chaladura psicod\u00e9lica, adorable y fecunda. Ha dado sobradas muestras de ello al frente de Super Furry Animals y en el resto de ramificaciones de su carrera, y vuelve a demostrarlo con su \u00faltimo lanzamiento: a ver si se puede emprender un proyecto m\u00e1s extravagante que el de componer, grabar y difundir una sentida canci\u00f3n de amor a la Uni\u00f3n Europea. La ha titulado <em>I Love EU<\/em>, aprovechando la feliz circunstancia de que las siglas suenan igual que el <em>you<\/em> de otros amores m\u00e1s cotidianos, y la dedica a la \u00abmujer idealista de 60 a\u00f1os\u00bb que en su opini\u00f3n es la comunidad. \u00abDel Danubio al Severn y al Sena, \/ me est\u00e1s volviendo loco\u00bb, canta el t\u00edo, para pedir el voto europe\u00edsta en el refer\u00e9ndum sobre el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Salida_del_Reino_Unido_de_la_Uni%C3%B3n_Europea\" target=\"_blank\" rel=\"external nofollow\">Brexit<\/a>. La letra, bien surtida de despreocupados ripios, menciona la pasta, las <em>baguettes<\/em>, las casta\u00f1uelas e incluso Maastricht, y concluye con una frase demencial que en el v\u00eddeo requiere sus correspondientes notas a pie de p\u00e1gina: \u00abMe quieres aunque soy vegetariano, republicano gal\u00e9s y mediterr\u00e1neo\u00bb.<\/p>\n<p>A trav\u00e9s de <a href=\"http:\/\/www.gruffrhys.com\/i-love-eu\/\" target=\"_blank\" rel=\"external nofollow\">un texto<\/a>, Rhys ha expuesto su visi\u00f3n de la UE como un club estupendo, y dice <em>club<\/em> en el sentido nocturno y juerguista de la palabra. \u00abEst\u00e1 todav\u00eda en construcci\u00f3n, tiene algunos problemas estructurales serios y algunos altavoces han reventado, pero Conny Plank y Marlene Dietrich lo est\u00e1n arreglando en estos momentos. El portero intenta mantener a la gente fuera, pero hay un enorme espacio interior que podr\u00eda albergar a un mont\u00f3n de los que hacen cola. Este fin de semana, sus pistas de baile acogen el Euro Classics Weekender. Tocan Daft Punk, Kraftwerk, Giorgio Moroder y Black Box. Ma\u00f1ana estar\u00e1n Abba, Brigitte Fontaine y Can. El domingo por la tarde tocar\u00e1n Sade, Stereolab, New Order y Technotronic, mientras Andy Votel y Mina Minerva preparan una temporada de electro b\u00e1ltico para el mes que viene. Picasso se ocupa de los <em>visuals<\/em> e Ibiza es la parte al aire libre, donde se congregan los fumadores\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Ur7_jT-obmc\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hace unos d\u00edas, a cuenta del fabuloso nuevo \u00e1lbum de Cate Le Bon, alud\u00ed una vez m\u00e1s por aqu\u00ed al cuelgue que parece intr\u00ednseco a tantos m\u00fasicos galeses. Pues bien, Gruff Rhys es algo as\u00ed como el sumo sacerdote de esa chaladura psicod\u00e9lica, adorable y fecunda. Ha dado sobradas muestras de ello al frente [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[962,1110,1205,2372],"class_list":["post-3163","post","type-post","status-publish","format-standard","hentry","category-musica","tag-europa","tag-gales","tag-gruff-rhys","tag-politica"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3163"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3163\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}