{"id":3151,"date":"2016-04-15T12:13:51","date_gmt":"2016-04-15T11:13:51","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3151"},"modified":"2016-04-15T12:13:51","modified_gmt":"2016-04-15T11:13:51","slug":"cancion-de-la-semana-tidal-wave","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2016\/04\/15\/cancion-de-la-semana-tidal-wave\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Tidal Wave&#039;"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2016\/04\/15\/cancion-de-la-semana-tidal-wave\/tales-of-murder-and-dust\/\" rel=\"attachment wp-att-3152\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3152\" title=\"El grupo dan\u00e9s Tales Of Murder And Dust\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Tales-Of-Murder-And-Dust.png\" alt=\"\" width=\"560\" height=\"257\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Tales-Of-Murder-And-Dust.png 998w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Tales-Of-Murder-And-Dust-150x69.png 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Tales-Of-Murder-And-Dust-300x138.png 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Tales-Of-Murder-And-Dust-768x353.png 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Tales-Of-Murder-And-Dust-600x276.png 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Hay \u00e1lbumes en los que resulta especialmente dif\u00edcil escoger una canci\u00f3n que represente al conjunto: son discos con un claro sentido de unidad, m\u00e1s all\u00e1 de la recopilaci\u00f3n circunstancial, y da la impresi\u00f3n de que cualquiera de sus temas queda un poco cojo si se le separa de sus compa\u00f1eros. El segundo \u00e1lbum de <a href=\"https:\/\/www.facebook.com\/talesonline\/\" target=\"_blank\" rel=\"external nofollow\">Tales Of Murder And Dust<\/a> es de esos: la m\u00fasica fluye sin prisas, con la insistencia necesaria en cada pasaje para que el \u00e1nimo del oyente se vaya impregnando de su tono, m\u00e1s o menos homog\u00e9neo a lo largo de los siete cortes. El quinteto dan\u00e9s (que se coloc\u00f3 ese raro bautismo en sus primeros tiempos, cuando sus principales influencias eran la m\u00fasica surf y las bandas sonoras de Morricone) es una de esas incontables bandas que practican una psicodelia impregnada de shoegaze y post rock, atmosf\u00e9rica y tirando siempre a lo pesaroso, con la peculiaridad de que su uso de instrumentos como el viol\u00edn, el sitar o los teclados les acerca a menudo al drone, a esos sonidos que se prolongan en el tiempo hasta revelar una trama r\u00edtmica y arm\u00f3nica.<\/p>\n<p>Ante la dificultad, he tirado por el camino m\u00e1s f\u00e1cil: <em>Tidal Wave<\/em> es la canci\u00f3n que abre el disco y tambi\u00e9n una de las m\u00e1s largas del lote, ya que se extiende hasta los nueve minutos. Tambi\u00e9n creo que es una de las que evidencian con mayor claridad la influencia de The Velvet Underground que suelen declarar los miembros del grupo, por los ecos de la viola de John Cale y de los ritmos m\u00e1s narcotizados de Moe Tucker. Y, adem\u00e1s, presenta una notable ventaja sobre las dem\u00e1s: si se quedan con el reproductor en marcha, acabar\u00e1n escuchando el \u00e1lbum entero, que es lo m\u00e1s recomendable.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=256176199\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=3833508007\/transparent=true\/\" width=\"320\" height=\"240\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hay \u00e1lbumes en los que resulta especialmente dif\u00edcil escoger una canci\u00f3n que represente al conjunto: son discos con un claro sentido de unidad, m\u00e1s all\u00e1 de la recopilaci\u00f3n circunstancial, y da la impresi\u00f3n de que cualquiera de sus temas queda un poco cojo si se le separa de sus compa\u00f1eros. El segundo \u00e1lbum de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,764,2822],"class_list":["post-3151","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-dinamarca","tag-tales-of-murder-and-dust"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3151"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3151\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}