{"id":3147,"date":"2016-04-07T23:23:27","date_gmt":"2016-04-07T22:23:27","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3147"},"modified":"2016-04-07T23:23:27","modified_gmt":"2016-04-07T22:23:27","slug":"cancion-de-la-semana-la-ribera","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2016\/04\/07\/cancion-de-la-semana-la-ribera\/","title":{"rendered":"Canci\u00f3n de la semana: \u2018La ribera\u2019"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2016\/04\/07\/cancion-de-la-semana-la-ribera\/leon-benavente\/\" rel=\"attachment wp-att-3148\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3148\" title=\"Le\u00f3n Benavente\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Le\u00f3n-Benavente.jpg\" alt=\"\" width=\"560\" height=\"188\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Le\u00f3n-Benavente.jpg 960w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Le\u00f3n-Benavente-150x50.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Le\u00f3n-Benavente-300x101.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Le\u00f3n-Benavente-768x258.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2016\/04\/Le\u00f3n-Benavente-600x202.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Antes de nada, una curiosidad: el primer \u00e1lbum de Le\u00f3n Benavente me gust\u00f3 sin llegar a entusiasmarme, pero es uno de los grupos sobre los que m\u00e1s he hablado en los \u00faltimos dos a\u00f1os. Incluso he acabado charlando sobre Le\u00f3n Benavente con desconocidos. La frase \u00abc\u00f3mo te pareces al de Le\u00f3n Benavente\u00bb ha acabado convirti\u00e9ndose en una especie de peque\u00f1a obsesi\u00f3n personal: me ha abordado gente para dec\u00edrmelo en los lugares m\u00e1s insospechados (incluidos bares a priori poco <em>benaventeros<\/em> como La Espuela, en Bilbao, o el Stereo de Logro\u00f1o), aunque en realidad el supuesto parecido con el vocalista Abraham Boba solo se da desde ciertos \u00e1ngulos. Sobre todo, <a href=\"http:\/\/cdn.shopify.com\/s\/files\/1\/0060\/0262\/products\/LS0651_1024x1024.jpg?v=1418202830\" target=\"_blank\" rel=\"external nofollow\">desde este<\/a>, porque ah\u00ed hasta mi madre podr\u00eda confundirme con \u00e9l, aunque con la foto de arriba tambi\u00e9n tendr\u00eda sus dudas. La prueba de que <a href=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xaf1\/v\/t1.0-9\/11800405_10153642206943738_1536640488728757012_n.jpg?oh=4b77d7905992f6551bb5efb9246c6c08&#038;oe=5787FD41\" target=\"_blank\" rel=\"external nofollow\">no nos parecemos tanto<\/a> es que la gente tambi\u00e9n me ha comparado con <a href=\"http:\/\/cultura.fnac.es\/uploads\/temp\/640x350antonioluque-1440151629.jpg.jpg\" target=\"_blank\" rel=\"external nofollow\">Antonio Luque<\/a>, con <a href=\"http:\/\/nsefotografia.com\/blog\/wp-content\/uploads\/2013\/12\/PS_Touring_Party_Madrid_12934_Mariano_Regidor.jpg\" target=\"_blank\" rel=\"external nofollow\">Ricky Falkner<\/a>, con <a href=\"http:\/\/palhansen.com\/content\/images\/stories\/wayne_coyne-2.jpg\" target=\"_blank\" rel=\"external nofollow\">Wayne Coyne<\/a> o con <a href=\"http:\/\/www.artsandecon.com\/wp-content\/uploads\/2015\/04\/Karl-Marx-014.jpg\" target=\"_blank\" rel=\"external nofollow\">Karl Marx<\/a>, as\u00ed que he llegado a la conclusi\u00f3n de que la presencia de rizos y barba canos elimina cualquier otra consideraci\u00f3n fison\u00f3mica. De todas formas, lo de Le\u00f3n Benavente ha sido exagerado y me ha permitido comprobar que la popularidad de la banda madrile\u00f1a llega mucho m\u00e1s all\u00e1 de lo que yo supon\u00eda, hasta alcanzar a compa\u00f1eros del curro a los que jam\u00e1s habr\u00eda imaginado escuchando su m\u00fasica o asistiendo a sus conciertos.<\/p>\n<p>Esa relaci\u00f3n circunstancial y un poco absurda con Le\u00f3n Benavente me ha hecho cogerles cari\u00f1o, as\u00ed que me alegr\u00e9 mucho hace un mes al descubrir que el segundo adelanto de su segundo \u00e1lbum me enganchaba por fin a lo que hacen, con ese pellizco definitivo que hasta ahora echaba en falta. He decidido traer la canci\u00f3n por aqu\u00ed hoy, justo el d\u00eda en el que se edita el disco, que lleva el escueto t\u00edtulo de <em>2<\/em>. Supongo que <em>La ribera<\/em> se puede interpretar en t\u00e9rminos puramente aleg\u00f3ricos, de desigualdad y orillas sociales, pero yo no puedo evitar que la letra resuene en m\u00ed con una literalidad casi disparatada e inesperadamente localista: caramba, en algunos momentos es como si Boba estuviese cantando desde (y sobre) Zorrozaurre, la pen\u00ednsula de Bilbao sometida a una radical transformaci\u00f3n seg\u00fan proyecto de la reci\u00e9n fallecida Zaha Hadid. Las luces y los trenes al otro lado, la almoneda urban\u00edstica, la incertidumbre sobre el progreso, ese \u00abas\u00f3mate a la ventana, \/ te har\u00e1 sentir un turista\u00bb&#8230; Aqu\u00ed tienen el v\u00eddeo-gif, que me hace pensar que debo adelgazar unos kilitos si quiero seguir pareci\u00e9ndome al de Le\u00f3n Benavente.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/lohRXxO7SfQ\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Antes de nada, una curiosidad: el primer \u00e1lbum de Le\u00f3n Benavente me gust\u00f3 sin llegar a entusiasmarme, pero es uno de los grupos sobre los que m\u00e1s he hablado en los \u00faltimos dos a\u00f1os. Incluso he acabado charlando sobre Le\u00f3n Benavente con desconocidos. La frase \u00abc\u00f3mo te pareces al de Le\u00f3n Benavente\u00bb ha acabado [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,1716],"class_list":["post-3147","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-leon-benavente"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3147"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3147\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}