{"id":314,"date":"2006-12-05T13:07:55","date_gmt":"2006-12-05T13:07:55","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=314"},"modified":"2006-12-05T13:07:55","modified_gmt":"2006-12-05T13:07:55","slug":"oteando","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/12\/05\/oteando\/","title":{"rendered":"Oteando"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"margin: 5px;\" title=\"Kike Santander\" src=\"\/evadidos\/files\/santa_02.jpg\" alt=\"\" width=\"220\" height=\"165\" align=\"right\" hspace=\"5\" vspace=\"5\" \/>Nunca veo <a href=\"http:\/\/www.ot.telecinco.es\/\" target=\"_blank\" rel=\"external nofollow\">OT<\/a>. No lo digo como un m\u00e9rito, sino a modo de constataci\u00f3n: m\u00e1s all\u00e1 de las breves escalas del <em>zapping<\/em>, que en alguna ocasi\u00f3n se extienden hasta cuatro o cinco minutos, procuro evitar esa f\u00e1brica televisiva que produce en cadena estrellas y fracasados. Pero este domingo me tragu\u00e9 una hora del programa y flip\u00e9, no por lo buenos o malos que puedan ser los concursantes sino por lo terribles -y creo que sobre esto hay poca discrepancia posible, aunque alguien se ofender\u00e1- que me parecen sus compositores oficiales. Porque, vamos, aun con los arreglos anodinos y las interpretaciones homog\u00e9neas que impone el programa, uno ve cantar &#8216;Blue Velvet&#8217;, &#8216;You Shook Me All Night Long&#8217; o &#8216;Back In The USSR&#8217; y se da cuenta de que la m\u00fasica popular del siglo XX ha merecido la pena, pero despu\u00e9s sale el desafortunado concursante al que le ha tocado una obra del <em>dire<\/em> Kike Santander -ya s\u00e9 que es se\u00f1or muy premiado, pero&#8230; \u00a1qu\u00e9 atrevimiento!- y el alma se cae a los pies. \u00a1Pobre hombre! \u00a1Ismael se llamaba! Claro que la cosa fue ya catastr\u00f3fica cuando aparecieron todos los participantes y cantaron, con cara de infinita pena que tambi\u00e9n podr\u00eda achacarse a la verg\u00fcenza, un <a href=\"http:\/\/todoesdon.wordpress.com\/2006\/11\/22\/dos-mares\/\" target=\"_blank\" rel=\"external nofollow\">tema sobre la emigraci\u00f3n<\/a> que han debido de escribir tres de ellos y que reza tal que as\u00ed, seg\u00fan transcripci\u00f3n que he encontrado en la red: \u00abInfinitos desiertos cubiertos de mantas. \/ Cansados del cruel sufrimiento que nunca se acaba. \/ Son hombres sedientos de un poco de abrigo, \/ del hambre y del miedo son mudos testigos \/ como aves negadas al vuelo que no tienen alas\u00bb. Ser\u00e9 de sentimientos mostrencos, pero a m\u00ed denme \u00abback in the US, back in the US, back in the USSR\u00bb.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nunca veo OT. No lo digo como un m\u00e9rito, sino a modo de constataci\u00f3n: m\u00e1s all\u00e1 de las breves escalas del zapping, que en alguna ocasi\u00f3n se extienden hasta cuatro o cinco minutos, procuro evitar esa f\u00e1brica televisiva que produce en cadena estrellas y fracasados. Pero este domingo me tragu\u00e9 una hora del programa y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1582,2218,2238,2848],"class_list":["post-314","post","type-post","status-publish","format-standard","hentry","category-musica","tag-kike-santander","tag-operacion-triunfo","tag-ot","tag-television"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=314"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/314\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}