{"id":313,"date":"2006-12-03T11:59:57","date_gmt":"2006-12-03T11:59:57","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=313"},"modified":"2006-12-03T11:59:57","modified_gmt":"2006-12-03T11:59:57","slug":"idolatria-navidena","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/12\/03\/idolatria-navidena\/","title":{"rendered":"Idolatr\u00eda navide\u00f1a"},"content":{"rendered":"<p>Se supone que los villancicos ablandan corazones e infunden en quien los escucha un sentimiento casi m\u00edstico de hermandad e hiperglucemia, pero todos sabemos que, en ocasiones, lo que provocan son ganas de arrasar el centro comercial con un subfusil. En particular, los villancicos <em>modernos <\/em>son capaces de convertir al m\u00e1s pac\u00edfico de los hombres en un perturbado: la vig\u00e9sima vez que uno oye a Boney M cantando con incansable \u00edmpetu lo de las <em>merry christmas<\/em>, una semilla oscura empieza a germinar en el alma y las bombillitas de colores se recolocan para transmitir un inequ\u00edvoco mensaje: &#8220;Mata, mata&#8221;. Pero, aun con eso, todos los a\u00f1os siguen saliendo unos cuantos \u00e1lbumes navide\u00f1os y la gente los compra y pide que se los envuelvan para regalo, supongo que con el prop\u00f3sito de boicotear las celebraciones familiares.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"margin: 5px;\" title=\"Billy Idol\" src=\"\/evadidos\/files\/idol.jpg\" alt=\"\" width=\"220\" height=\"146\" align=\"right\" hspace=\"5\" vspace=\"5\" \/>El colmo es que ya no s\u00f3lo cantan villancicos buenas personas como Raphael o Enya, sino tambi\u00e9n&#8230; \u00a1<a href=\"http:\/\/www.billyidol.com\/v1\/frame.html\" target=\"_blank\" rel=\"external nofollow\">Billy Idol<\/a>! El <em>nexus 6<\/em> del punk comercial edita este a\u00f1o &#8216;Happy Holidays: A Very Special Christmas Album&#8217;, con titulazos como &#8216;White Christmas&#8217;, &#8216;Oh Christmas Tree&#8217; o &#8216;Jingle Bell Rock&#8217;, que pueden escuchar en <a href=\"http:\/\/www.myspace.com\/billyidol\" target=\"_blank\" rel=\"external nofollow\">su MySpace<\/a> si se atreven. \u00bfQue ustedes son gente joven y ni siquiera tienen idea de qui\u00e9n es este hombre? Pues miren, Billy Idol empez\u00f3 en los 70 con Generation X, un grupo punk que todo el mundo da por malillo pero que estaba bastante bien, y arras\u00f3 en solitario durante los 80 con himnos de pub de barrio como <a href=\"http:\/\/www.youtube.com\/watch?v=us9ks6P5UeE\" target=\"_blank\" rel=\"external nofollow\">&#8216;Rebel Yell&#8217;<\/a>, <a href=\"http:\/\/www.youtube.com\/watch?v=DONbY9wd6vU\" target=\"_blank\" rel=\"external nofollow\">&#8216;Dancing With Myself&#8217;<\/a> o el <em>cover <\/em>de <a href=\"http:\/\/www.youtube.com\/watch?v=UXYjeWbZ62w\" target=\"_blank\" rel=\"external nofollow\">&#8216;LA Woman&#8217;<\/a>. En realidad, con una honestidad que le honra, \u00e9l mismo admite que la idea de grabar un disco navide\u00f1o ha sido &#8220;bastante loca&#8221;, argumenta que tiene que pagar facturas y recuerda que, durante dos d\u00e9cadas, ha aprovechado las fiestas para &#8220;colocarse&#8221;. Ahora, contrarresten el subid\u00f3n de glucosa con <a href=\"http:\/\/www.myspace.com\/billyidol\" target=\"_blank\" rel=\"external nofollow\">su versi\u00f3n de &#8216;Eve Of Destruction&#8217;<\/a>, una canci\u00f3n sobre la marcha del mundo hacia el desastre que no estar\u00eda mal colar en la selecci\u00f3n navide\u00f1a de alg\u00fan centro comercial.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Se supone que los villancicos ablandan corazones e infunden en quien los escucha un sentimiento casi m\u00edstico de hermandad e hiperglucemia, pero todos sabemos que, en ocasiones, lo que provocan son ganas de arrasar el centro comercial con un subfusil. En particular, los villancicos modernos son capaces de convertir al m\u00e1s pac\u00edfico de los hombres [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[343,2118,3175],"class_list":["post-313","post","type-post","status-publish","format-standard","hentry","category-musica","tag-billy-idol","tag-navidad","tag-villancicos"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}