{"id":309,"date":"2006-11-22T21:24:59","date_gmt":"2006-11-22T21:24:59","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=309"},"modified":"2006-11-22T21:24:59","modified_gmt":"2006-11-22T21:24:59","slug":"himnos-resurreccion","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/11\/22\/himnos-resurreccion\/","title":{"rendered":"Himnos de resurrecci\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"margin: 5px;\" title=\"Fernando Alfaro\" src=\"\/evadidos\/files\/Alfaro2.jpg\" alt=\"\" width=\"180\" height=\"355\" align=\"right\" hspace=\"5\" vspace=\"5\" \/>Tengo la impresi\u00f3n de que los aficionados al rock nos ponemos de acuerdo con m\u00e1s facilidad cuando hablamos de m\u00fasica que cuando hablamos de letras. Ustedes prueben a decir a sus amistades qui\u00e9n es su letrista favorito en castellano y ver\u00e1n: lo m\u00e1s probable es que sus colegas se carcajeen de forma explosiva, emitiendo incluso proyectiles de saliva, y les repliquen que ese artista concreto es un pedante, un cursi o un indocumentado. \u00bfSantiago Auser\u00f3n? No hay dios que entienda lo que quiere decir. \u00bfCorcobado? Venga ya, \u00e9se es el de \u00absangre de perro en el champ\u00e1n\u00bb. \u00bfBunbury? Bah, pretensiones de u\u00f1itas pintadas. \u00bfJosele Santiago? Un par buenas y el resto, balbuceos de borrachuzo. Y as\u00ed, como dec\u00eda un profesor de mi instituto, sucesiva e indefinidamente, incluso sin meternos a defender plazas tan fr\u00e1giles como las canciones de <a href=\"http:\/\/www.elefant.com\/grupos_dis.php?id=9\" target=\"_blank\" rel=\"external nofollow\">Family<\/a> y otros hipersensibles.<\/p>\n<p>As\u00ed que me da un poco de miedo decir que mi letrista preferido del rock espa\u00f1ol es Fernando Alfaro, y que estoy alegre como un cascabel ante la perspectiva de ver ma\u00f1ana en el <a href=\"http:\/\/www.wintercase.com\/wintercase.html\" target=\"_blank\" rel=\"external nofollow\">Wintercase<\/a> a los Surfin&#8217; Bichos, embarcados en una breve resurrecci\u00f3n. S\u00e9 que la l\u00edrica de este hombre tiende al tremendismo y que su aire b\u00edblico puede resultar cargante, pero a m\u00ed me encanta desde las primeras canciones del grupo, como <a href=\"http:\/\/www.musicoscopio.com\/surfin-bichos\/letras\/4395\/\" target=\"_blank\" rel=\"external nofollow\">&#8216;Gente abollada&#8217;<\/a> o &#8216;\u00bfAmas lo desconocido?&#8217;, hasta las \u00faltimas, como &#8216;Comida china y subfusiles&#8217; o esa maravilla de &#8216;El final de una quimera&#8217;. Chucho, su proyecto posterior, nunca ha llegado a llenarme de igual manera, aunque creo que Alfaro alcanz\u00f3 ah\u00ed su cumbre po\u00e9tica con <a href=\"http:\/\/www.nosololetras.com\/grupos\/c\/chucho\/78\/un-angel-turbio.php\" target=\"_blank\" rel=\"external nofollow\">&#8216;Un \u00e1ngel turbio&#8217;<\/a>, el retrato de un \u00e1ngel contaminado de humanidad. \u00bfC\u00f3mo? \u00bfQue a ustedes les parece un redicho y un hueco? Pues nada, d\u00edganme qui\u00e9n es su favorito en un comentario y as\u00ed me r\u00edo yo tambi\u00e9n.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tengo la impresi\u00f3n de que los aficionados al rock nos ponemos de acuerdo con m\u00e1s facilidad cuando hablamos de m\u00fasica que cuando hablamos de letras. Ustedes prueben a decir a sus amistades qui\u00e9n es su letrista favorito en castellano y ver\u00e1n: lo m\u00e1s probable es que sus colegas se carcajeen de forma explosiva, emitiendo incluso [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[327,602,1011,2798],"class_list":["post-309","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao","tag-conciertos","tag-fernando-alfaro","tag-surfin-bichos"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=309"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/309\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}