{"id":3007,"date":"2015-10-16T15:03:38","date_gmt":"2015-10-16T14:03:38","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=3007"},"modified":"2015-10-16T15:03:38","modified_gmt":"2015-10-16T14:03:38","slug":"cancion-de-la-semana-17-el-lobo-en-tu-puerta","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2015\/10\/16\/cancion-de-la-semana-17-el-lobo-en-tu-puerta\/","title":{"rendered":"Canci\u00f3n de la semana: 17"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/10\/16\/cancion-de-la-semana-17-el-lobo-en-tu-puerta\/el-lobo-en-tu-puerta\/\" rel=\"attachment wp-att-3008\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3008\" title=\"El Lobo en Tu Puerta\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/10\/El-Lobo-en-Tu-Puerta.jpg\" alt=\"\" width=\"560\" height=\"374\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/10\/El-Lobo-en-Tu-Puerta.jpg 960w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/10\/El-Lobo-en-Tu-Puerta-150x100.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/10\/El-Lobo-en-Tu-Puerta-300x200.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/10\/El-Lobo-en-Tu-Puerta-768x512.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/10\/El-Lobo-en-Tu-Puerta-600x400.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>S\u00e9 que hay gente que tiene en gran estima la sutileza y la contenci\u00f3n en la m\u00fasica, pero un servidor es m\u00e1s bien de la tendencia opuesta, que podr\u00edamos resumir en el bonito eslogan \u2018todo al m\u00e1ximo\u2019. Los autores de nuestra canci\u00f3n de la semana, <a href=\"https:\/\/www.facebook.com\/elloboentupuerta\" target=\"_blank\" rel=\"external nofollow\">El Lobo en Tu Puerta<\/a>, vienen a ser la aplicaci\u00f3n de esa est\u00e9tica al blues: el tr\u00edo de Chiclana (bautizado en homenaje a <a href=\"https:\/\/www.youtube.com\/watch?v=aVNJfI7o7_0\" target=\"_blank\" rel=\"external nofollow\">una canci\u00f3n de Howlin\u2019 Wolf<\/a>) acuchilla al venerable g\u00e9nero y se dedica a hurgar en sus heridas, en busca de su coraz\u00f3n venenoso. Lo hace a base de una guitarra que suena como un cohete en ignici\u00f3n, una arm\u00f3nica distorsionada, una bater\u00eda noqueante y una amplitud de miras que lo mismo puede recordar a Black Sabbath que a Rage Against The Machine.<\/p>\n<p>Lo de RATM se refiere sobre todo a dos de las canciones <a href=\"https:\/\/knockturnerecords.bandcamp.com\/album\/el-lobo-en-tu-puerta-grabaciones-sumergidas-2015\" target=\"_blank\" rel=\"external nofollow\">incluidas en el \u00e1lbum<\/a>, las dedicadas a Manny Pacquiao y Serena Williams. Mi intenci\u00f3n era colgarles una de las dos, por eso de mostrar la versatilidad de la banda, pero por el camino me he enamorado de uno de sus temas m\u00e1s <em>tradicionales<\/em>, entendiendo esa palabra a la manera de estos brutos barbudos: <em>17<\/em> suena como Dr. Feelgood tras una mutaci\u00f3n nuclear y retrata el animado velatorio de un tal Charly, al que acudieron&#8230; \u00bfcu\u00e1ntas chicas? \u00a1\u00a1\u00a1Diecisiete!!!, grito yo, y gritar\u00e1n tambi\u00e9n ustedes despu\u00e9s de o\u00edr este himno arrebatador y tozudo. A nadie se le escapar\u00e1 que esto hay que escucharlo y corearlo en directo en cuanto se pueda.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=4141353089\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=3790296181\/transparent=true\/\" width=\"320\" height=\"240\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; S\u00e9 que hay gente que tiene en gran estima la sutileza y la contenci\u00f3n en la m\u00fasica, pero un servidor es m\u00e1s bien de la tendencia opuesta, que podr\u00edamos resumir en el bonito eslogan \u2018todo al m\u00e1ximo\u2019. Los autores de nuestra canci\u00f3n de la semana, El Lobo en Tu Puerta, vienen a ser la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,872],"class_list":["post-3007","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-el-lobo-en-tu-puerta"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=3007"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/3007\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=3007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=3007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=3007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}