{"id":2981,"date":"2015-09-23T17:55:57","date_gmt":"2015-09-23T16:55:57","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2981"},"modified":"2015-09-23T17:55:57","modified_gmt":"2015-09-23T16:55:57","slug":"ochenta-y-ocho-musicos-y-un-piano","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2015\/09\/23\/ochenta-y-ocho-musicos-y-un-piano\/","title":{"rendered":"Ochenta y ocho m\u00fasicos y un piano"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/09\/23\/ochenta-y-ocho-musicos-y-un-piano\/keiji-haino-foto-kazuyuki-funaki\/\" rel=\"attachment wp-att-2982\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-2982\" title=\"Keiji Haino (foto - Kazuyuki Funaki)\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/09\/Keiji-Haino-foto-Kazuyuki-Funaki.png\" alt=\"\" width=\"249\" height=\"374\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/09\/Keiji-Haino-foto-Kazuyuki-Funaki.png 640w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/09\/Keiji-Haino-foto-Kazuyuki-Funaki-100x150.png 100w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/09\/Keiji-Haino-foto-Kazuyuki-Funaki-200x300.png 200w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/09\/Keiji-Haino-foto-Kazuyuki-Funaki-600x901.png 600w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>En esta casa siempre hemos sido <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/tag\/john-cage\" target=\"_blank\">muy aficionados a <em>4\u201933\u2019\u2019<\/em><\/a>, ya saben, la composici\u00f3n de John Cage que consiste en cuatro minutos y treinta y tres segundos de silencio, mientras el mundo y la vida siguen sonando alrededor. Y, cuando digo <em>aficionados<\/em>, no me refiero tanto a escucharla (podr\u00edamos decir, como en el chiste, que es la pieza id\u00f3nea para esos momentos en los que a uno no le apetece escuchar nada) como a hablar de ella y de las iniciativas que surgen a su alrededor, habitualmente muy entretenidas.<\/p>\n<p>As\u00ed que c\u00f3mo no iba a traer por aqu\u00ed la que se presenta como \u00abrespuesta definitiva\u00bb a <em>4\u201933\u2019\u2019<\/em>, si adem\u00e1s se trata de un proyecto de Keiji Haino, el alucinante se\u00f1or de la foto, un m\u00fasico japon\u00e9s que siempre me ha parecido ideal para molestar a los vecinos: cuando me preguntan por un disco apropiado para la autodefensa dom\u00e9stica, recomiendo encarecidamente <a href=\"https:\/\/www.youtube.com\/watch?v=rZItuNoXhAM\" target=\"_blank\" rel=\"external nofollow\">este \u00e1lbum suyo<\/a>. Haino no suele distinguir entre improvisaci\u00f3n y composici\u00f3n, por considerarlas la misma cosa, pero el mes que viene presentar\u00e1 <em>Miracle<\/em>, una pieza a la que viene dando vueltas desde hace cuatro d\u00e9cadas. Es, esta vez s\u00ed, una composici\u00f3n para 88 m\u00fasicos: cada uno de ellos tiene que tocar, con un dedo, una tecla del piano, y han de hacerlo todos de manera simult\u00e1nea. \u00abEsta instrucci\u00f3n completamente espec\u00edfica implica una complicaci\u00f3n f\u00edsica. \u00bfC\u00f3mo pueden juntarse 88 personas alrededor del teclado, de 120 cent\u00edmetros de anchura?\u00bb, plantean los organizadores del <a href=\"http:\/\/www.soundlivetokyo.com\/2015\/en\/miracle.html\" target=\"_blank\" rel=\"external nofollow\">festival Sound Live Tokyo<\/a>, que acoger\u00e1 el estreno. Esa dificultad circense es la que justifica el t\u00edtulo de <em>Milagro<\/em>, por la escasa probabilidad de que salga bien, aunque Keiji Haino ha reclutado a un experto llamado Noriyuki Kiguchi para que le ayude en la disposici\u00f3n de los m\u00fasicos-contorsionistas. Aqu\u00ed tienen un delirante v\u00eddeo de los ensayos, por el que asoma una y otra vez la cabellera plateada del se\u00f1or compositor, como uno de esos se\u00f1ores feudales que mandaban en <em>Humor amarillo<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/dCaIu-ZqOH0?rel=0\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En esta casa siempre hemos sido muy aficionados a 4\u201933\u2019\u2019, ya saben, la composici\u00f3n de John Cage que consiste en cuatro minutos y treinta y tres segundos de silencio, mientras el mundo y la vida siguen sonando alrededor. Y, cuando digo aficionados, no me refiero tanto a escucharla (podr\u00edamos decir, como en el chiste, que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[22,1417,1471,1567,3145],"class_list":["post-2981","post","type-post","status-publish","format-standard","hentry","category-musica","tag-22","tag-japon","tag-john-cage","tag-keiji-haino","tag-vanguardia"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2981"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2981\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}