{"id":2957,"date":"2015-08-14T15:14:31","date_gmt":"2015-08-14T14:14:31","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2957"},"modified":"2015-08-14T15:14:31","modified_gmt":"2015-08-14T14:14:31","slug":"cancion-de-la-semana-edicion-vacaciones-goodbye","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2015\/08\/14\/cancion-de-la-semana-edicion-vacaciones-goodbye\/","title":{"rendered":"Canci\u00f3n de la semana, edici\u00f3n vacaciones: &#039;Goodbye&#039;"},"content":{"rendered":"<p lang=\"es-ES\" align=\"LEFT\"><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/08\/14\/cancion-de-la-semana-edicion-vacaciones-goodbye\/silver-scooter\/\" rel=\"attachment wp-att-2958\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2958\" title=\"Silver Scooter\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/08\/Silver-Scooter.jpg\" alt=\"\" width=\"560\" height=\"385\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/08\/Silver-Scooter.jpg 1080w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/08\/Silver-Scooter-150x103.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/08\/Silver-Scooter-300x207.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/08\/Silver-Scooter-768x529.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/08\/Silver-Scooter-600x413.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p lang=\"es-ES\" align=\"LEFT\">\n<p lang=\"es-ES\" align=\"LEFT\">En mi lista de <em>canciones que habr\u00edan sido un \u00e9xito si el mundo tuviese algo de o\u00eddo<\/em>, ocupa un lugar destacado este <em>Goodbye<\/em> de los estadounidenses Silver Scooter, a quienes podr\u00edamos tambi\u00e9n englobar en alguna categor\u00eda especial, como la de <em>grupos con demasiadas gafas para triunfar<\/em>. En realidad, el \u00e1lbum entero (<em>The Blue Law<\/em>, de 2001) se habr\u00eda merecido una relevancia mucho mayor que la que consigui\u00f3, porque el cuarteto de Texas se las arregl\u00f3 para abrir fuego con esta peque\u00f1a maravilla y, despu\u00e9s, mantener un nivel que no defraudaba en ning\u00fan momento: de hecho, he estado a punto de elegir para esta secci\u00f3n de repesca vacacional alg\u00fan otro corte del disco, como <a href=\"https:\/\/www.youtube.com\/watch?v=-wUF66b-nAA\" target=\"_blank\" rel=\"external nofollow\"><em>Albert Hall<\/em><\/a>, <em>Dirty Little Bar<\/em>,<em> The Lonely Singer<\/em> o <a href=\"https:\/\/www.youtube.com\/watch?v=PPXhti3y-DU\" target=\"_blank\" rel=\"external nofollow\"><em>Crash<\/em><\/a>, aunque al final he vuelto a sucumbir a la fascinaci\u00f3n melanc\u00f3lica de <em>Goodbye<\/em>, con esa letra m\u00ednima sobre marcharse a vivir a otra ciudad.<\/p>\n<p>Silver Scooter eran algo as\u00ed como unos New Order del rock americano, con la misma tristeza agridulce y cabizbaja, pero engarzada en otra tradici\u00f3n. Al frente estaba el cantante y guitarrista Scott Garred, un hombre de voz muy personal que se gana la vida como terapeuta musical para pacientes psiqui\u00e1tricos: estuvo trabajando bastante tiempo en el Oregon State Hospital, donde se rod\u00f3 <em>Alguien vol\u00f3 sobre el nido del cuco<\/em>. El \u00e1lbum que nos ocupa fue el tercero y \u00faltimo que grab\u00f3 con Silver Scooter, pero despu\u00e9s ha editado un mont\u00f3n de referencias bajo el nombre de <a href=\"https:\/\/superxxman.bandcamp.com\/\" target=\"_blank\" rel=\"external nofollow\">Super XX Man<\/a>, un proyecto cambiante que hace dos o tres a\u00f1os se llev\u00f3 a su nuevo lugar de residencia, Melbourne.<\/p>\n<p>\u201cI wanna live in another town&#8230;\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/9Ov6rh5Ym0A?rel=0\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En mi lista de canciones que habr\u00edan sido un \u00e9xito si el mundo tuviese algo de o\u00eddo, ocupa un lugar destacado este Goodbye de los estadounidenses Silver Scooter, a quienes podr\u00edamos tambi\u00e9n englobar en alguna categor\u00eda especial, como la de grupos con demasiadas gafas para triunfar. En realidad, el \u00e1lbum entero (The Blue Law, de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,2674,2792,2860],"class_list":["post-2957","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-silver-scooter","tag-super-xx-man","tag-texas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2957"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2957\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}