{"id":2931,"date":"2015-07-03T11:38:38","date_gmt":"2015-07-03T10:38:38","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2931"},"modified":"2015-07-03T11:38:38","modified_gmt":"2015-07-03T10:38:38","slug":"algunos-conciertos-de-julio","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2015\/07\/03\/algunos-conciertos-de-julio\/","title":{"rendered":"Algunos conciertos de julio"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/07\/03\/algunos-conciertos-de-julio\/bombino\/\" rel=\"attachment wp-att-2932\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2932\" title=\"Bombino\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/07\/Bombino.jpg\" alt=\"\" width=\"560\" height=\"373\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/07\/Bombino.jpg 1280w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/07\/Bombino-150x100.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/07\/Bombino-300x200.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/07\/Bombino-768x512.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/07\/Bombino-600x400.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Bufff, qu\u00e9 solitario ha estado esto. Me he tirado doce d\u00edas de vacaciones, desconectado de todo, as\u00ed que afronto el preceptivo repaso del mes como si fuese un extraterrestre reci\u00e9n aterrizado. O, peor a\u00fan, como el turista abotargado que realmente soy, reci\u00e9n llegado de Menorca y con el cerebro transformado en una masa de queso, sobrasada y <a href=\"http:\/\/blogs.elcorreo.com\/culinariosidad\/2010\/08\/18\/cuixot-joya-la-cocina-menorquina\/\" target=\"_blank\"><em>cuixot<\/em><\/a>. A bote pronto, me llaman la atenci\u00f3n estas siete citas en siete salas (o lugares) diferentes, como mandan las normas del blog.<\/p>\n<p><strong>-Bombino (d\u00eda 3, Palacio Tola de Elorrio).<\/strong> El <a href=\"http:\/\/www.musikaire.eus\/es\" target=\"_blank\" rel=\"external nofollow\">Musikaire<\/a> de Elorrio tiene varios conciertos muy recomendables, entre los que destaca esta nueva visita a Euskadi del cuarteto encabezado por Omara <em>Bombino<\/em> Moctar, una de las figuras m\u00e1s destacadas del rock des\u00e9rtico del N\u00edger. Lo tienen en la foto. Sus estructuras repetitivas, hipn\u00f3ticas y lib\u00e9rrimas podr\u00edan interpretarse como un laxo <a href=\"https:\/\/www.youtube.com\/watch?v=IaqScs7vR-4\" target=\"_blank\" rel=\"external nofollow\"><em>stoner<\/em> sahariano<\/a>.<\/p>\n<p><strong>-DUM Fest (d\u00eda 3, Sonora).<\/strong> Si est\u00e1n al tanto de la escena local, seguramente se habr\u00e1n enterado de que el Sentinel de Erandio ha dejado de programar conciertos, por problemas con la municipalidad. Esta desgraciada circunstancia ha llevado a la elaboraci\u00f3n de un manifiesto titulado <a href=\"https:\/\/www.facebook.com\/derechosuniversalesmusicos\/timeline\" target=\"_blank\" rel=\"external nofollow\">Derechos Universales de los M\u00fasicos<\/a>, que alienta este festi con intenci\u00f3n mensual. Esta vez tocar\u00e1n Indomables, Ancient Emblem, Humano, Beruna, Mala Noche, Fiend y Lion Heart. A <a href=\"https:\/\/www.youtube.com\/watch?v=ZgLdgeHYZ3k\" target=\"_blank\" rel=\"external nofollow\">Beruna<\/a>, por cierto, los vi en el propio Sentinel, y fue uno de los conciertos m\u00e1s ensordecedores a los que he asistido, en estrecha competencia con Swans, Merzbow y Bruce Gilbert.<\/p>\n<p><strong>-Repe Rock (d\u00eda 3, Rep\u00e9lega).<\/strong> Un homenaje a Eskorbuto siempre es buena idea, y este tiene el aliciente inesperado de ver en acci\u00f3n a <a href=\"https:\/\/www.youtube.com\/watch?v=vlbLVhkczMo\" target=\"_blank\" rel=\"external nofollow\">Pako<\/a>, el bater\u00eda y \u00fanico superviviente de la formaci\u00f3n can\u00f3nica de la banda. Pasar\u00e1n por el escenario una docena de grupos y habr\u00e1 apariciones estelares. Despu\u00e9s de Marky Ramone (protagonista del a\u00f1o pasado) y de esto, la asociaci\u00f3n que organiza el evento roquero de Rep\u00e9lega va a tener que echarle imaginaci\u00f3n para superarse en futuras convocatorias.<\/p>\n<p><strong>-The Jesus And Mary Chain (d\u00eda 10, Kobetamendi).<\/strong> Ya s\u00e9 que el <a href=\"http:\/\/www.bilbaobbklive.com\/2015\/es\/\" target=\"_blank\" rel=\"external nofollow\">Bilbao BBK Live<\/a> tiene un programa muy amplio con much\u00edsimas m\u00e1s bandas, pero para m\u00ed <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2012\/02\/09\/hermanos-de-sangre\/\" target=\"_blank\">los Jesus<\/a> est\u00e1n en una dimensi\u00f3n distinta a la del resto del cartel, as\u00ed que destacarlos supone casi una obligaci\u00f3n moral. Tocar\u00e1n \u00edntegramente <em>Psychocandy<\/em>, uno de los discos que marcaron mi adolescencia: han pasado treinta a\u00f1os, pero su sonido es tan extraordinario que ni siquiera parece envejecer.<\/p>\n<p><strong>-Nudozurdo (d\u00eda 11, plaza del Arriaga).<\/strong> Ya que nos dieron esquinazo en mayo, cuando destacamos <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/04\/30\/algunos-conciertos-de-mayo\/\" target=\"_blank\">con foto y todo<\/a> un concierto que acab\u00f3 suspendi\u00e9ndose, vamos a subrayar esta actuaci\u00f3n paralela del Bilbao BBK Live. \u00bfMe puedo copiapegar? Veeeenga: el tr\u00edo madrile\u00f1o ha mudado de estilo en su nuevo \u00e1lbum y suena ahora m\u00e1s sint\u00e9tico y menos rabioso, como si hubiese cambiado de carril para pasar de lo siniestro a lo nuevaolero, pero sobreviven su identidad singular (esa voz&#8230;) y su aire inquietante.<\/p>\n<p><strong>-Kristonfest (d\u00eda 11, Santana 27).<\/strong> Bendita osad\u00eda la que lleva a programar un festival en la jornada grande de un monstruo como el BBK Live, aunque, ciertamente, no s\u00e9 si Muse compartir\u00e1n mucha audiencia con los diversos tent\u00e1culos met\u00e1licos del Kristonfest. Este a\u00f1o veo el conjunto menos <em>stoner<\/em> que de costumbre, con el poder\u00edo y la t\u00e9cnica de los franceses Gojira (cada vez m\u00e1s <a href=\"https:\/\/www.youtube.com\/watch?v=BGHlZwMYO9g\" target=\"_blank\" rel=\"external nofollow\">influidos por Killing Joke<\/a>) y las exploraciones post de los alemanes The Ocean y los madrile\u00f1os internacionales <a href=\"https:\/\/www.youtube.com\/watch?v=XyfdVdLGQpg\" target=\"_blank\" rel=\"external nofollow\">Toundra<\/a>. Completan el cartel Childrain.<\/p>\n<p><strong>-Redd Kross y Bum (d\u00eda 24, Kafe Antzokia).<\/strong> Los hermanos McDonald son unos virtuosos de la melod\u00eda guitarrera y efervescente, que saben traducir sus canciones en directos de felicidad explosiva y contagiosa. Me perd\u00ed su paso por el Antzoki de hace m\u00e1s de un a\u00f1o, pero cont\u00f3 Cubillo que <a href=\"https:\/\/www.youtube.com\/watch?v=6teoeHq6pig\" target=\"_blank\" rel=\"external nofollow\">Redd Kross<\/a> \u00abse salieron de puro estimulantes\u00bb. En esta ocasi\u00f3n, adem\u00e1s, les acompa\u00f1an los adictivos canadienses <a href=\"https:\/\/www.youtube.com\/watch?v=tqO4bmE_Nn4\" target=\"_blank\" rel=\"external nofollow\">Bum<\/a>.<\/p>\n<p>Vamos con los Jesus y sus gloriosos chirridos. Me hace cierta gracia que esto encabece festivales con miles de asistentes.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/zK2nJWNgZBA?rel=0\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Bufff, qu\u00e9 solitario ha estado esto. Me he tirado doce d\u00edas de vacaciones, desconectado de todo, as\u00ed que afronto el preceptivo repaso del mes como si fuese un extraterrestre reci\u00e9n aterrizado. O, peor a\u00fan, como el turista abotargado que realmente soy, reci\u00e9n llegado de Menorca y con el cerebro transformado en una masa de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[327,328,394,602,820,891,927,939,1616,2087,2188,2392,2484,2499,2714,2935],"class_list":["post-2931","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao","tag-bilbao-bbk-live","tag-bombino","tag-conciertos","tag-dum-fest","tag-elorrio","tag-erandio","tag-eskorbuto","tag-kristonfest","tag-muskaire","tag-nudozurdo","tag-portugalete","tag-redd-kross","tag-repe-rock","tag-sonidos-de","tag-the-jesus-and-mary-chain"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2931"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2931\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}