{"id":2885,"date":"2015-04-20T23:05:50","date_gmt":"2015-04-20T22:05:50","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2885"},"modified":"2015-04-20T23:05:50","modified_gmt":"2015-04-20T22:05:50","slug":"lou-y-lulu","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2015\/04\/20\/lou-y-lulu\/","title":{"rendered":"Lou y &#039;Lulu&#039;"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/04\/20\/lou-y-lulu\/lou-reed-metallica\/\" rel=\"attachment wp-att-2886\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2886\" title=\"Lou Reed &#038; Metallica\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/04\/Lou-Reed-Metallica.jpg\" alt=\"\" width=\"559\" height=\"297\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/04\/Lou-Reed-Metallica.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/04\/Lou-Reed-Metallica-150x80.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/04\/Lou-Reed-Metallica-300x160.jpg 300w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>La inclusi\u00f3n, o introducci\u00f3n, o como se diga de Lou Reed en el Rock And Roll Hall Of Fame (con eso de <em>hall<\/em>, yo me lo imagino como un recibidor de abuela repleto de retratitos enmarcados) ha dado pie para recordar su figura y hablar un poco sobre \u00e9l. Su hermana Merrill, por ejemplo, ha escrito <a href=\"https:\/\/medium.com\/cuepoint\/a-family-in-peril-lou-reed-s-sister-sets-the-record-straight-about-his-childhood-20e8399f84a3\" target=\"_blank\" rel=\"external nofollow\">una semblanza<\/a> con la que pretende corregir algunos errores y enderezar algunos mitos sobre la infancia y juventud del difunto Lou: en particular, se refiere al tratamiento de electroshock que, seg\u00fan se ha publicado m\u00e1s de una vez, buscaba corregir sus tendencias homosexuales. \u00abMis padres eran muchas cosas, pero no eran hom\u00f3fobos\u00bb, descarta Merrill, que en su repaso de aquellos a\u00f1os plantea una explosiva mezcla de chaval problem\u00e1tico y depresivo, familia \u00abansiosa y controladora\u00bb y ali\u00f1o de drogas y rock and roll.<\/p>\n<p>Pero lo m\u00e1s curioso de este protagonismo p\u00f3stumo del m\u00fasico neoyorquino ha sido que, en fin, nos ha permitido saber cu\u00e1l cree David Bowie que es la obra maestra de Lou Reed. Y no, no se ha inclinado por las desoladoras profundidades del alma de <em>Berlin<\/em>, ni tampoco por el glam callejero de <em>Transformer<\/em>, en el que algo tuvo que ver \u00e9l mismo. A Bowie, el que le parece un disco redondo y una pasada de verdad es <em>Lulu<\/em>, el disco que firmaron a medias Lou Reed y Metallica, que dio lugar a algunas de <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2011\/10\/27\/descuartizando-a-lulu\/\" target=\"_blank\">las cr\u00edticas m\u00e1s brutales<\/a> de la historia del rock. Lo ha contado Laurie Anderson, la viuda: \u00abDespu\u00e9s de la muerte de Lou, David Bowie me dijo: \u2018Escucha, este es el trabajo m\u00e1s grande de Lou, esta es su obra maestra. Espera y ver\u00e1s, va a ser como <em>Berlin<\/em>, har\u00e1 falta un poco de tiempo para que todo el mundo se ponga al d\u00eda\u2019\u00bb. La propia Laurie, que en su momento no apreci\u00f3 mucho este singular trabajo, lo contempla ahora como un momento crucial y morrocotudo: \u00abHe estado leyendo las letras y es tan feroz&#8230; Est\u00e1 escrito por un hombre que entend\u00eda el miedo y la rabia y el veneno y el temor y la venganza y el amor. Y es rabioso. Cualquiera que haya escuchado a Lou cantar <em>Junior Dad<\/em> nunca olvidar\u00e1 la experiencia de esa canci\u00f3n, arrancada de la Biblia. Esto era rock and roll llevado a niveles enteramente nuevos\u00bb. \u00bfA alguien le apetece emprender la reevaluaci\u00f3n de <em>Loutallica<\/em>? Seguro que algunos estar\u00edan m\u00e1s dispuestos a probar lo del electroshock, pero, por si acaso, ah\u00ed les va&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/MCq4SqGStzE?rel=0\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; La inclusi\u00f3n, o introducci\u00f3n, o como se diga de Lou Reed en el Rock And Roll Hall Of Fame (con eso de hall, yo me lo imagino como un recibidor de abuela repleto de retratitos enmarcados) ha dado pie para recordar su figura y hablar un poco sobre \u00e9l. Su hermana Merrill, por ejemplo, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[686,1698,1813,1960],"class_list":["post-2885","post","type-post","status-publish","format-standard","hentry","category-musica","tag-david-bowie","tag-laurie-anderson","tag-lou-reed","tag-metallica"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2885"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2885\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}