{"id":286,"date":"2006-10-11T13:53:00","date_gmt":"2006-10-11T13:53:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=286"},"modified":"2006-10-11T13:53:00","modified_gmt":"2006-10-11T13:53:00","slug":"rock-alta-graduacion","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/10\/11\/rock-alta-graduacion\/","title":{"rendered":"Rock de alta graduaci\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Drones.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1711\" title=\"The Drones\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Drones.jpg\" alt=\"\" width=\"525\" height=\"375\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Drones.jpg 525w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Drones-150x107.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Drones-300x214.jpg 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Australia es una caldera cerrada donde el rock ha ido fermentando hasta convertirse en algo mucho m\u00e1s peligroso, sucio y viciado. The Birthday Party y los Beasts Of Bourbon son dos ejemplos claros de esa mutaci\u00f3n insular, pero existen casos todav\u00eda m\u00e1s extremos -los temibles <a href=\"http:\/\/www.getonthehorse.com\/whitehorse.htm\" target=\"_blank\" rel=\"external nofollow\">Whitehorse<\/a>, por ejemplo- y, desde luego, m\u00e1s actuales, como el grupo que visita este viernes el Kafe Antzokia bilba\u00edno:<a href=\"http:\/\/www.thedrones.com.au\/\" target=\"_blank\" rel=\"external nofollow\"> The Drones<\/a>, un cuarteto de Melbourne borracho de electricidad y bajas pasiones. El \u00fanico disco suyo que tengo, el absorbente &#8216;Wait Long By The River &#038; The Bodies Of Your Enemies Will Float By&#8217;, promete todo tipo de excesos sobre el escenario, y parece que los tipos sacian con creces esas expectativas. No s\u00e9 qu\u00e9 tal estuvieron la semana pasada en Vitoria, pero gente de cr\u00e9dito que los vio ayer en Madrid todav\u00eda sigue con la boca abierta y el o\u00eddo zumbador. Adem\u00e1s, de primer plato est\u00e1n Se\u00f1or No: \u00bfqu\u00e9 m\u00e1s se puede pedir?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Australia es una caldera cerrada donde el rock ha ido fermentando hasta convertirse en algo mucho m\u00e1s peligroso, sucio y viciado. The Birthday Party y los Beasts Of Bourbon son dos ejemplos claros de esa mutaci\u00f3n insular, pero existen casos todav\u00eda m\u00e1s extremos -los temibles Whitehorse, por ejemplo- y, desde luego, m\u00e1s actuales, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[228,327,602,2529,2906],"class_list":["post-286","post","type-post","status-publish","format-standard","hentry","category-musica","tag-australia","tag-bilbao","tag-conciertos","tag-rock","tag-the-drones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=286"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/286\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}