{"id":2855,"date":"2015-03-18T18:34:33","date_gmt":"2015-03-18T17:34:33","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2855"},"modified":"2015-03-18T18:34:33","modified_gmt":"2015-03-18T17:34:33","slug":"no-se-vende-el-tecnopop","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2015\/03\/18\/no-se-vende-el-tecnopop\/","title":{"rendered":"No se vende el tecnopop"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/03\/18\/no-se-vende-el-tecnopop\/supergrupo\/\" rel=\"attachment wp-att-2856\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-2856 aligncenter\" title=\"Supergrupo\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Supergrupo.jpg\" alt=\"\" width=\"600\" height=\"404\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Supergrupo.jpg 2048w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Supergrupo-150x101.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Supergrupo-300x202.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Supergrupo-768x518.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Supergrupo-600x404.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Hay un nuevo supergrupo llamado <a href=\"https:\/\/www.facebook.com\/Supergupo?fref=ts\" target=\"_blank\" rel=\"external nofollow\">Supergrupo<\/a>. En realidad no es tan nuevo, pero alguien ha debido de pensar que, cuando tienes entre manos un supergrupo, lo mejor es dejar las cosas claras desde el nombre: Supergrupo es como se llama ahora la suma de Aviador Dro, L-Kan y La Monja Enana, una alianza ya veterana que debut\u00f3 hace m\u00e1s de una d\u00e9cada con un disco conjunto de compadreo intergeneracional. Ahora, los miembros de este ej\u00e9rcito mutante regresan de la hibernaci\u00f3n para cumplir su misi\u00f3n sagrada: \u00abSalvar al mundo de los indies, de los hashtags, de los gint\u00f3nics con cosas, de las grasas saturadas, de los <em>diyeis<\/em>, de nosotros mismos\u00bb.<\/p>\n<p>Supergrupo suma once miembros y su \u00e1lbum reci\u00e9n salidito, <em>Crisis en autonom\u00edas infinitas<\/em>, viene a ser como una org\u00eda desprejuiciada de gente flexible y promiscua, en la que unos cantan alegremente temas de otros y se van colando canciones nuevas y unas cuantas versiones de corrales ajenos: de Le\u00f1o, de Par\u00e1lisis Permanente, de los Who, de Michael Nyman. A bote pronto, mi tema favorito del disco es <a href=\"https:\/\/www.youtube.com\/watch?v=G4pb2qhs7qY\" target=\"_blank\" rel=\"external nofollow\"><em>Fortaleza<\/em><\/a>, con su melancol\u00eda existencial a lo New Order, pero no me resisto a colgarles su adaptaci\u00f3n del <a href=\"https:\/\/www.youtube.com\/watch?v=P_7CVs_KZe4\" target=\"_blank\" rel=\"external nofollow\"><em>No se vende el rock and roll<\/em><\/a> de Rosendo y los suyos. Aqu\u00ed se ha transformado en <em>No se vende el tecnopop<\/em>, y soy consciente de que a algunos lectores tradicionalistas les provocar\u00e1 ronchas y picores. Los hay que no lo pueden entender.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/iZZPg4Uh_1A?rel=0\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hay un nuevo supergrupo llamado Supergrupo. En realidad no es tan nuevo, pero alguien ha debido de pensar que, cuando tienes entre manos un supergrupo, lo mejor es dejar las cosas claras desde el nombre: Supergrupo es como se llama ahora la suma de Aviador Dro, L-Kan y La Monja Enana, una alianza ya [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[235,774,1632,1647,1715,2793,3161],"class_list":["post-2855","post","type-post","status-publish","format-standard","hentry","category-musica","tag-aviador-dro","tag-discos","tag-l-kan","tag-la-monja-enana","tag-leno","tag-supergrupo","tag-versiones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2855"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2855\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}