{"id":2845,"date":"2015-03-09T19:58:41","date_gmt":"2015-03-09T18:58:41","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2845"},"modified":"2015-03-09T19:58:41","modified_gmt":"2015-03-09T18:58:41","slug":"el-dificil-cruce-de-naranjo-y-manzanera","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2015\/03\/09\/el-dificil-cruce-de-naranjo-y-manzanera\/","title":{"rendered":"El dif\u00edcil cruce de Naranjo y Manzanera"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/03\/09\/el-dificil-cruce-de-naranjo-y-manzanera\/docu_grupo-roxy-music\/\" rel=\"attachment wp-att-2846\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2846\" title=\"Phil Manzanera (foto: Emilio Naranjo\/Efe)\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Phil-Manzanera-Emilio-Naranjo-Efe.jpg\" alt=\"\" width=\"560\" height=\"373\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Phil-Manzanera-Emilio-Naranjo-Efe.jpg 1056w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Phil-Manzanera-Emilio-Naranjo-Efe-150x100.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Phil-Manzanera-Emilio-Naranjo-Efe-300x200.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Phil-Manzanera-Emilio-Naranjo-Efe-768x512.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Phil-Manzanera-Emilio-Naranjo-Efe-600x400.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Tiene cierta l\u00f3gica que Naranjo y Manzanera no se lleven del todo bien, porque al fin y al cabo uno es una rut\u00e1cea y el otro una ros\u00e1cea. Una vez dicha la tonter\u00eda bot\u00e1nica, saltemos a la m\u00fasica, porque con <a href=\"www.monicanaranjo.com\" target=\"_blank\">Naranjo<\/a> y <a href=\"www.manzanera.com\" target=\"_blank\">Manzanera<\/a> nos referimos a M\u00f3nica y Phil, la diva de la voz incontenible y el guitarrista de Roxy Music. Los caminos de ambos se cruzaron all\u00e1 por los tiempos de <em>Sobrevivir\u00e9<\/em>, la versi\u00f3n del <a href=\"https:\/\/www.youtube.com\/watch?v=8BNNBCjy_pU\" target=\"_blank\" rel=\"external nofollow\"><em>Fiume azzurro<\/em><\/a> de Mina, producida por el brit\u00e1nico, y hasta ahora el hombre no hab\u00eda hecho mucho recuento de aquella colaboraci\u00f3n. Bueno, hace cinco a\u00f1os <a href=\"http:\/\/elpais.com\/diario\/2010\/06\/17\/cultura\/1276725606_850215.html\" target=\"_blank\" rel=\"external nofollow\">coment\u00f3 en <em>El Pa\u00eds<\/em><\/a> que la voz de M\u00f3nica le hab\u00eda parecido \u00abun instrumento incre\u00edble\u00bb.<\/p>\n<p>En el \u00faltimo n\u00famero de la revista <a href=\"http:\/\/www.uncut.co.uk\/\" target=\"_blank\" rel=\"external nofollow\"><em>Uncut<\/em><\/a>, Manzanera, a quien tienen en la foto de arriba, <a href=\"http:\/\/manzanera.com\/new\/wp-content\/uploads\/2015\/02\/Uncut_Phil-Manzanera_Interview-feature_The-Sound-of-Blue_March-Issue-copy.pdf\" target=\"_blank\" rel=\"external nofollow\">protagoniza una secci\u00f3n<\/a> en la que un artista se somete al interrogatorio de los lectores y de algunos colegas. David Gilmour (s\u00ed, el de Pink Floyd, aqu\u00ed hay nivelillo) le pregunta si alguno de los incontables artistas a los que ha producido le ha derrotado. Y no puedo resistirme a copiar la respuesta \u00edntegra, aunque sea un poco larga: \u00abMe resulta bastante dif\u00edcil producir a divas. Recuerdo a M\u00f3nica Naranjo, que era n\u00famero uno en Espa\u00f1a y Sudam\u00e9rica. Yo ten\u00eda que hacer tres canciones con ella. En aquel tiempo, mi estudio estaba en construcci\u00f3n, as\u00ed que instal\u00e9 una cabina de voces en el piso de abajo, con los trenes pasando por fuera. Ella, reci\u00e9n salida de \u00e1lbumes con ventas millonarias, lleg\u00f3 a Kilburn Lane y todo ten\u00eda una pinta un poco chunga. Yo le dije: \u2018No te preocupes, simplemente entra ah\u00ed y estar\u00e1 bien\u2019. En unas horas, hab\u00edamos construido el tema y sonaba fant\u00e1stico. Dije: \u2018Bueno, eso es todo, \u00a1ya est\u00e1 hecho!\u2019. Bueno, dice Naranjo, no puede ser, ha sido demasiado r\u00e1pido. As\u00ed que alquila un estudio puntero en el lago de Lugano. Vamos all\u00ed con su esposo, el t\u00edpico coproductor que estaba un poco mosqueado porque el trabajo lo hac\u00eda yo y no \u00e9l. Todos los d\u00edas, ella volv\u00eda a cantar su parte. Est\u00e1bamos en hoteles separados, con vistas al lago, y yo me aburr\u00eda a muerte. Un d\u00eda el marido me llam\u00f3 y me dijo que a ella no le apetec\u00eda grabar. Y contest\u00e9: \u2018\u00bfSab\u00e9is qu\u00e9? No me apetece hacer vuestro disco, voy a llamar a un taxi y me largo al aeropuerto. Hacedlo vosotros. Buena suerte. Adi\u00f3s\u2019. Me largu\u00e9, fue un momento liberador. Intentaron hacerlo por su cuenta durante meses, pero al final editaron la versi\u00f3n que hab\u00edamos grabado aqu\u00ed, en el piso de abajo. Fue un \u00e9xito enorme\u00bb.<\/p>\n<p>La verdad es que les qued\u00f3 bien&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/cEhNceJvMhY\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Tiene cierta l\u00f3gica que Naranjo y Manzanera no se lleven del todo bien, porque al fin y al cabo uno es una rut\u00e1cea y el otro una ros\u00e1cea. Una vez dicha la tonter\u00eda bot\u00e1nica, saltemos a la m\u00fasica, porque con Naranjo y Manzanera nos referimos a M\u00f3nica y Phil, la diva de la voz [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[148,693,1997,2032,2333,2415],"class_list":["post-2845","post","type-post","status-publish","format-standard","hentry","category-musica","tag-anecdotas","tag-david-gilmour","tag-mina","tag-monica-naranjo","tag-phil-manzanera","tag-productores"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2845"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2845\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}