{"id":2841,"date":"2015-03-06T08:25:28","date_gmt":"2015-03-06T07:25:28","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2841"},"modified":"2015-03-06T08:25:28","modified_gmt":"2015-03-06T07:25:28","slug":"cancion-de-la-semana-honestly-do-yr-worst","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2015\/03\/06\/cancion-de-la-semana-honestly-do-yr-worst\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Honestly Do Yr Worst&#039;"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2015\/03\/06\/cancion-de-la-semana-honestly-do-yr-worst\/joanna-gruesome\/\" rel=\"attachment wp-att-2842\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2842\" title=\"Joanna Gruesome\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Joanna-Gruesome.jpg\" alt=\"\" width=\"560\" height=\"355\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Joanna-Gruesome.jpg 1021w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Joanna-Gruesome-150x95.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Joanna-Gruesome-300x191.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Joanna-Gruesome-768x488.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/03\/Joanna-Gruesome-600x381.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Llevaba mucho tiempo con ganas de dedicar una canci\u00f3n de la semana al quinteto gal\u00e9s <a href=\"https:\/\/www.facebook.com\/pages\/Joanna-Gruesome\/116457368434206\" target=\"_blank\" rel=\"external nofollow\">Joanna Gruesome<\/a>, pero siempre se acababa cruzando algo en el camino: <a href=\"https:\/\/www.youtube.com\/watch?v=CdcvYuQstYA\" target=\"_blank\" rel=\"external nofollow\"><em>Sugarcrush<\/em><\/a>, clara heredera de My Bloody Valentine, estuvo tan a punto que creo que abort\u00e9 el <em>post<\/em> cuando ya hab\u00eda empezado a escribirlo. As\u00ed que no pienso desperdiciar la ocasi\u00f3n que me brinda <em>Honestly Do Yr Worst<\/em>, porque me parece una s\u00edntesis perfecta de las virtudes del grupo en un minuto y cincuenta y un segundos, que viene a ser un suspiro. Bueno, vale, un suspiro largo. Y cu\u00e1ntas cosas pasan en esos dos minutillos de nada: las guitarras arrancan como si se creyesen en una canci\u00f3n de los Buzzcocks, pero a los doce segundos ya estamos en los dominios del indie pop (con cierto aire <em>valentinero<\/em> en el juego de las voces masculina y femenina) y de pronto, all\u00e1 por los cuarenta segundos, se cuela la disonancia y el riff inicial regresa con la cantante Alanna McArdle haciendo de las suyas encima, como en un recordatorio de que algunos miembros de Joanna Gruesome tienen un pasado hardcore.<\/p>\n<p><em>Honestly Do Yr Worst<\/em> sirve como adelanto del segundo \u00e1lbum de Joanna Gruesome (el nombre, por cierto, es un jueguecito de palabras a costa de la pobre <a href=\"https:\/\/www.youtube.com\/watch?v=nfdHy8Vo4Og\" target=\"_blank\" rel=\"external nofollow\">Joanna Newsom<\/a>, con ese <em>gruesome<\/em> que viene a significar <em>espantoso<\/em>). El disco, explican, ir\u00e1 m\u00e1s lejos que sus producciones anteriores \u00aben el experimento de combinar pop hipermel\u00f3dico con violencia sonora\u00bb. Qu\u00e9 bien.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/193994766&#038;color=ff5500&#038;auto_play=false&#038;hide_related=false&#038;show_comments=true&#038;show_user=true&#038;show_reposts=false\" frameborder=\"no\" scrolling=\"no\" width=\"100%\" height=\"166\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Llevaba mucho tiempo con ganas de dedicar una canci\u00f3n de la semana al quinteto gal\u00e9s Joanna Gruesome, pero siempre se acababa cruzando algo en el camino: Sugarcrush, clara heredera de My Bloody Valentine, estuvo tan a punto que creo que abort\u00e9 el post cuando ya hab\u00eda empezado a escribirlo. As\u00ed que no pienso desperdiciar [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,1110,1462],"class_list":["post-2841","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-gales","tag-joanna-gruesome"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2841"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2841\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}