{"id":282,"date":"2006-10-06T12:35:00","date_gmt":"2006-10-06T12:35:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=282"},"modified":"2006-10-06T12:35:00","modified_gmt":"2006-10-06T12:35:00","slug":"psicofonias-informaticas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/10\/06\/psicofonias-informaticas\/","title":{"rendered":"Psicofon\u00edas inform\u00e1ticas"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/IBM-1401.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1716\" title=\"IBM 1401\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/IBM-1401.jpg\" alt=\"\" width=\"538\" height=\"268\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/IBM-1401.jpg 538w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/IBM-1401-150x75.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/IBM-1401-300x149.jpg 300w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan he descubierto hace diez minutos, los pioneros que manejaban los primeros ordenadores sol\u00edan utilizar el sonido para comprobar que el mecanismo funcionaba correctamente. No esperen una explicaci\u00f3n t\u00e9cnica, pero el asunto es que conectaban un altavoz al sistema y lo<em> o\u00edan<\/em> trabajar: en tanto la cosa iba bien, se escuchaba una sucesi\u00f3n de ruiditos de distintas frecuencias, mientras que una nota continua significaba que la computadora se hab\u00eda bloqueado. En realidad, esto no tiene mucho que ver con lo que les iba a contar, pero supongo que en aquel truco est\u00e1n los primeros balbuceos de la m\u00fasica por ordenador. Y ahora, a lo que iba: en 1964, lleg\u00f3 a Islandia el IBM 1401, \u00faltimo grito de la t\u00e9cnica de aquel entonces, y el ingeniero encargado de su mantenimiento, el m\u00fasico aficionado J\u00f3hann Gunnarsson, concibi\u00f3 una manera de aprovechar art\u00edsticamente las ondas electromagn\u00e9ticas que emit\u00eda al funcionar. Programaba la m\u00e1quina, en lo que vendr\u00eda a ser la fase compositiva, y colocaba al lado un receptor de radio, que captaba melod\u00edas de consistencia casi fantasmal.<\/p>\n<p>Cuarenta a\u00f1os despu\u00e9s, el hijo de aquel ingeniero se ha convertido en uno de los principales m\u00fasicos de la isla, <a href=\"http:\/\/www.johannjohannsson.com\/\" target=\"_blank\" rel=\"external nofollow\">J\u00f3hann J\u00f3hannsson<\/a>, cuyo disco <a href=\"http:\/\/www.youtube.com\/watch?v=QDV9nkqsrGA\" target=\"_blank\" rel=\"external nofollow\">&#8216;Englab\u00f6rn&#8217;<\/a> les recomend\u00e9 hace poquito. Y, claro, ha desempolvado las arcaicas cintas de su padre y se ha organizado un \u00e1lbum llamado <a href=\"http:\/\/www.ausersmanual.com\/\" target=\"_blank\" rel=\"external nofollow\">&#8216;IBM 1401, a User&#8217;s Manual&#8217;<\/a>, que sale dentro de diez d\u00edas en el sello 4AD y tiene pinta de ser una cosa serena y m\u00e1s relajante que los Enigma del compa\u00f1ero Arrieta. No se dejen enga\u00f1ar por los <a href=\"http:\/\/www.youtube.com\/watch?v=-k7yE3yMPmw\" target=\"_blank\" rel=\"external nofollow\">movimientos espasm\u00f3dicos<\/a> que hace una tal Erna \u00d3marsdottir (me encantan estos nombres) en el ballet basado en la obra.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Seg\u00fan he descubierto hace diez minutos, los pioneros que manejaban los primeros ordenadores sol\u00edan utilizar el sonido para comprobar que el mecanismo funcionaba correctamente. No esperen una explicaci\u00f3n t\u00e9cnica, pero el asunto es que conectaban un altavoz al sistema y lo o\u00edan trabajar: en tanto la cosa iba bien, se escuchaba una sucesi\u00f3n [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[774,883,1323,1374,1470,2224],"class_list":["post-282","post","type-post","status-publish","format-standard","hentry","category-musica","tag-discos","tag-electronica","tag-ibm-1401","tag-islandia","tag-johann-johannsson","tag-ordenadores"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}