{"id":2806,"date":"2015-02-02T13:35:39","date_gmt":"2015-02-02T12:35:39","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2806"},"modified":"2015-02-02T13:35:39","modified_gmt":"2015-02-02T12:35:39","slug":"algunos-conciertos-de-febrero","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2015\/02\/02\/algunos-conciertos-de-febrero\/","title":{"rendered":"Algunos conciertos de febrero"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/?attachment_id=2805\" rel=\"attachment wp-att-2805\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2805\" title=\"Salem's Pot\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/02\/Salems-Pot.jpg\" alt=\"\" width=\"560\" height=\"420\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/02\/Salems-Pot.jpg 1000w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/02\/Salems-Pot-150x113.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/02\/Salems-Pot-300x225.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/02\/Salems-Pot-768x576.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2015\/02\/Salems-Pot-600x450.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Febrero es cortito, pero viene cargado de conciertos interesantes. Ah\u00ed van nada menos que siete; como de costumbre, en otras tantas salas distintas.<\/p>\n<p><strong>The Clamps (La Nube, d\u00eda 3).<\/strong> Qu\u00e9 buena pinta tiene este <a href=\"https:\/\/www.youtube.com\/watch?v=pSeggzL8A90\" rel=\"external nofollow\">tr\u00edo italiano<\/a>, de B\u00e9rgamo, al que describen por ah\u00ed como \u00abspeed stoner rock and roll\u00bb. Y lo describen bien: lo suyo son riffs pesados que se aceleran hasta acercarse a Mot\u00f6rhead y dem\u00e1s bestias del rock duro y grasiento. Vamos, el plan ideal para una noche de martes en el vibrante garito santutx\u00ed.<\/p>\n<p><strong>B\u00f6lzer y Mantar (Sentinel, d\u00eda 5).<\/strong> Creo que el curro me impedir\u00e1 ir (empieza pronto, para que la gente pueda pillar los \u00faltimos metros), pero me parece el concierto m\u00e1s atractivo del mes. Yo soy un seguidor irregular, inconstante e intermitente del metal durete, pero da la casualidad de que a estos dos d\u00faos s\u00ed los he escuchado con atenci\u00f3n y mucho gusto: los suizos <a href=\"https:\/\/www.youtube.com\/watch?v=3XAE5KDWxc0\" target=\"_blank\" rel=\"external nofollow\">B\u00f6lzer<\/a>, que demuestran que el misticismo psicod\u00e9lico tambi\u00e9n puede ser bien bruto, y los alemanes Mantar, que en el fondo son un grupo mutante de rock and roll. Soy tan simple que habr\u00eda pensado que la suma de estas dos bandas exig\u00eda un local mucho m\u00e1s grande que el Sentinel.<\/p>\n<p><strong>The Paperhead (Kafe Antzokia, d\u00eda 6).<\/strong> Al final no entr\u00f3 en <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2014\/12\/24\/cinco-de-2014-la-lista-evadida\/\" target=\"_blank\">la microlista<\/a> <em>evadida<\/em> de fin de a\u00f1o, pero el \u00e1lbum de <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2014\/12\/05\/cancion-de-la-semana-africa\" target=\"_blank\">estos muchachos<\/a> fue uno de los que m\u00e1s me gustaron en 2014. Son de Nashville, pero suenan que se matan a anta\u00f1ona psicodelia brit\u00e1nica, hasta el punto de canalizar en ocasiones el esp\u00edritu de los primeros Pink Floyd.<\/p>\n<p><strong>Amon Amarth (Santana 27, d\u00eda 6).<\/strong> Mira que me va poco el rollo \u00e9pico, pero estos vikingos de Tumba siempre me han parecido una excepci\u00f3n: en su caso, contra lo que pudiera parecer, la obsesi\u00f3n por la mitolog\u00eda n\u00f3rdica y dem\u00e1s zarandajas paganas es un factor secundario, que simplemente redondea unas canciones <a href=\"https:\/\/www.youtube.com\/watch?v=CpAcxbtXUgQ\" target=\"_blank\" rel=\"external nofollow\">may\u00fasculas, pegadizas y poderosas<\/a>. Levanten sus cuernos de cerveza para brindar con el coloso Johan Hegg.<\/p>\n<p><strong>Ben Watt Trio (Alh\u00f3ndiga, d\u00eda 13).<\/strong> El chico de Everything But The Girl solo hab\u00eda editado un \u00e1lbum en solitario, hace ya la friolera de treinta a\u00f1os, pero en 2014 repiti\u00f3 la experiencia con <a href=\"https:\/\/www.youtube.com\/watch?v=2e_KxrI3erc\" target=\"_blank\" rel=\"external nofollow\"><em>Hendra<\/em><\/a>. Es un disco maduro, de aire cl\u00e1sico e intemporal, que trata temas muy serios sin ponerse tremendo ni melodram\u00e1tico. Vamos, ese tipo de m\u00fasica que podr\u00eda gustar a las masas si el mundo fuese normal.<\/p>\n<p><strong>Santiago Delgado y los Runaway Lovers con Villapellejos (Teatro Campos, d\u00eda 20).<\/strong> A veces, los cruces del ciclo <a href=\"https:\/\/www.facebook.com\/pages\/IZAR-STAR\/101130223305049?ref=ts&#038;fref=ts\" target=\"_blank\" rel=\"external nofollow\">Izar &#038; Star<\/a> son m\u00e1s o menos previsibles, por la sinton\u00eda obvia entre los versionadores y los versionados, pero en casos como este se prende la chispa de la sorpresa. Santiago Delgado y compa\u00f1\u00eda, los hombres del dudu\u00e1, las camisetas a rayas y la ingenuidad a prueba de bombas, revisar\u00e1n a Kaka de Luxe, Pegamoides y Para\u00edso con el apoyo de Villapellejos y ante un p\u00fablico&#8230; muy listo, no hagan caso <a href=\"https:\/\/www.youtube.com\/watch?v=61C4XJSsrn0\" target=\"_blank\" rel=\"external nofollow\">a la canci\u00f3n<\/a>.<\/p>\n<p><strong>Salem\u2019s Pot y Monolord (Sonora, d\u00eda 28).<\/strong> Y redondeamos el mes de manera similar a como lo empezamos, con m\u00e1s guitarras humeantes y m\u00e1s cerebros agujereados. Estas dos bandas suecas, herederas del rock m\u00e1s pesado de los 70, ya dar\u00edan un poco de miedo <a href=\"https:\/\/www.youtube.com\/watch?v=RpC9h5Rsjsw\" target=\"_blank\" rel=\"external nofollow\">por<\/a> <a href=\"https:\/\/www.youtube.com\/watch?v=rCc901E02eY\" target=\"_blank\" rel=\"external nofollow\">separado<\/a>, pero su visita conjunta amenaza con deshacer la materia a base de electricidad reverberante. Arriba tienen, en la foto, a los miembros de Salem\u2019s Pot dispuestos a acometer uno de sus rituales sonoros de largo minutaje.<\/p>\n<p>Ah\u00ed les van cuarenta minutos de Mantar en las sesiones de St. Pauli.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/NQWNZ7AU75g?rel=0\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Febrero es cortito, pero viene cargado de conciertos interesantes. Ah\u00ed van nada menos que siete; como de costumbre, en otras tantas salas distintas. The Clamps (La Nube, d\u00eda 3). Qu\u00e9 buena pinta tiene este tr\u00edo italiano, de B\u00e9rgamo, al que describen por ah\u00ed como \u00abspeed stoner rock and roll\u00bb. Y lo describen bien: lo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[135,304,327,393,602,927,1883,2037,2572,2591,2714,2889,2968],"class_list":["post-2806","post","type-post","status-publish","format-standard","hentry","category-musica","tag-amon-amarth","tag-ben-watt","tag-bilbao","tag-bolzer","tag-conciertos","tag-erandio","tag-mantar","tag-monolord","tag-salems-pot","tag-santiago-delgado-y-los-runaway-lovers","tag-sonidos-de","tag-the-clamps","tag-the-paperhead"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2806"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2806\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}