{"id":279,"date":"2006-10-02T20:39:00","date_gmt":"2006-10-02T20:39:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=279"},"modified":"2006-10-02T20:39:00","modified_gmt":"2006-10-02T20:39:00","slug":"todos-sordos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/10\/02\/todos-sordos\/","title":{"rendered":"Todos sordos"},"content":{"rendered":"<p><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Merzbow.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1719\" title=\"Masami Akita, Merzbow\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Merzbow.jpg\" alt=\"\" width=\"253\" height=\"300\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Merzbow.jpg 349w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Merzbow-127x150.jpg 127w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/10\/Merzbow-254x300.jpg 254w\" sizes=\"auto, (max-width: 253px) 100vw, 253px\" \/><\/a>Los chicos del <a href=\"http:\/\/www.musicaexmachina.com\/\" target=\"_blank\" rel=\"external nofollow\">Musica Ex Machina<\/a> lo han incluido en su p\u00e1gina como quien no quiere la cosa, pero conviene difundirlo para que todo el mundo se vaya preparando: el 16 de diciembre pondr\u00e1 a prueba la resistencia de Bilborock el japon\u00e9s Masami Akita, m\u00e1s conocido como <a href=\"http:\/\/merzbow.net\/\" target=\"_blank\" rel=\"external nofollow\">Merzbow<\/a>, un hombre que lleva m\u00e1s de 25 a\u00f1os entregado a la facci\u00f3n m\u00e1s extrema del ruidismo. Si no lo han escuchado, no s\u00e9 si se har\u00e1n una idea, porque hasta el concepto de <em>estruendo ensordecedor<\/em> es relativo: imaginen un agujero negro que absorbiese todos los sonidos del universo y los vomitase directamente sobre su o\u00eddo interno&#8230; Pues en algo as\u00ed hacen pensar sus obras. Lo que normalmente se conoce como <em>ruido<\/em> en el mundo del rock -desde Sonic Youth y My Bloody Valentine hasta el grindcore y el metal industrial- se queda en fr\u00e1giles canciones de cuna comparado con lo que hace este hombre.<\/p>\n<p>Tengo que puntualizar que a m\u00ed los discos de Merzbow me aburren. Supongo que, en buena medida, eso sucede porque nunca puedo escucharlos al volumen apropiado, ya que alg\u00fan mecanismo de autodefensa me mantiene por debajo de los niveles realmente agresivos. Pero lo he visto dos veces en directo, donde el volumen lo deciden otros, y he salido como nuevo, igual que si me hubiese sometido a un en\u00e9rgico masaje. La primera vez, el tipo se dedic\u00f3 a frotar un instrumento el\u00e9ctrico que parec\u00eda salido de un cap\u00edtulo orate de &#8216;Bricoman\u00eda&#8217;, mientras una chica le acompa\u00f1aba al <a href=\"http:\/\/blogs.elcorreo.com\/index.php\/evadidos\/2005\/12\/08\/\" target=\"_blank\">theremin<\/a> distorsionado. La segunda, utiliz\u00f3 s\u00f3lo su ordenador port\u00e1til para abrir la puerta de los infiernos en compa\u00f1\u00eda de otros tres energ\u00famenos. En las entrevistas, Akita suele explicar que a \u00e9l le encantaban las culminaciones finales de ruido desatado t\u00edpicas de los directos de rock duro, pero le aburr\u00edan las canciones que hab\u00eda entre medias, as\u00ed que ha consagrado su carrera a compensar aquella frustraci\u00f3n adolescente. Venga, echen un vistazo <a href=\"http:\/\/www.youtube.com\/watch?v=Xi3EZvJlXBg\" target=\"_blank\" rel=\"external nofollow\">a esto<\/a>, a ser posible con los altavoces a tope y las orejas prevenidas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los chicos del Musica Ex Machina lo han incluido en su p\u00e1gina como quien no quiere la cosa, pero conviene difundirlo para que todo el mundo se vaya preparando: el 16 de diciembre pondr\u00e1 a prueba la resistencia de Bilborock el japon\u00e9s Masami Akita, m\u00e1s conocido como Merzbow, un hombre que lleva m\u00e1s de 25 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[327,1018,1417,1946,1952,2083,2168,2554],"class_list":["post-279","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao","tag-festivales","tag-japon","tag-mem","tag-merzbow","tag-musica-ex-machina","tag-noise","tag-ruido"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=279"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/279\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}