{"id":2673,"date":"2014-09-23T10:43:51","date_gmt":"2014-09-23T09:43:51","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2673"},"modified":"2014-09-23T10:43:51","modified_gmt":"2014-09-23T09:43:51","slug":"mucho-cuidado-con-vulvatron","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2014\/09\/23\/mucho-cuidado-con-vulvatron\/","title":{"rendered":"Mucho cuidado con Vulvatron"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2014\/09\/23\/mucho-cuidado-con-vulvatron\/vulvatron\/\" rel=\"attachment wp-att-2674\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-2674\" title=\"Vulvatron\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/09\/Vulvatron.jpg\" alt=\"\" width=\"266\" height=\"314\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/09\/Vulvatron.jpg 711w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/09\/Vulvatron-127x150.jpg 127w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/09\/Vulvatron-254x300.jpg 254w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/09\/Vulvatron-600x708.jpg 600w\" sizes=\"auto, (max-width: 266px) 100vw, 266px\" \/><\/a>Tengo cierta costumbre de <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2013\/09\/19\/una-firmita-para-llevar-a-gwar-a-la-super-bowl\/\" target=\"_blank\">mencionar a Gwar<\/a>, as\u00ed que alguien podr\u00eda pensar que soy un fan fatal de la banda de <em>shock rock<\/em>, acostumbrado a ba\u00f1arme en fluidos verdosos y salir a la calle con postizos de monstruo, pero no: mi relaci\u00f3n con ellos no va m\u00e1s all\u00e1 de haberlos visto en directo una vez (y me lo pas\u00e9 bien, pese a las manchas duraderas en la ropa) y seguir sus correr\u00edas a distancia, a la suficiente distancia para que no vuelvan a salpicarme. Este a\u00f1o, las locas aventuras de <a href=\"http:\/\/www.gwar.net\/\" target=\"_blank\" rel=\"external nofollow\">Gwar<\/a> adquirieron un inusual tono l\u00fagubre, ya que el vocalista Dave Brockie, m\u00e1s conocido como el humanoide intergal\u00e1ctico y cornudo Oderus Urungus, falleci\u00f3 en marzo de una sobredosis.<\/p>\n<p>Hab\u00eda cierta curiosidad por saber qui\u00e9n iba a ocupar el hueco enorme y viscoso de Oderus Urungus, y se ve que Gwar se han esforzarlo por cubrirlo bien: primero, volvieron a enrolar a Mike Bishop, que en alineaciones veteranas atend\u00eda por Beefcake The Almighty (algo as\u00ed como <em>El Cachas Todopoderoso<\/em>) y ahora se ha rebautizado como Blothar. Pero la gran novedad ha llegado estos \u00faltimos d\u00edas con la presentaci\u00f3n de Vulvatron, que compartir\u00e1 con \u00e9l las funciones de vocalista. Vulvatron, como ya insin\u00faa el nombre, es una mujer, aunque su curr\u00edculum oficial puntualiza que est\u00e1 \u00abgen\u00e9ticamente modificada para lograr las proporciones \u00f3ptimas de una hembra de su especie\u00bb, que \u00abha regresado del a\u00f1o 69000\u00bb y que domina \u00ablas artes de la guerra, la mec\u00e1nica cu\u00e1ntica y la musicolog\u00eda intergal\u00e1ctica\u00bb. Adem\u00e1s, como corresponde a un grupo tan aficionado a los surtidores repugnantes, es capaz de expulsar chorros de sangre por sus pechos prost\u00e9ticos.<\/p>\n<p>Hac\u00eda mucho que en Gwar no militaba una chica, y hasta ahora siempre hab\u00edan asumido roles secundarios, pero Vulvatron tiene pinta de convertirse en una presencia central en sus conciertos. Bajo la caracterizaci\u00f3n se esconde Kim Dylla, una dise\u00f1adora que ha confeccionado <a href=\"http:\/\/www.kyllacustomrockwear.com\" target=\"_blank\" rel=\"external nofollow\">ropa muy bonita<\/a> para bandas coomo Slipknot, Carcass, Cradle Of Filth, Dimmu Borgir, Kreator o los propios Gwar. \u00abMi misi\u00f3n es alterar la actual senda de Gwar para que puedan prevenir el periodo m\u00e1s oscuro de la historia del universo -ha explicado Vulvatron en sus primeras declaraciones-. He calculado el plan de acci\u00f3n \u00f3ptimo para conseguirlo&#8230; \u00a1Eh, dejad de mirarme las tetas!\u00bb.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tengo cierta costumbre de mencionar a Gwar, as\u00ed que alguien podr\u00eda pensar que soy un fan fatal de la banda de shock rock, acostumbrado a ba\u00f1arme en fluidos verdosos y salir a la calle con postizos de monstruo, pero no: mi relaci\u00f3n con ellos no va m\u00e1s all\u00e1 de haberlos visto en directo una vez [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1223,2663,3196],"class_list":["post-2673","post","type-post","status-publish","format-standard","hentry","category-musica","tag-gwar","tag-shock-rock","tag-vulvatron"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2673"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2673\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}