{"id":2520,"date":"2014-03-27T11:37:51","date_gmt":"2014-03-27T10:37:51","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2520"},"modified":"2014-03-27T11:37:51","modified_gmt":"2014-03-27T10:37:51","slug":"esa-estupida-coleccion-de-discos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2014\/03\/27\/esa-estupida-coleccion-de-discos\/","title":{"rendered":"Esa est\u00fapida colecci\u00f3n de discos"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2014\/03\/27\/esa-estupida-coleccion-de-discos\/tumblr_inline_n2crcsqst01sauz6x\/\" rel=\"attachment wp-att-2521\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-2521\" title=\"Sarah O'Holla con el disco de Arab On Radar\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/03\/tumblr_inline_n2crcsqST01sauz6x.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/03\/tumblr_inline_n2crcsqST01sauz6x.jpg 500w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/03\/tumblr_inline_n2crcsqST01sauz6x-150x113.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/03\/tumblr_inline_n2crcsqST01sauz6x-300x225.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Dicen los que saben de estas cosas que los blogs est\u00e1n pasados de moda, porque los usos de nuestra era est\u00e1n sujetos a una especie de mudanza acelerada, que ha relegado ya estos entra\u00f1ables <em>posts<\/em> al nivel de los pergaminos y los frisos en bajorrelieve. Pero, bueno, todav\u00eda ocurre de vez en cuando que un blog llame la atenci\u00f3n y genere cierto debate: uno de los \u00faltimos que han avivado la controversia es <a href=\"http:\/\/alltherecords.tumblr.com\/\" target=\"_blank\" rel=\"external nofollow\"><em>My Husband\u2019s Stupid Record Collection<\/em><\/a>, es decir, <em>La est\u00fapida colecci\u00f3n de discos de mi marido<\/em>, en el que la bibliotecaria estadounidense Sarah O&#8217;Holla afronta la dura tarea de escuchar y rese\u00f1ar, uno por uno y por orden alfab\u00e9tico, los 1.500 discos de su esposo Alex. A m\u00ed me cautiv\u00f3 desde la primera vez que le\u00ed una de sus entregas: a Sarah le gusta la m\u00fasica, pero le ha tocado convivir con un tipo un poco latoso que mezcla en su discoteca mil estilos diferentes, incluidos algunos muy poco amables, as\u00ed que sus comentarios tienen el aliciente de ver c\u00f3mo alguien se enfrenta sin prejuicios ni pudores a artistas como Albert Ayler, Alternative TV, las Au Pairs, Arab On Radar o Anthrax, que son algunos de los que han salido en la letra A. Pese al t\u00edtulo del blog, por cierto, Sarah adopta una actitud muy constructiva, ir\u00f3nica a veces pero siempre positiva: \u00abNo me veo intent\u00e1ndolo m\u00e1s de una vez con este tipo de m\u00fasica \u2013escribe sobre Ayler\u2013, as\u00ed que no creo que lo ponga de nuevo, pero parece que era un artista de verdad que hac\u00eda la m\u00fasica que necesitaba hacer, y me siento feliz de que, al menos, algunas personas disfruten con ella\u00bb.<\/p>\n<p>Como les dec\u00eda, el blog ha generado un debate intenso, porque muchos lo consideran sexista: \u00abPerpet\u00faa la idea, digna del Woody Allen de los 70, de que las relaciones heterosexuales se centran en la educaci\u00f3n de las mujeres a cargo de los hombres\u00bb, reprocha <a href=\"http:\/\/flavorwire.com\/445998\/the-uncomfortable-gender-politics-of-my-husbands-stupid-record-collection\" target=\"_blank\" rel=\"external nofollow\"><em>Flavorwire<\/em><\/a>. Otros an\u00e1lisis admiten su efecto c\u00f3mico, pero resaltan que, a la vez, ratifica estereotipos sobre la relaci\u00f3n de las mujeres con el rock: \u00abEsos mismos t\u00edos obsesionados por la m\u00fasica que han dejado a las mujeres fuera de la subcultura, manteni\u00e9ndolas en los roles perif\u00e9ricos de esposas y novias, comparten el enlace como confirmaci\u00f3n de que las mujeres simplemente no lo entienden\u00bb, lamenta <a href=\"http:\/\/www.slate.com\/blogs\/xx_factor\/2014\/03\/18\/my_husband_s_stupid_record_collection_sarah_o_holla_reviews_music_nerd_husband.html\" target=\"_blank\" rel=\"external nofollow\"><em>Slate<\/em><\/a>. Al final, la propia Sarah ha aprovechado las vacaciones para responder a todo este l\u00edo, y la r\u00e9plica no le ha quedado nada mal: \u00abUn mont\u00f3n de las cr\u00edticas dicen que este blog juega con la idea de que las voces de las mujeres son marginales o menos importantes, pero, con todo lo que se ha escrito, nadie ha hecho ning\u00fan esfuerzo para ponerse en contacto conmigo y recoger mis comentarios, o hacerme alguna pregunta. Un art\u00edculo daba mal mi nombre. Esta claro que los cr\u00edticos est\u00e1n m\u00e1s interesados en convertirme en un s\u00edmbolo de alg\u00fan estereotipo da\u00f1ino que en entender qu\u00e9 es esto o qui\u00e9n soy yo. Hablar conmigo podr\u00eda complicar las cosas. Podr\u00eda humanizarme\u00bb.<\/p>\n<p>Yo, por cierto, tambi\u00e9n lo intent\u00e9 alguna vez con Albert Ayler y me di por vencido&#8230;<\/p>\n<p>&nbsp;<br \/>\n<iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/2HShu-cIDwg?rel=0\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Dicen los que saben de estas cosas que los blogs est\u00e1n pasados de moda, porque los usos de nuestra era est\u00e1n sujetos a una especie de mudanza acelerada, que ha relegado ya estos entra\u00f1ables posts al nivel de los pergaminos y los frisos en bajorrelieve. Pero, bueno, todav\u00eda ocurre de vez en cuando que un [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[89,192,369,641,1007],"class_list":["post-2520","post","type-post","status-publish","format-standard","hentry","category-musica","tag-albert-ayler","tag-arab-on-radar","tag-blogs","tag-critica","tag-feminismo"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2520"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2520\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}