{"id":2496,"date":"2014-03-04T12:01:15","date_gmt":"2014-03-04T11:01:15","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2496"},"modified":"2014-03-04T12:01:15","modified_gmt":"2014-03-04T11:01:15","slug":"cosecha-de-enlaces-de-marge-simpson-a-mike-oldfield","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2014\/03\/04\/cosecha-de-enlaces-de-marge-simpson-a-mike-oldfield\/","title":{"rendered":"Cosecha de enlaces: de Marge Simpson a Mike Oldfield"},"content":{"rendered":"<p>Igual que los artistas que no tienen mucho nuevo que decir, de vez en cuando me suelto con un recopilatorio de cositas pasadas de fecha: es la cosecha de enlaces, el repaso apresurado y un poco ca\u00f3tico a textos que he ido publicando los \u00faltimos meses en el m\u00f3dulo de ocio (esa elegante columna negra que asoma en la portada de <a href=\"http:\/\/www.elcorreo.com\/\" target=\"_blank\" rel=\"external nofollow\">El Correo<\/a> todas las tardes) o que han salido originalmente en el papel, han dado el brinco hasta lo digital y tienen cierto inter\u00e9s pop, porque tampoco me parece bien enlazarles aqu\u00ed la situaci\u00f3n <a href=\"http:\/\/www.lasprovincias.es\/v\/20140123\/sociedad\/mongolia-despierta-20140123.html\" target=\"_blank\" rel=\"external nofollow\">en Ul\u00e1n Bator<\/a>. Muchas son previas de conciertos a los que ya no podr\u00e1n ir, o a lo mejor incluso ya han ido, pero de nuevo ocurre como con los recopilatorios: hay que darle un poco de cuerpo al disco, aunque no todo sean grandes \u00e9xitos.<\/p>\n<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2014\/03\/04\/cosecha-de-enlaces-de-marge-simpson-a-mike-oldfield\/marge-simpson-aleksandro-palombojpg\/\" rel=\"attachment wp-att-2497\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-2497\" title=\"Marge Simpson (Aleksandro Palombo\/Vogue)\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/03\/Marge-Simpson-Aleksandro-Palombojpg.jpg\" alt=\"\" width=\"237\" height=\"358\" \/><\/a>As\u00ed que tenemos el debut de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/v\/20131125\/gente\/modelo-perfecta-20131125.html\" target=\"_blank\" rel=\"external nofollow\">Marge Simpson<\/a> como modelo, el debut de <a href=\"http:\/\/www.eldiariomontanes.es\/v\/20131126\/sociedad\/destacados\/bisabuelo-rock-20131126.html\" target=\"_blank\" rel=\"external nofollow\">Mick Jagger<\/a> como bisabuelo, el debut de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201312\/17\/keith-richards.html\" target=\"_blank\" rel=\"external nofollow\">Keith Richards<\/a> como septuagenario (vale, vale, dejo ah\u00ed la f\u00f3rmula, que se est\u00e1 agotando), un <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201311\/26\/primavera-sound-touring-party.html\" target=\"_blank\" rel=\"external nofollow\">trocito de Primavera<\/a> en Bilbao, los treinta a\u00f1os del <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201312\/01\/domingo-michael-jackson-thriller.html\" target=\"_blank\" rel=\"external nofollow\">v\u00eddeo de <em>Thriller<\/em><\/a>, el desconcierto adulto ante <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201312\/02\/quien-es-violetta.html\" target=\"_blank\" rel=\"external nofollow\">Violetta<\/a>, la dimensi\u00f3n pop de <a href=\"http:\/\/www.larioja.com\/v\/20131207\/mundo\/mandela-inesperado-icono-20131207.html\" target=\"_blank\" rel=\"external nofollow\">Nelson Mandela<\/a>, los encantos de la <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201312\/08\/domingo-navidad-londres.html\" target=\"_blank\" rel=\"external nofollow\">navidad londinense<\/a>, el test bilbainista a <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201312\/11\/concierto-chica-chico.html\" target=\"_blank\" rel=\"external nofollow\">Chico y Chica<\/a>, la orquesta de guitarras el\u00e9ctricas <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201312\/18\/concierto-sinfonity.html\" target=\"_blank\" rel=\"external nofollow\">Sinfonity<\/a>, la casa de don <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201312\/19\/sorteo-casa-periodico-el-correo.html\" target=\"_blank\" rel=\"external nofollow\">Gumersindo Barbadillo<\/a>, el homenaje vasco a <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201401\/08\/homenaje-lou-reed.html\" target=\"_blank\" rel=\"external nofollow\">Lou Reed<\/a>, la prometedora voz de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201401\/12\/domingo-sam-smith-promesa-ano.html\" target=\"_blank\" rel=\"external nofollow\">Sam Smith<\/a>, la efervescencia eterna de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201401\/14\/concierto-redd-kross.html\" target=\"_blank\" rel=\"external nofollow\">Redd Kross<\/a>, el pitote de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201401\/21\/concierto-fleshtones.html\" target=\"_blank\" rel=\"external nofollow\">The Fleshtones<\/a>, el rap quinqui de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201401\/23\/concierto-el-coleta.html\" target=\"_blank\" rel=\"external nofollow\">El Coleta<\/a>, el baile en pijama de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201401\/26\/domingo-morning-glory.html\" target=\"_blank\" rel=\"external nofollow\">Morning Glory<\/a>, el hilo negro de la Mafia que borda <a href=\"http:\/\/www.hoy.es\/v\/20140126\/sociedad\/hilo-negro-mafia-20140126.html\" target=\"_blank\" rel=\"external nofollow\">\u00cd\u00f1igo Dom\u00ednguez<\/a>, <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201401\/28\/concierto-basia-bulat-unai-azkune.html\" target=\"_blank\" rel=\"external nofollow\">Basia Bulat<\/a> y su charango, el extra\u00f1o h\u00edbrido de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201401\/29\/tarja-udo-bella-bestia-metal.html\" target=\"_blank\" rel=\"external nofollow\">Tarja y Udo<\/a>, las m\u00fasicas y las tetas de la <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/02\/domingo-actuaciones-musicales-super-bowl.html\" target=\"_blank\" rel=\"external nofollow\">Super Bowl<\/a>, el desembarco de <a href=\"http:\/\/www.hoy.es\/v\/20140203\/sociedad\/ellos-llego-locura-20140203.html\" target=\"_blank\" rel=\"external nofollow\">los Beatles<\/a> en Estados Unidos, el piano m\u00e1gico de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/03\/concierto-tigran.html\" target=\"_blank\" rel=\"external nofollow\">Tigran<\/a>, la improbable alianza de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/05\/video-julie-gayet.html\" target=\"_blank\" rel=\"external nofollow\">Minor Alps<\/a> y Julie Gayet, el feliz matrimonio de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/10\/concierto-nashville-pussy.html\" target=\"_blank\" rel=\"external nofollow\">Nashville Pussy<\/a>, el ensordecedor <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/11\/concierto-resurrection-fest.html\" target=\"_blank\" rel=\"external nofollow\">Tour Of Chaos<\/a>, la flauta de zanahoria y r\u00e1bano japon\u00e9s de <a href=\"http:\/\/www.hoy.es\/v\/20140216\/sociedad\/menestra-sinfonica-20140216.html\" target=\"_blank\" rel=\"external nofollow\">The Vegetable Orchestra<\/a>, las pezoneras de cinta aislante de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/18\/concierto-butcher-babies.html\" target=\"_blank\" rel=\"external nofollow\">Butcher Babies<\/a>, los treinta a\u00f1os de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/23\/domingo-los-smiths.html\" target=\"_blank\" rel=\"external nofollow\"><em>The Smiths<\/em><\/a>, la objeci\u00f3n pionera de <a href=\"http:\/\/www.hoy.es\/v\/20140223\/sociedad\/hombre-quiso-soldado-20140223.html\" target=\"_blank\" rel=\"external nofollow\">Pepe Beunza<\/a>, la consulta psicoanal\u00edtica y risoterap\u00e9utica de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/25\/concierto-les-luthiers.html\" target=\"_blank\" rel=\"external nofollow\">Les Luthiers<\/a> y la <em>nueva cara<\/em> de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201403\/02\/domingo-nuevo-disco-mikel-oldfield.html\" target=\"_blank\" rel=\"external nofollow\">Mike Oldfield<\/a>. Adem\u00e1s, por supuesto, est\u00e1n los repasos mensuales a la actualidad de hace cien a\u00f1os, esas <em>noticias f\u00f3siles<\/em> con los <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201312\/09\/noticias-fosiles.html\" target=\"_blank\" rel=\"external nofollow\">asesinatos \u00abpor cuesti\u00f3n de baile\u00bb<\/a>, las <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201401\/07\/noticias-fosiles-enero.html\" target=\"_blank\" rel=\"external nofollow\">coplas mortificantes<\/a> de C\u00e1ndido Lav\u00edn, la obscenidad reincidente de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/04\/noticias-fosiles-lunes-3-febrero.html\" target=\"_blank\" rel=\"external nofollow\">Julia Ca\u00f1ete<\/a> y la eficacia de la <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201403\/03\/lunes-noticias-fosiles-marzo.html\" target=\"_blank\" rel=\"external nofollow\">pomada de El Cairo<\/a> contra las almorranas.\u00a0 Buffff, esto es por lo menos un triple \u00e1lbum.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Igual que los artistas que no tienen mucho nuevo que decir, de vez en cuando me suelto con un recopilatorio de cositas pasadas de fecha: es la cosecha de enlaces, el repaso apresurado y un poco ca\u00f3tico a textos que he ido publicando los \u00faltimos meses en el m\u00f3dulo de ocio (esa elegante columna negra [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[621,1900,1974,1988,2179,3295,2984],"class_list":["post-2496","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cosecha-de-enlaces","tag-marge-simpson","tag-michael-jackson","tag-mike-oldfield","tag-noticias-fosiles","tag-the-beatles","tag-the-rolling-stones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2496"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2496\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}