{"id":2490,"date":"2014-02-27T11:34:25","date_gmt":"2014-02-27T10:34:25","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2490"},"modified":"2014-02-27T11:34:25","modified_gmt":"2014-02-27T10:34:25","slug":"algunos-sonidos-de-marzo-3","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2014\/02\/27\/algunos-sonidos-de-marzo-3\/","title":{"rendered":"Algunos sonidos de marzo"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2014\/02\/27\/algunos-sonidos-de-marzo-3\/nina-coyote-eta-chico-tornado\/\" rel=\"attachment wp-att-2491\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2491\" title=\"Ni\u00f1a Coyote eta Chico Tornado\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Ni\u00f1a-Coyote-eta-Chico-Tornado.jpg\" alt=\"\" width=\"560\" height=\"407\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Ni\u00f1a-Coyote-eta-Chico-Tornado.jpg 917w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Ni\u00f1a-Coyote-eta-Chico-Tornado-150x109.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Ni\u00f1a-Coyote-eta-Chico-Tornado-300x219.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Ni\u00f1a-Coyote-eta-Chico-Tornado-768x559.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Ni\u00f1a-Coyote-eta-Chico-Tornado-600x437.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Febrero pasa en un suspiro, \u00bfverdad? Aqu\u00ed tienen la selecci\u00f3n de conciertos de marzo en Bilbao y alrededores, un surtidito de seis citas en seis salas distintas que abarca desde cl\u00e1sicos imperecederos argentinos hasta ignotos grupos n\u00f3rdicos. \u00a1Viva el omnivorismo!<\/p>\n<p><strong>Les Luthiers (d\u00edas 1, 2 y 3, Euskalduna).<\/strong> Ten\u00eda mis dudas sobre Les Luthiers. Porque, claro, eran alucinantemente divertidos hace cuarenta a\u00f1os, pero \u00bfse puede mantener el ingenio en forma durante tanto tiempo? Los recelos se me disiparon en cuanto vi en YouTube unas cuantas canciones de <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201402\/25\/concierto-les-luthiers.html\" target=\"_blank\" rel=\"external nofollow\"><em>Lutherapia<\/em><\/a>, el espect\u00e1culo que traen al Euskalduna. S\u00ed, se puede.<\/p>\n<p><strong>Staer (d\u00eda 4, Sentinel).<\/strong> Desde la f\u00e9rtil escena noruega del rock de vanguardia llega este tr\u00edo del que, para qu\u00e9 vamos a enga\u00f1arnos, no ten\u00eda conocimiento hasta que se anunci\u00f3 este concierto en la sala de Erandio. Staer parecen muy j\u00f3venes y se mueven por terrenos que lindan con el hardcore, el noise rock, la experimentaci\u00f3n o incluso el free jazz: vamos, que hacen <a href=\"http:\/\/discorporate.bandcamp.com\/track\/sex-varnish\" target=\"_blank\" rel=\"external nofollow\">lo que les da la gana<\/a>, que suelen ser cosas chirriantes y retorcidas. Telonea <a href=\"http:\/\/www.youtube.com\/watch?feature=player_embedded&#038;v=PtBF8ZL1OKI\" target=\"_blank\" rel=\"external nofollow\">Horacio Pollard<\/a>, un ibicenco anglo-argentino.<\/p>\n<p><strong>Neil Halstead (d\u00eda 12, Kafe Antzokia).<\/strong> El afortunado cruce entre dos ciclos (el nacional We Used To Party y el local Izar &#038; Star) nos brinda un nuevo homenaje a la obra del difunto Lou Reed. Esta vez es Neil Halstead, l\u00edder de Slowdive y Mojave 3, quien versionar\u00e1 \u00edntegramente y acompa\u00f1ado por banda <em>The Velvet Underground &#038; Nico<\/em>, ya saben, el disco del pl\u00e1tano. Un \u00e1lbum que es como un mundo entero.<\/p>\n<p><strong>Kill! Kill! Pussycat! (d\u00eda 15, La Nube).<\/strong> Un poco de garaje sueco, o de \u00abhigh speed rock &#038; roll\u00bb, en pleno coraz\u00f3n de Santutxu. La agenda del <a href=\"https:\/\/www.facebook.com\/LaNubeCafeTeatro\" target=\"_blank\" rel=\"external nofollow\">Caf\u00e9 Teatro La Nube<\/a> est\u00e1 cada mes m\u00e1s repleta y, adem\u00e1s, propone tratos ventajosos: con la entrada de <a href=\"http:\/\/www.youtube.com\/watch?v=I-USo-7VJh8\" target=\"_blank\" rel=\"external nofollow\">los suecos<\/a>, te invitan al concierto de los australianos <a href=\"http:\/\/soundcloud.com\/the-volcanics\/hold-it-down-live\" target=\"_blank\" rel=\"external nofollow\">The Volcanics<\/a> diez d\u00edas m\u00e1s tarde. \u00a1Y son cinco euros!<\/p>\n<p><strong>Maceo Parker (d\u00eda 25, Sala BBK).<\/strong> Mi ignorancia sobre <a href=\"http:\/\/www.youtube.com\/watch?v=KbP7ColBp04\" target=\"_blank\" rel=\"external nofollow\">Maceo Parker<\/a> es may\u00fascula (apedreen, apedreen), pero llevo media vida escuchando a mucha gente fiable que el saxofonista de James Brown es uno de esos artistas que cortocircuitan cerebros en directo. Copio el arranque de una de las m\u00faltiples rese\u00f1as de conciertos suyos que ha firmado el colega <a href=\"http:\/\/bilbaoenvivo.wordpress.com\/\" target=\"_blank\" rel=\"external nofollow\">Cubillo<\/a>: \u00abTres horas, seis minutos y 35 segundos de superfunk de calidad estratosf\u00e9rica, soul carnoso y jazz participativo\u00bb, resum\u00eda.<\/p>\n<p><strong>Fuzz In The City (d\u00edas 28 y 29, Hika).<\/strong> Olv\u00eddense de macrofestivales deshumanizados y pasteurizados y acudan a este evento amigable, manejable, adorable, que anuncia \u00ablas bandas mas atronadoras, explosivas y salvajes de los m\u00e1s remotos rincones\u00bb, como Toledo, C\u00e1diz o Italia. Tocar\u00e1n en el ateneo ribere\u00f1o <a href=\"http:\/\/www.youtube.com\/watch?v=OeHJXEp4wUk\" target=\"_blank\" rel=\"external nofollow\">Ni\u00f1a Coyote eta Chico Tornado<\/a> (esos muchachos tan <em>crampianos<\/em> de la foto de arriba), Aullido At\u00f3mico, Little Cobras, <a href=\"http:\/\/www.youtube.com\/watch?v=u0PXRIOqWlE\" target=\"_blank\" rel=\"external nofollow\">Tony la Muerte<\/a>, The Limboos, Screamin\u2019 George &#038; The Hustlers y <a href=\"http:\/\/www.youtube.com\/watch?v=uKF17bpNNiQ\" target=\"_blank\" rel=\"external nofollow\">Las Aspiradoras<\/a>, y habr\u00e1 adem\u00e1s enviados especiales a otros lugares de Bilbao, como Rolando Bruno y su Gran Orquesta Midi. Seguiremos informando.<\/p>\n<p>Les dejo con Les Luthiers y su <em>Aria agraria<\/em>, apasionada defensa del tarareo conceptual. A ver qui\u00e9n es el listo que se aprende la letra y la canta sin trastabillar.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/9MtJQZaF6sQ?rel=0\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Febrero pasa en un suspiro, \u00bfverdad? Aqu\u00ed tienen la selecci\u00f3n de conciertos de marzo en Bilbao y alrededores, un surtidito de seis citas en seis salas distintas que abarca desde cl\u00e1sicos imperecederos argentinos hasta ignotos grupos n\u00f3rdicos. \u00a1Viva el omnivorismo! Les Luthiers (d\u00edas 1, 2 y 3, Euskalduna). Ten\u00eda mis dudas sobre Les Luthiers. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[327,602,927,1104,1723,1842,2124,2153,2714,2745],"class_list":["post-2490","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao","tag-conciertos","tag-erandio","tag-fuzz-in-the-city","tag-les-luthiers","tag-maceo-parker","tag-neil-halstead","tag-nina-coyote-eta-chico-tornado","tag-sonidos-de","tag-staer"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2490"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2490\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}