{"id":2488,"date":"2014-02-26T11:30:14","date_gmt":"2014-02-26T10:30:14","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2488"},"modified":"2014-02-26T11:30:14","modified_gmt":"2014-02-26T10:30:14","slug":"contabilidad-zoe-keating","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2014\/02\/26\/contabilidad-zoe-keating\/","title":{"rendered":"La contabilidad de Zo\u00eb"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2014\/02\/26\/contabilidad-zoe-keating\/zoe-keating-foto-nicole-cleary\/\" rel=\"attachment wp-att-2489\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2489\" title=\"Zo\u00eb Keating (foto - Nicole Cleary)\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Zo\u00eb-Keating-foto-Nicole-Cleary.jpg\" alt=\"\" width=\"560\" height=\"403\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Zo\u00eb-Keating-foto-Nicole-Cleary.jpg 640w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Zo\u00eb-Keating-foto-Nicole-Cleary-150x108.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Zo\u00eb-Keating-foto-Nicole-Cleary-300x216.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/02\/Zo\u00eb-Keating-foto-Nicole-Cleary-600x432.jpg 600w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.zoekeating.com\" target=\"_blank\" rel=\"external nofollow\">Zo\u00eb Keating<\/a>, chelista canadiense afincada en California, tiene la curiosa costumbre de publicar lo que gana anualmente a trav\u00e9s de las ventas de discos y las reproducciones en <em>streaming<\/em>, en un ejercicio de transparencia detallada poco frecuente en el mundillo. Zo\u00eb es un personaje peculiar, a caballo entre la m\u00fasica cl\u00e1sica, la vanguardia y el pop, con una imagen llamativa y un dominio evidente de los resortes tecnol\u00f3gicos. En 2013, seg\u00fan el <a href=\"https:\/\/docs.google.com\/spreadsheet\/ccc?key=0AkasqHkVRM1OdHg2eWZRYVp1YmgyUDFvbWtwLWNCN0E#gid=0\" target=\"_blank\">documento p\u00fablico<\/a> que ha confeccionado en Google, vendi\u00f3 32.806 sencillos y 8.635 \u00e1lbumes a trav\u00e9s de iTunes, Amazon y Bandcamp, que le rindieron unos ingresos de 75.341 d\u00f3lares. Y obtuvo 6.380 d\u00f3lares extras de las reproducciones en Spotify, YouTube, Pandora, Soundcloud, Bandcamp y dem\u00e1s. Seg\u00fan mis cuentas, viene a obtener un centavo por cada tres reproducciones en Spotify (concretamente, saca 0,0043 d\u00f3lares cada vez que alguien escucha un tema suyo).<\/p>\n<p>No tengo la sensaci\u00f3n, por lo que he le\u00eddo por ah\u00ed, de que Zo\u00eb Keating se queje de este sistema, pero veo que los datos se est\u00e1n interpretando como una nueva demostraci\u00f3n de la racaner\u00eda de Spotify, porque le har\u00edan falta 232 reproducciones para ganar un d\u00f3lar. Yo siempre eludo estas discusiones, enconadas y habitualmente est\u00e9riles, pero me parece que sigue habiendo cierto empe\u00f1o en comparar el <em>streaming<\/em> con la venta de discos y no con el otro referente a mano, que son las reproducciones radiof\u00f3nicas. Me gustar\u00eda saber cu\u00e1nto puede cobrar un artista del tipo de Zo\u00eb Keating en concepto de derechos por cada canci\u00f3n suya que suena en la radio, y comprobar si esa cifra se acerca a los 0,43 centavos por oyente. De todas formas, lo m\u00e1s sorprendente de todo esto es c\u00f3mo la chelista ha conseguido convertir su cuenta de resultados en un efectivo mecanismo promocional: eso s\u00ed que es innovar.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0pt none; width: 100%; height: 120px;\" src=\"\/\/bandcamp.com\/EmbeddedPlayer\/album=1901731418\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/t=5\/transparent=true\/\" width=\"320\" height=\"240\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Zo\u00eb Keating, chelista canadiense afincada en California, tiene la curiosa costumbre de publicar lo que gana anualmente a trav\u00e9s de las ventas de discos y las reproducciones en streaming, en un ejercicio de transparencia detallada poco frecuente en el mundillo. Zo\u00eb es un personaje peculiar, a caballo entre la m\u00fasica cl\u00e1sica, la vanguardia y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[765,2259,2724,2739,3274,3286],"class_list":["post-2488","post","type-post","status-publish","format-standard","hentry","category-musica","tag-dinero","tag-pandora","tag-soundcloud","tag-spotify","tag-youtube","tag-zoe-keating"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2488"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2488\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}