{"id":244,"date":"2007-08-04T17:09:00","date_gmt":"2007-08-04T16:09:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=244"},"modified":"2007-08-04T17:09:00","modified_gmt":"2007-08-04T16:09:00","slug":"euskal-txahaltxitxa","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/08\/04\/euskal-txahaltxitxa\/","title":{"rendered":"Euskal Txahaltxitxa"},"content":{"rendered":"<p>\u00bfYa saben que pueden comer salchichas elaboradas exclusivamente con vacuno del pa\u00eds (vasco)? Ha nacido la Euskal Txahaltxitxa, la imagen de abajo es el cartel que la promociona y todo esto, seg\u00fan parece, no es un nuevo montaje de <A target=\"_blank\" href=\"http:\/\/www.gorkalimotxo.net\/blog\/\">Gorka Limotxo<\/a> sino la m\u00e1s pura realidad nacional. Temblad, Frankfurt y Viena, que peligra vuestro imperio salchichero.<\/p>\n<p><IMG src=\"\/evadidos\/files\/Euskal2.jpg\" align=\"middle\" width=\"450\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfYa saben que pueden comer salchichas elaboradas exclusivamente con vacuno del pa\u00eds (vasco)? Ha nacido la Euskal Txahaltxitxa, la imagen de abajo es el cartel que la promociona y todo esto, seg\u00fan parece, no es un nuevo montaje de Gorka Limotxo sino la m\u00e1s pura realidad nacional. Temblad, Frankfurt y Viena, que peligra vuestro imperio [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,6],"tags":[485,967],"class_list":["post-244","post","type-post","status-publish","format-standard","hentry","category-inclasificables","category-mundo-freak","tag-carniceria","tag-euskadi"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=244"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/244\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}