{"id":2432,"date":"2014-01-17T08:10:36","date_gmt":"2014-01-17T07:10:36","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2432"},"modified":"2014-01-17T08:10:36","modified_gmt":"2014-01-17T07:10:36","slug":"cancion-de-la-semana-suicide","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2014\/01\/17\/cancion-de-la-semana-suicide\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Suicide&#039;"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2014\/01\/17\/cancion-de-la-semana-suicide\/mind-spiders\/\" rel=\"attachment wp-att-2433\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-2433\" title=\"Mind Spiders\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/01\/Mind-Spiders.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/01\/Mind-Spiders.jpg 640w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/01\/Mind-Spiders-150x100.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/01\/Mind-Spiders-300x200.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2014\/01\/Mind-Spiders-600x400.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Al tejano Mark Ryan no le iba mal con su anterior grupo, The Marked Men, pero en los \u00faltimos cuatro a\u00f1os lo tiene aparcado para dedicarse a lo que naci\u00f3 como proyecto paralelo, <a href=\"https:\/\/www.facebook.com\/pages\/Mind-Spiders\/168482384014\" target=\"_blank\" rel=\"external nofollow\">Mind Spiders<\/a>. De hecho, parece haber entrado en un periodo de inspiraci\u00f3n febril que le ha llevado a editar tres \u00e1lbumes en tres a\u00f1os, todos ellos caracterizados por la presencia de teclados, que dan a algunos temas un toque como de ciencia ficci\u00f3n <em>low cost<\/em>. En el \u00faltimo disco aparecen adem\u00e1s varias cajas de ritmos, que constituyen uno de los motivos por los que decidieron titularlo <em>Inhumanistic<\/em>, pero a lo mejor esta introducci\u00f3n un poco latosa les ha llevado a enga\u00f1o y se est\u00e1n imaginando un rollo cercano al tecnopop o la electr\u00f3nica de baile, y no: en esencia, Ryan no ha traicionado el punk rock de su anterior banda y sigue componiendo lo que \u00e9l describe como \u00abcanciones est\u00fapidamente sencillas\u00bb, resueltas con dos o tres acordes y adictivas en su combinaci\u00f3n de energ\u00eda, gancho mel\u00f3dico y brevedad. Miren, <a href=\"http:\/\/www.dirtnaprecs.com\/website\/mind-spiders-inhumanistic\/\" target=\"_blank\" rel=\"external nofollow\">su sello<\/a> cita como referencias a Devo y Wall Of Voodoo, aunque tampoco s\u00e9 si me convence mucho la comparaci\u00f3n.<\/p>\n<p>El \u00e1lbum entero es muy recomendable, pero yo me enganch\u00e9 desde el principio a este trepidante <em>Suicide<\/em>.<\/p>\n<p>&nbsp;<br \/>\n<iframe loading=\"lazy\" style=\"border: 0pt none; width: 100%; height: 142px;\" src=\"\/\/bandcamp.com\/EmbeddedPlayer\/album=2167682438\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/t=3\/transparent=true\/\" width=\"320\" height=\"240\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Al tejano Mark Ryan no le iba mal con su anterior grupo, The Marked Men, pero en los \u00faltimos cuatro a\u00f1os lo tiene aparcado para dedicarse a lo que naci\u00f3 como proyecto paralelo, Mind Spiders. De hecho, parece haber entrado en un periodo de inspiraci\u00f3n febril que le ha llevado a editar tres \u00e1lbumes en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,1999,2860,2949],"class_list":["post-2432","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-mind-spiders","tag-texas","tag-the-marked-men"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2432"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2432\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}