{"id":2379,"date":"2013-12-03T13:44:41","date_gmt":"2013-12-03T12:44:41","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2379"},"modified":"2013-12-03T13:44:41","modified_gmt":"2013-12-03T12:44:41","slug":"dsolea-ciencia-tierra-mas-alla","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2013\/12\/03\/dsolea-ciencia-tierra-mas-alla\/","title":{"rendered":"De la sole\u00e1 de la ciencia a la tierra de m\u00e1s all\u00e1"},"content":{"rendered":"<p>Algunos de los artistas que m\u00e1s me gustan acaban resultando damnificados: no les presto aqu\u00ed la atenci\u00f3n que merecen porque me da cosa ponerme latoso, en plan monotem\u00e1tico y monomaniaco, centrado siempre en mis favoritos. Pero, como eso tampoco es justo, quiero dejar constancia de que han salido dos \u00e1lbumes muy interesantes firmados por santos patrones de este blog.<\/p>\n<p>El primero lo firma el granadino <a href=\"https:\/\/www.facebook.com\/multiverso2\" target=\"_blank\" rel=\"external nofollow\">Antonio Arias<\/a>, l\u00edder de Lagartija Nick. En 2009 edit\u00f3 <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2010\/02\/06\/cancion-la-semana-laika\/\" target=\"_blank\">su primer \u00e1lbum en solitario<\/a>, <em>Multiverso<\/em>, en el que musicaba varios poemas de tema cient\u00edfico, y ahora ha dado continuidad a aquel empe\u00f1o con <em>Multiverso II: de la sole\u00e1 de la ciencia a la f\u00edsica de la inmortalidad<\/em>, basado en su mayor\u00eda en textos de David Jou, catedr\u00e1tico de F\u00edsica de la Materia Condensada de la Universidad Aut\u00f3noma de Barcelona. En baladas y medios tiempos que serpentean entre \u00e1tomos y planetas, Antonio Arias nos brinda algo as\u00ed como el pop de otro universo posible, fascinado ante la belleza y el misterio de la realidad. Son letras muy alejadas de la l\u00edrica habitual del rock, pero Antonio logra encajarlas en melod\u00edas perfectamente pegadizas, con arreglos cuidados (\u00a1hay sonidos astron\u00f3micos!) y con los ocasionales deslumbramientos de los coros de Sole\u00e1 Morente. Me gustar\u00eda colgarles alg\u00fan tema (ahora mismo, mis favoritos son <em>La f\u00edsica de la inmortalidad<\/em> y <em>Proyecto Marte<\/em>), pero no encuentro que est\u00e9n disponibles por ning\u00fan lado. Una pena c\u00f3smica.<\/p>\n<p>As\u00ed que paso a otro \u00e1lbum bastante at\u00edpico que acaba de salir a la venta: <a href=\"http:\/\/www.britishseapower.co.uk\/\" target=\"_blank\" rel=\"external nofollow\">British Sea Power<\/a>, que llevan m\u00e1s de una d\u00e9cada de carrera pero atraviesan uno de sus mejores momentos, se han animado por fin a editar <em>From The Sea To The Land Beyond<\/em>, su banda sonora para un documental que recopila im\u00e1genes de la costa brit\u00e1nica filmadas a lo largo de todo el siglo XX, desde 1901 hasta 1999. El grupo resolvi\u00f3 la tarea grabando nuevas versiones de varios temas, en las que se subraya esa melancol\u00eda brumosa y agridulce tan caracter\u00edstica de su estilo. <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2013\/02\/08\/cancion-de-la-semana-from-the-sea-to-the-land-beyond\/\" target=\"_blank\">Ya hablamos de este disco<\/a> en febrero, pero hasta ahora no ha estado disponible, en una <a href=\"http:\/\/www.amazon.co.uk\/From-The-Sea-Land-Beyond\/dp\/B00GCI94JW\/ref=sr_1_1?ie=UTF8&#038;qid=1386073243&#038;sr=8-1&#038;keywords=british+sea+power+sea+land+beyond\" target=\"_blank\" rel=\"external nofollow\">bonita edici\u00f3n<\/a> que combina CD y DVD. Y seguramente volveremos a mencionarlo dentro de unas semanas, cuando llegue la lista de lo mejor del a\u00f1o, aunque ah\u00ed tiene un duro competidor en el propio <em>Machineries Of Joy<\/em>, el espl\u00e9ndido disco de material nuevo de British Sea Power. Les dejo con el tr\u00e1iler de <em>From The Sea To The Land Beyond<\/em>, en el que suena un fragmento del tema hom\u00f3nimo.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/ulKK4dS6lfc?rel=0\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Algunos de los artistas que m\u00e1s me gustan acaban resultando damnificados: no les presto aqu\u00ed la atenci\u00f3n que merecen porque me da cosa ponerme latoso, en plan monotem\u00e1tico y monomaniaco, centrado siempre en mis favoritos. Pero, como eso tampoco es justo, quiero dejar constancia de que han salido dos \u00e1lbumes muy interesantes firmados por santos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[176,264,420,774,1667,2182],"class_list":["post-2379","post","type-post","status-publish","format-standard","hentry","category-musica","tag-antonio-arias","tag-bandas-sonoras","tag-british-sea-power","tag-discos","tag-lagartija-nick","tag-novedades"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2379"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2379\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}